{"id":7388,"date":"2020-12-29T18:02:10","date_gmt":"2020-12-29T14:32:10","guid":{"rendered":"https:\/\/pezeshkekhoob.com\/blog\/?p=7388"},"modified":"2025-07-22T14:04:00","modified_gmt":"2025-07-22T10:34:00","slug":"mmpi-test","status":"publish","type":"post","link":"https:\/\/ravandarman.com\/blog\/mmpi-test\/","title":{"rendered":"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646"},"content":{"rendered":"\r\n<p style=\"text-align: justify;\">\u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627\u060c \u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0686\u0646\u062f\u0648\u062c\u0647\u06cc \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u06cc\u062c\u200c\u062a\u0631\u06cc\u0646 \u062a\u0633\u062a \u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0627\u0633\u062a. \u062a\u0633\u062a mmpi \u062a\u0648\u0633\u0637 \u062f\u0648 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u0648 \u0639\u0635\u0628 \u0634\u0646\u0627\u0633 \u0639\u0636\u0648 \u0647\u06cc\u0627\u062a \u0639\u0644\u0645\u06cc \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062a\u0633\u062a \u062f\u0631 \u0627\u0635\u0644 \u0628\u0631\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0647 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u062f\u0631 \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u0647 \u0628\u0648\u062f.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u0632 \u0627\u0648\u0644\u06cc\u0646 \u0646\u0633\u062e\u0647 \u0622\u0646 \u062a\u0627 \u06a9\u0646\u0648\u0646 \u0628\u0627\u0632\u0628\u06cc\u0646\u06cc\u200c\u0647\u0627 \u0648 \u0628\u0647 \u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc\u200c\u0647\u0627\u06cc \u0645\u062a\u0639\u062f\u062f\u06cc \u0631\u0648\u06cc \u0622\u0646 \u0627\u0646\u062c\u0627\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a \u062a\u0627 \u062f\u0642\u06cc\u0642\u200c\u062a\u0631 \u0648 \u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0645\u0627\u062f\u062a\u0631 \u0628\u0627\u0634\u062f. \u0646\u0633\u062e\u0647 \u0628\u0647 \u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc \u0634\u062f\u0647 \u062a\u0633\u062a MMPI2 \u062f\u0631 \u0628\u06cc\u0634 \u0627\u0632 \u0686\u0647\u0644 \u06a9\u0634\u0648\u0631 \u062c\u0647\u0627\u0646 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u062a\u0633\u062a mmpi \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f \u0622\u0646 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_80 ez-toc-wrap-right counter-hierarchy ez-toc-counter-rtl ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0642\u0627\u0644\u0647<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D8%AA%D8%B3%D8%AA_%D9%85%DB%8C%D9%86%D9%87_%D8%B3%D9%88%D8%AA%D8%A7_%DB%8C%D8%A7_%D8%AA%D8%B3%D8%AA_mmpi_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D8%AA%D8%A7%D8%B1%DB%8C%D8%AE%DA%86%D9%87_%D8%AA%D8%B3%D8%AA_mmpi_%DB%8C%D8%A7_%D8%AA%D8%B3%D8%AA_%D9%85%DB%8C%D9%86%D9%87_%D8%B3%D9%88%D8%AA%D8%A7\" >\u062a\u0627\u0631\u06cc\u062e\u0686\u0647 \u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D8%AA%D8%B3%D8%AA_MMPI_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u06a9\u0627\u0631\u0628\u0631\u062f \u062a\u0633\u062a MMPI \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%86%D8%B3%D8%AE%D9%87_%D9%87%D8%A7%DB%8C_%D8%AA%D8%B3%D8%AA_mmpi\" >\u0646\u0633\u062e\u0647 \u0647\u0627\u06cc \u062a\u0633\u062a mmpi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%86%D8%AD%D9%88%D9%87_%D8%A7%D8%AC%D8%B1%D8%A7%DB%8C_%D8%AA%D8%B3%D8%AA_mmpi\" >\u0646\u062d\u0648\u0647 \u0627\u062c\u0631\u0627\u06cc \u062a\u0633\u062a mmpi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D8%A8%D8%A7%D9%84%DB%8C%D9%86%DB%8C_%D8%AA%D8%B3%D8%AA_MMPI\" >\u0645\u0639\u06cc\u0627\u0631\u0647\u0627\u06cc \u0628\u0627\u0644\u06cc\u0646\u06cc \u062a\u0633\u062a MMPI<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DB%B1_%D8%AE%D9%88%D8%AF%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%D8%A7%D9%86%DA%AF%D8%A7%D8%B1%DB%8C_%DB%8C%D8%A7_%D9%87%DB%8C%D9%BE%D9%88%DA%A9%D9%86%D8%AF%D8%B1%DB%8C%D8%A7%D8%B2%DB%8C%D8%B3_Hs\" >\u06f1. \u062e\u0648\u062f\u0628\u06cc\u0645\u0627\u0631\u0627\u0646\u06af\u0627\u0631\u06cc \u06cc\u0627 \u0647\u06cc\u067e\u0648\u06a9\u0646\u062f\u0631\u06cc\u0627\u0632\u06cc\u0633 (Hs)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DB%B2_%D8%A7%D9%81%D8%B3%D8%B1%D8%AF%DA%AF%DB%8C_D\" >\u06f2. \u0627\u0641\u0633\u0631\u062f\u06af\u06cc (D)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DB%B3_%D9%87%DB%8C%D8%B3%D8%AA%D8%B1%DB%8C_Hy\" >\u06f3. \u0647\u06cc\u0633\u062a\u0631\u06cc (Hy)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DB%B4_%D8%A7%D9%86%D8%AD%D8%B1%D8%A7%D9%81_%D8%B1%D9%88%D8%A7%D9%86%DB%8C_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C_Pd\" >\u06f4. \u0627\u0646\u062d\u0631\u0627\u0641 \u0631\u0648\u0627\u0646\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc (Pd)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DB%B5_%D9%85%D8%B1%D8%AF%D8%A7%D9%86%DA%AF%DB%8C%D8%B2%D9%86%D8%A7%D9%86%DA%AF%DB%8C_Mf\" >\u06f5. \u0645\u0631\u062f\u0627\u0646\u06af\u06cc\/\u0632\u0646\u0627\u0646\u06af\u06cc (Mf)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DB%B6_%D9%BE%D8%A7%D8%B1%D8%A7%D9%86%D9%88%DB%8C%D8%A7_%D8%A8%D8%AF%DA%AF%D9%85%D8%A7%D9%86%DB%8C_Pa\" >\u06f6. \u067e\u0627\u0631\u0627\u0646\u0648\u06cc\u0627 (\u0628\u062f\u06af\u0645\u0627\u0646\u06cc) (Pa)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DB%B7_%D8%B6%D8%B9%D9%81_%D8%B1%D9%88%D8%A7%D9%86%DB%8C_Pt\" >\u06f7. \u0636\u0639\u0641 \u0631\u0648\u0627\u0646\u06cc (Pt)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DB%B8_%D8%A7%D8%B3%DA%A9%DB%8C%D8%B2%D9%88%D9%81%D8%B1%D9%86%DB%8C_Sc\" >\u06f8. \u0627\u0633\u06a9\u06cc\u0632\u0648\u0641\u0631\u0646\u06cc (Sc)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DB%B9_%D9%87%DB%8C%D9%BE%D9%88%D9%85%D8%A7%D9%86%DB%8C%D8%A7_Ma\" >\u06f9. \u0647\u06cc\u067e\u0648\u0645\u0627\u0646\u06cc\u0627 (Ma)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%DB%B1%DB%B0_%D8%AF%D8%B1%D9%88%D9%86%DA%AF%D8%B1%D8%A7%DB%8C%DB%8C_%D8%A7%D8%AC%D8%AA%D9%85%D8%A7%D8%B9%DB%8C_Si\" >\u06f1\u06f0. \u062f\u0631\u0648\u0646\u06af\u0631\u0627\u06cc\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc (Si)<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D8%B1%D9%88%D8%A7%DB%8C%DB%8C_%D8%AF%D8%B1_%D8%AA%D8%B3%D8%AA_mmpi_%D8%A2%D9%86%D9%84%D8%A7%DB%8C%D9%86\" >\u0645\u0639\u06cc\u0627\u0631\u0647\u0627\u06cc \u0631\u0648\u0627\u06cc\u06cc \u062f\u0631 \u062a\u0633\u062a mmpi \u0622\u0646\u0644\u0627\u06cc\u0646<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D8%AA%D8%B8%D8%A7%D9%87%D8%B1_%D8%A8%D9%87_%D8%AE%D9%88%D8%A8%DB%8C_%DB%8C%D8%A7_%D8%AF%D8%B1%D9%88%D8%BA_L\" >\u0645\u0639\u06cc\u0627\u0631 \u062a\u0638\u0627\u0647\u0631 \u0628\u0647 \u062e\u0648\u0628\u06cc \u06cc\u0627 \u062f\u0631\u0648\u063a\u00a0 (L)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D8%AA%D8%B8%D8%A7%D9%87%D8%B1_%D8%A8%D9%87_%D8%A8%D8%AF%DB%8C_F\" >\u0645\u0639\u06cc\u0627\u0631 \u062a\u0638\u0627\u0647\u0631 \u0628\u0647 \u0628\u062f\u06cc (F)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D8%AD%D8%A7%D9%84%D8%AA_%D8%AA%D8%AF%D8%A7%D9%81%D8%B9%DB%8C_K\" >\u0645\u0639\u06cc\u0627\u0631 \u062d\u0627\u0644\u062a \u062a\u062f\u0627\u0641\u0639\u06cc (K)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D8%A8%DB%8C_%D9%BE%D8%A7%D8%B3%D8%AE%DB%8C_%D8%9F\" >\u0645\u0639\u06cc\u0627\u0631 \u0628\u06cc \u067e\u0627\u0633\u062e\u06cc (\u061f)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D9%86%D8%A7%D9%87%D9%85%D8%B3%D8%A7%D9%86%DB%8C_%D9%BE%D8%A7%D8%B3%D8%AE_%D8%AF%D8%B1%D8%B3%D8%AA_TRIN\" >\u0645\u0639\u06cc\u0627\u0631 \u0646\u0627\u0647\u0645\u0633\u0627\u0646\u06cc \u067e\u0627\u0633\u062e \u062f\u0631\u0633\u062a (TRIN)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D9%86%D8%A7%D9%87%D9%85%D8%B3%D8%A7%D9%86%DB%8C_%D9%BE%D8%A7%D8%B3%D8%AE_%D9%85%D8%AA%D8%BA%DB%8C%D8%B1_VRIN\" >\u0645\u0639\u06cc\u0627\u0631 \u0646\u0627\u0647\u0645\u0633\u0627\u0646\u06cc \u067e\u0627\u0633\u062e \u0645\u062a\u063a\u06cc\u0631 (VRIN)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D9%86%D8%A7%D8%A8%D8%B3%D8%A7%D9%85%D8%AF%DB%8C_%D8%A7%D9%86%D8%AA%D9%87%D8%A7%DB%8C_%D8%A2%D8%B2%D9%85%D9%88%D9%86_Fb\" >\u0645\u0639\u06cc\u0627\u0631 \u00a0\u0646\u0627\u0628\u0633\u0627\u0645\u062f\u06cc \u0627\u0646\u062a\u0647\u0627\u06cc \u0622\u0632\u0645\u0648\u0646 (Fb)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D9%86%D8%A7%D8%A8%D8%B3%D8%A7%D9%85%D8%AF%DB%8C_%D8%A2%D8%B3%DB%8C%D8%A8_%D8%B4%D9%86%D8%A7%D8%B3%DB%8C_%D8%B1%D9%88%D8%A7%D9%86%DB%8C_Fp\" >\u0645\u0639\u06cc\u0627\u0631 \u00a0\u0646\u0627\u0628\u0633\u0627\u0645\u062f\u06cc \u0622\u0633\u06cc\u0628 \u0634\u0646\u0627\u0633\u06cc \u0631\u0648\u0627\u0646\u06cc (Fp)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_FBS_%D8%AF%D8%B1_%D8%AA%D8%B3%D8%AA_mmpi\" >\u0645\u0639\u06cc\u0627\u0631 FBS \u062f\u0631 \u062a\u0633\u062a mmpi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D8%AE%D9%88%D8%AF%D8%AA%D9%88%D8%B5%DB%8C%D9%81%DB%8C_%D8%B9%D8%A7%D9%84%DB%8C_S\" >\u0645\u0639\u06cc\u0627\u0631 \u00a0\u062e\u0648\u062f\u062a\u0648\u0635\u06cc\u0641\u06cc \u0639\u0627\u0644\u06cc (S)<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D8%AA%D8%B3%D8%AA_MMPI_%DA%86%D9%82%D8%AF%D8%B1_%D8%AF%D9%82%DB%8C%D9%82_%D8%A7%D8%B3%D8%AA%D8%9F\" >\u062a\u0633\u062a MMPI \u0686\u0642\u062f\u0631 \u062f\u0642\u06cc\u0642 \u0627\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D9%85%D9%88%D8%A7%D8%B1%D8%AF%DB%8C_%DA%A9%D9%87_%D8%A8%D8%A7%DB%8C%D8%AF_%D9%87%D9%86%DA%AF%D8%A7%D9%85_%D8%A7%D9%86%D8%AC%D8%A7%D9%85_%D8%AA%D8%B3%D8%AA_%D8%B4%D8%AE%D8%B5%DB%8C%D8%AA_mmpi_%D8%AF%D8%B1_%D9%86%D8%B8%D8%B1_%D8%A8%DA%AF%DB%8C%D8%B1%DB%8C%D8%AF\" >\u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0647\u0646\u06af\u0627\u0645 \u0627\u0646\u062c\u0627\u0645 \u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a mmpi \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#%D8%AA%D8%B3%D8%AA_mmpi_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D8%B1%D9%86%D8%B3_%D9%87%D8%A7\" >\u062a\u0633\u062a mmpi \u0628\u0631\u0627\u06cc \u062a\u0631\u0646\u0633 \u0647\u0627<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B3%D8%AA_%D9%85%DB%8C%D9%86%D9%87_%D8%B3%D9%88%D8%AA%D8%A7_%DB%8C%D8%A7_%D8%AA%D8%B3%D8%AA_mmpi_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span><strong><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi \u0686\u06cc\u0633\u062a\u061f<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a MMPI (\u0645\u062e\u0641\u0641 Minnesota Multiphasic Personality Inventory) \u06cc\u06a9\u06cc \u0627\u0632 <strong><a href=\"https:\/\/ravandarman.com\/blog\/psychological-test\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0627\u0646\u0648\u0627\u0639 \u062a\u0633\u062a\u200c\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc <\/a><\/strong>\u0631\u0627\u06cc\u062c \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u062a\u062d\u0642\u06cc\u0642\u0627\u062a\u06cc \u0648 \u06a9\u0644\u06cc\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0627\u0633\u062a. \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u0627\u0632 \u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a mmpi \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0631\u0627 \u062a\u0634\u062e\u06cc\u0635 \u062f\u0647\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n<p id=\"2\" style=\"text-align: justify;\">\u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0627\u0648\u0644\u06cc\u0646 \u0628\u0627\u0631 \u062f\u0631 \u062f\u0647\u0647 \u06f1\u06f9\u06f3\u06f0 \u0645\u06cc\u0644\u0627\u062f\u06cc \u0627\u0628\u062f\u0627\u0639 \u0634\u062f. \u0627\u0645\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0635\u062d\u062a \u0648 \u0627\u0639\u062a\u0628\u0627\u0631 \u0622\u0646 \u0628\u0627\u0631\u0647\u0627 \u062a\u062c\u062f\u06cc\u062f\u0646\u0638\u0631 \u0648 \u0628\u0647 \u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u062a\u0633\u062a MMPI2 \u06a9\u0647 \u0634\u0627\u0645\u0644 \u06f5\u06f6\u06f7 \u067e\u0632\u0633\u0634 \u0635\u062d\u06cc\u062d \u0648 \u063a\u0644\u0637 \u0627\u0633\u062a \u062d\u062f\u0648\u062f \u06f6\u06f0 \u0627\u0644\u06cc \u06f9\u06f0 \u062f\u0642\u06cc\u0642\u0647 \u0632\u0645\u0627\u0646 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u062a\u0633\u062a MMPI2 \u062f\u0627\u0631\u0627\u06cc \u06f3\u06f7\u06f0 \u067e\u0631\u0633\u0634 \u0635\u062d\u06cc\u062d \u0648 \u063a\u0644\u0637 \u0627\u0633\u062a \u0648 \u062d\u062f\u0648\u062f \u06f3\u06f5 \u0627\u0644\u06cc \u06f5\u06f0 \u062f\u0642\u06cc\u0642\u0647 \u0632\u0645\u0627\u0646 \u0644\u0627\u0632\u0645 \u062f\u0627\u0631\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AA%D8%A7%D8%B1%DB%8C%D8%AE%DA%86%D9%87_%D8%AA%D8%B3%D8%AA_mmpi_%DB%8C%D8%A7_%D8%AA%D8%B3%D8%AA_%D9%85%DB%8C%D9%86%D9%87_%D8%B3%D9%88%D8%AA%D8%A7\"><\/span><strong><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u062a\u0627\u0631\u06cc\u062e\u0686\u0647 \u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u062a\u0633\u062a mmpi \u0627\u062d\u062a\u0645\u0627\u0644\u0627\u064b \u067e\u0631\u06a9\u0627\u0631\u0628\u0631\u062f\u062a\u0631\u06cc\u0646 \u0627\u0628\u0632\u0627\u0631 \u0686\u0646\u062f \u0628\u0639\u062f\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0647 \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062a\u0633\u062a \u0628\u0631\u0627\u06cc \u0627\u0648\u0644\u06cc\u0646 \u0628\u0627\u0631 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f9\u06f3\u06f9 \u062a\u0648\u0633\u0637 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u0628\u0627\u0644\u06cc\u0646\u06cc \u0627\u0633\u062a\u0627\u0631\u06a9 \u0647\u0627\u062a\u0627\u0648\u06cc \u0648 \u0631\u0648\u0627\u0646\u067e\u0632\u0634\u06a9 \u0627\u0639\u0635\u0627\u0628 \u062c\u06cc \u0633\u06cc \u0645\u06a9 \u06a9\u06cc\u0646\u0644\u06cc \u062f\u0631 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0627\u06cc\u062c\u0627\u062f \u0634\u062f \u0648 \u0627\u0648\u0644\u06cc\u0646 \u0628\u0627\u0631 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f9\u06f4\u06f3 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f. \u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a mmpi \u0627\u0632 \u0622\u0646\u062c\u0627\u06cc\u06cc \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f \u0628\u0631\u0627\u06cc \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u0622\u0633\u06cc\u0628 \u0634\u0646\u0627\u0633\u06cc \u0631\u0648\u0627\u0646\u06cc \u0628\u0647 \u0637\u0648\u0631 \u062e\u0627\u0635 \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u06a9\u0647 \u0628\u0647 \u062c\u0627\u06cc \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0633\u0627\u062f\u0647 \u0634\u062e\u0635\u06cc\u062a \u0647\u0631 \u0641\u0631\u062f\u060c \u0645\u0642\u06cc\u0627\u0633 \u0647\u0627\u06cc \u0628\u0627\u0644\u06cc\u0646\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0627 \u0628\u0631\u0631\u0633\u06cc \u0628\u06cc\u0645\u0627\u0631\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0627 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u062e\u0627\u0635\u06cc \u062a\u0634\u062e\u06cc\u0635 \u062f\u0627\u062f\u0647 \u0634\u062f\u0647 \u0628\u0648\u062f\u0646\u062f\u060c \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\r\n<p style=\"text-align: justify;\">\u0628\u0631\u062e\u0644\u0627\u0641 \u0633\u0627\u06cc\u0631 \u0622\u0632\u0645\u0648\u0646\u200c\u0647\u0627\u06cc \u0634\u062e\u0635\u06cc\u062a\u06cc\u060c \u062a\u0633\u062a mmpi \u0628\u0631 \u0627\u0633\u0627\u0633 \u0646\u0638\u0631\u06cc\u0647\u200c\u0647\u0627\u06cc \u0631\u0627\u06cc\u062c \u062e\u0627\u0635\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0634\u062e\u0635\u06cc\u062a\u060c \u0645\u0627\u0646\u0646\u062f \u0645\u062f\u0644 \u067e\u0646\u062c \u0639\u0627\u0645\u0644\u06cc \u06cc\u0627 \u06f1\u06f6 \u0634\u062e\u0635\u06cc\u062a \u0646\u0628\u0648\u062f. \u0627\u06cc\u0646 \u062a\u0633\u062a \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0628\u0647 \u0633\u0627\u062f\u06af\u06cc \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u0645\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u06cc\u06a9 \u0641\u0631\u062f \u062f\u0631 \u06f1\u06f0 \u0645\u0642\u06cc\u0627\u0633 \u0645\u062e\u062a\u0644\u0641 \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u06a9\u062c\u0627\u06cc \u0637\u06cc\u0641 \u0642\u0631\u0627\u0631 \u0645\u06cc \u06af\u06cc\u0631\u062f \u062a\u0627 \u0645\u0634\u06a9\u0644 \u0631\u0627 \u062a\u0634\u062e\u06cc\u0635 \u062f\u0647\u062f \u0648 \u062f\u0631\u0645\u0627\u0646 \u0645\u0646\u0627\u0633\u0628 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u062f.<\/p>\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u062a\u0633\u062a \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u062f\u0627\u0631\u0627\u06cc \u062f\u0648 \u0646\u0633\u062e\u0647 \u062f\u0631 \u062d\u0627\u0644 \u06a9\u0627\u0631 \u0627\u0633\u062a\u060c \u0646\u0633\u062e\u0647 \u0627\u0635\u0644\u06cc \u0622\u0646 MMPI \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u062f\u0647\u0647 \u06f1\u06f9\u06f4\u06f0 \u062a\u0648\u0633\u0639\u0647 \u06cc\u0627\u0641\u062a \u0648 \u0647\u0646\u0648\u0632 \u0647\u0645 \u062f\u0631 \u062d\u0627\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0633\u062a. MMPI \u0627\u0632 \u0635\u062f\u0647\u0627 \u0633\u0624\u0627\u0644 \u062f\u0631\u0633\u062a\/\u063a\u0644\u0637 \u06a9\u0647 \u0627\u062d\u0633\u0627\u0633 \u0645\u06cc\u200c\u0634\u062f \u062f\u0631 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0627\u0628\u0639\u0627\u062f \u0634\u062e\u0635\u06cc\u062a \u0645\u0641\u06cc\u062f \u0627\u0633\u062a\u060c \u0627\u06cc\u062c\u0627\u062f \u0634\u062f. \u0633\u067e\u0633 \u0627\u06cc\u0646 \u0633\u0648\u0627\u0644\u0627\u062a \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0631\u0646\u062c \u0645\u06cc \u0628\u0631\u062f\u0646\u062f \u0648 \u06af\u0631\u0648\u0647\u06cc \u06a9\u0647 \u0627\u0632 \u0647\u06cc\u0686 \u0627\u062e\u062a\u0644\u0627\u0644\u06cc \u0631\u0646\u062c \u0646\u0645\u06cc \u0628\u0631\u062f\u0646\u062f\u060c \u0627\u0631\u0627\u0626\u0647 \u0634\u062f.<\/p>\r\n<p style=\"text-align: justify;\">\u0633\u067e\u0633 \u0622\u0646\u0647\u0627 \u0633\u0624\u0627\u0644\u0627\u062a\u06cc \u0631\u0627 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u06a9\u0631\u062f\u0646\u062f \u06a9\u0647 \u0627\u06a9\u062b\u0631 \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0627\u0632 \u0646\u0648\u0639 \u062e\u0627\u0635\u06cc \u0627\u0632 \u0627\u062e\u062a\u0644\u0627\u0644 \u0631\u0646\u062c \u0645\u06cc \u0628\u0631\u0646\u062f \u0628\u0647 \u0622\u0646\u0647\u0627 \u067e\u0627\u0633\u062e \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0639\u0627\u062f\u06cc \u062a\u0634\u062e\u06cc\u0635 \u062f\u0627\u062f\u0647 \u0634\u062f\u0647 \u0628\u0648\u062f\u0646\u062f\u060c \u0645\u06cc \u062f\u0627\u062f\u0646\u062f. \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647\u060c \u0627\u06af\u0631 \u0641\u0631\u062f\u06cc \u062a\u0645\u0627\u06cc\u0644 \u062f\u0627\u0634\u062a \u0628\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0633\u0648\u0627\u0644\u0627\u062a \u0628\u0647 \u0631\u0648\u0634\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u067e\u0627\u0631\u0627\u0646\u0648\u0626\u06cc\u062f \u067e\u0627\u0633\u062e \u0645\u06cc\u200c\u062f\u0647\u0646\u062f\u060c \u067e\u0627\u0633\u062e \u062f\u0647\u062f\u060c \u0628\u0647 \u0627\u062d\u062a\u0645\u0627\u0644 \u0632\u06cc\u0627\u062f \u0622\u0646 \u0641\u0631\u062f \u0646\u06cc\u0632 \u067e\u0627\u0631\u0627\u0646\u0648\u0626\u06cc\u062f \u0628\u0648\u062f.<\/p>\r\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-16216 size-full\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-mmpi.jpg\" alt=\"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627\" width=\"1001\" height=\"645\" srcset=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-mmpi.jpg 1001w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-mmpi-300x193.jpg 300w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-mmpi-768x495.jpg 768w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-mmpi-585x377.jpg 585w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D8%AA%D8%B3%D8%AA_MMPI_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span><strong><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06a9\u0627\u0631\u0628\u0631\u062f \u062a\u0633\u062a MMPI \u0686\u06cc\u0633\u062a\u061f<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p id=\"4\" style=\"text-align: justify;\">\u062a\u0633\u062a MMPI \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0628\u0631\u0627\u06cc \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0648 \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u061b \u0627\u0645\u0627 \u062e\u0627\u0631\u062c \u0627\u0632 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u062f\u0631\u0645\u0627\u0646\u06cc \u0647\u0645 \u06a9\u0627\u0631\u0628\u0631\u062f \u062f\u0627\u0631\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0627\u0632 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0648 \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0627\u062b\u0631\u0628\u062e\u0634\u06cc \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0633\u0648\u0621 \u0645\u0635\u0631\u0641 \u0645\u0648\u0627\u062f \u0647\u0645 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062a\u0633\u062a mmpi \u0627\u063a\u0644\u0628 \u062f\u0631 \u067e\u0631\u0648\u0646\u062f\u0647 \u0647\u0627\u06cc \u062d\u0642\u0648\u0642\u06cc\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u062f\u0641\u0627\u0639 \u062c\u0646\u0627\u06cc\u06cc \u0648 \u0627\u062e\u062a\u0644\u0627\u0641\u0627\u062a \u062d\u0636\u0627\u0646\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f.<\/p>\r\n<blockquote>\r\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/ravandarman.com\/blog\/rorschach-test\/\" target=\"_blank\" rel=\"noopener\">\u062a\u0633\u062a \u0631\u0648\u0631\u0634\u0627\u062e \u0686\u06cc\u0633\u062a\u061f \u06f1\u06f0 \u06a9\u0627\u0631\u062a \u0622\u0632\u0645\u0648\u0646 \u0631\u0648\u0631\u0634\u0627\u062e \u0628\u0627 \u062a\u0641\u0633\u06cc\u0631 \u0648 \u0646\u0645\u0631\u0647 \u06af\u0630\u0627\u0631\u06cc<\/a><\/strong><\/p>\r\n<\/blockquote>\r\n\r\n\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%86%D8%B3%D8%AE%D9%87_%D9%87%D8%A7%DB%8C_%D8%AA%D8%B3%D8%AA_mmpi\"><\/span><strong><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0646\u0633\u062e\u0647 \u0647\u0627\u06cc \u062a\u0633\u062a mmpi<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u062f\u0631 \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u0627\u0648\u0644 \u067e\u0633 \u0627\u0632 \u0627\u0646\u062a\u0634\u0627\u0631 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627\u060c \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0632 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u0648 \u0645\u062d\u0642\u0642\u0627\u0646 \u0635\u062d\u062a \u0648 \u0627\u0639\u062a\u0628\u0627\u0631 \u062a\u0633\u062a MMPI \u0631\u0627 \u0632\u06cc\u0631 \u0633\u0648\u0627\u0644 \u0628\u0631\u062f\u0646\u062f. \u0627\u0646\u062a\u0642\u0627\u062f \u0622\u0646\u200c\u0647\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u062a\u0633\u062a\u060c \u0633\u0648\u06af\u06cc\u0631\u06cc \u062f\u0627\u0634\u062a\u0646 \u0646\u062a\u0627\u06cc\u062c \u0622\u0646 \u0628\u0648\u062f. \u0628\u0631\u062e\u06cc \u062f\u06cc\u06af\u0631 \u0647\u0645 \u0628\u0647 \u062c\u0646\u0633\u06cc\u062a \u0632\u062f\u06af\u06cc \u0648 \u0646\u0698\u0627\u062f\u067e\u0631\u0633\u062a\u0627\u0646\u0647 \u0628\u0648\u062f\u0646 \u0628\u0631\u062e\u06cc \u0633\u0648\u0627\u0644\u0627\u062a \u0627\u06cc\u0646 \u062a\u0633\u062a \u0627\u0646\u062a\u0642\u0627\u062f \u062f\u0627\u0634\u062a\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0628\u0647 \u062f\u0644\u06cc\u0644 \u0627\u0646\u062a\u0642\u0627\u062f\u0627\u062a\u06cc \u06a9\u0647 \u0628\u0647 \u067e\u0631\u0633\u0634\u0646\u0627\u0645\u0647 \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0648\u0627\u0631\u062f \u0634\u062f \u062f\u0631 \u0627\u0648\u0627\u062e\u0631 \u062f\u0647\u0647 \u06f1\u06f9\u06f8\u06f0 \u0645\u06cc\u0644\u0627\u062f\u06cc \u0628\u0627\u0632\u0646\u06af\u0631\u06cc \u062f\u0631 \u062a\u0633\u062a \u0627\u0646\u062c\u0627\u0645 \u0634\u062f. \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0633\u0648\u0627\u0644\u0627\u062a \u062a\u0633\u062a \u062d\u0630\u0641 \u0634\u062f\u060c \u0633\u0648\u0627\u0644\u0627\u062a \u062c\u062f\u06cc\u062f \u0627\u0636\u0627\u0641\u0647 \u0634\u062f \u0648 \u0628\u0631\u062e\u06cc \u0627\u0632 \u0633\u0648\u0627\u0644\u0627\u062a \u0647\u0645 \u0645\u0648\u0631\u062f \u0628\u0627\u0632\u0628\u06cc\u0646\u06cc \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631\u0647\u0627\u06cc \u0631\u0648\u0627\u06cc\u06cc \u062c\u062f\u06cc\u062f\u06cc \u062f\u0631 \u0646\u0633\u062e\u0647 \u0628\u0627\u0632\u0628\u06cc\u0646\u06cc \u0634\u062f\u0647 \u062a\u0633\u062a \u06af\u0646\u062c\u0627\u0646\u062f\u0647 \u0634\u062f.<\/p>\r\n\r\n\r\n\r\n<p id=\"5\" style=\"text-align: justify;\">\u0646\u0633\u062e\u0647 \u0628\u0627\u0632\u0628\u06cc\u0646\u06cc \u0634\u062f\u0647 \u062a\u0633\u062a \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f9\u06f8\u06f9 \u0628\u0627 \u0639\u0646\u0648\u0627\u0646 \u062a\u0633\u062a MMPI2 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f. \u062f\u0631 \u0633\u0627\u0644 \u06f2\u06f0\u06f0\u06f1 \u062f\u0648\u0628\u0627\u0631\u0647 \u067e\u0631\u0633\u0634\u0646\u0627\u0645\u0647 mmpi \u0645\u0648\u0631\u062f \u0628\u0627\u0632\u0628\u06cc\u0646\u06cc \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a \u0648 \u062f\u0631 \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u06f2\u06f0\u06f0\u06f5 \u0648 \u06f2\u06f0\u06f0\u06f9 \u062f\u0648\u0628\u0627\u0631\u0647 \u0628\u0647 \u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc \u0634\u062f. \u0646\u0633\u062e\u0647 \u0647\u0627\u06cc \u062a\u0633\u062a mmpi \u0628\u0631 \u0627\u0633\u0627\u0633 \u0647\u0646\u062c\u0627\u0631\u0647\u0627 \u0648 \u0645\u0642\u06cc\u0627\u0633 \u0647\u0627\u06cc \u0628\u0627\u0644\u06cc\u0646\u06cc \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u0647\u0633\u062a\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u0627\u0646\u0648\u0627\u0639 \u0645\u062e\u062a\u0644\u0641\u06cc \u0627\u0632 MMPI \u062f\u0631 \u062d\u0627\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0639\u0645\u0648\u0645\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f:<\/p>\r\n\r\n\r\n\r\n<ol style=\"text-align: justify;\">\r\n<li><strong>MMPI 2:<\/strong> \u0627\u06cc\u0646 \u0646\u0633\u062e\u0647 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u0627\u0646 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0628\u0631\u0627\u06cc \u0627\u0648\u0644\u06cc\u0646 \u0628\u0627\u0631 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f9\u06f8\u06f9 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f. \u062d\u0627\u0648\u06cc \u06f5\u06f6\u06f7 \u0633\u0648\u0627\u0644 \u062f\u0631\u0633\u062a \u0648 \u063a\u0644\u0637 \u0627\u0633\u062a \u0648 \u06f6\u06f0 \u062a\u0627 \u06f9\u06f0 \u062f\u0642\u06cc\u0642\u0647 \u0637\u0648\u0644 \u0645\u06cc \u06a9\u0634\u062f \u062a\u0627 \u062a\u06a9\u0645\u06cc\u0644 \u0634\u0648\u062f. \u0628\u0631\u0627\u06cc \u0645\u0646\u0639\u06a9\u0633 \u06a9\u0631\u062f\u0646 \u0627\u0631\u0632\u0634\u200c\u0647\u0627\u06cc \u0641\u0631\u0647\u0646\u06af\u06cc \u0645\u062a\u0646\u0648\u0639\u200c\u062a\u0631 \u0646\u0633\u0628\u062a \u0628\u0647 \u0646\u0633\u062e\u0647 \u0627\u0635\u0644\u06cc \u06f1\u06f9\u06f4\u06f2 \u0628\u0627\u0632\u0628\u06cc\u0646\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a.<\/li>\r\n<li><strong>MMPI 2-\u0641\u0631\u0645 \u06a9\u0648\u062a\u0627\u0647:<\/strong> \u0627\u06cc\u0646 \u0646\u0633\u062e\u0647 \u06a9\u0647 \u062f\u0631 \u0633\u0627\u0644 \u06f2\u06f0\u06f0\u06f8 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f\u060c \u0646\u0633\u062e\u0647 \u06a9\u0648\u062a\u0627\u0647\u062a\u0631 MMPI-2 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0628\u0631\u0627\u06cc \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u0627\u0646 \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a \u0648 \u0634\u0627\u0645\u0644 \u06f3\u06f3\u06f8 \u0645\u0648\u0631\u062f \u062f\u0631\u0633\u062a\/\u063a\u0644\u0637 \u0627\u0633\u062a. \u0646\u0633\u062e\u0647 \u0641\u0627\u0631\u0633\u06cc \u0622\u0646 \u06f3\u06f7\u06f0 \u0633\u0648\u0627\u0644 \u0627\u0633\u062a.<\/li>\r\n<li><strong>MMPI \u0646\u0648\u062c\u0648\u0627\u0646:<\/strong>\u00a0\u0627\u06cc\u0646 \u0646\u0633\u062e\u0647 \u0627\u06cc \u0627\u0632 \u0622\u0632\u0645\u0648\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f9\u06f9\u06f2 \u0628\u0631\u0627\u06cc \u0646\u0648\u062c\u0648\u0627\u0646\u0627\u0646 \u06f1\u06f4 \u062a\u0627 \u06f1\u06f8 \u0633\u0627\u0644 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f. MMPI-A \u0634\u0627\u0645\u0644 \u06f4\u06f7\u06f8 \u0645\u0648\u0631\u062f \u0627\u0633\u062a \u0648 \u062a\u06a9\u0645\u06cc\u0644 \u0622\u0646 \u062d\u062f\u0648\u062f \u06f6\u06f0 \u062f\u0642\u06cc\u0642\u0647 \u0637\u0648\u0644 \u0645\u06cc \u06a9\u0634\u062f.<\/li>\r\n<li><strong>MMPI \u0646\u0648\u062c\u0648\u0627\u0646 \u0641\u0631\u0645 \u06a9\u0648\u062a\u0627\u0647:<\/strong>\u00a0\u0627\u06cc\u0646 \u0641\u0631\u0645 \u06a9\u0648\u062a\u0627\u0647 \u0627\u0632 \u0622\u0632\u0645\u0648\u0646 \u0628\u0631\u0627\u06cc \u0646\u0648\u062c\u0648\u0627\u0646\u0627\u0646 \u062f\u0631 \u0633\u0627\u0644 \u06f2\u06f0\u06f1\u06f6 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f \u06a9\u0647 \u0634\u0627\u0645\u0644 \u06f2\u06f4\u06f1 \u0645\u0648\u0631\u062f \u0627\u0633\u062a \u0648 \u062a\u06a9\u0645\u06cc\u0644 \u0622\u0646 \u06f2\u06f5 \u062a\u0627 \u06f4\u06f5 \u062f\u0642\u06cc\u0642\u0647 \u0632\u0645\u0627\u0646 \u0645\u06cc \u0628\u0631\u062f.<\/li>\r\n<li><strong>MMPI 3:<\/strong> \u0627\u06cc\u0646 \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0646\u0633\u062e\u0647 \u062a\u0633\u062a MMPI \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0633\u0627\u0644 \u06f2\u06f0\u06f2\u06f0 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f. \u0645\u0648\u0627\u0631\u062f\u060c \u0645\u0642\u06cc\u0627\u0633\u200c\u0647\u0627 \u0648 \u0647\u0646\u062c\u0627\u0631\u0647\u0627\u06cc \u0622\u0646 \u0628\u0647\u200c\u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0634\u0627\u0645\u0644 \u06f3\u06f3\u06f5 \u0645\u0648\u0631\u062f \u0627\u0633\u062a \u0648 \u062a\u06a9\u0645\u06cc\u0644 \u0622\u0646 \u06f2\u06f5 \u062a\u0627 \u06f5\u06f0 \u062f\u0642\u06cc\u0642\u0647 \u0637\u0648\u0644 \u0645\u06cc \u06a9\u0634\u062f.<\/li>\r\n<\/ol>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%86%D8%AD%D9%88%D9%87_%D8%A7%D8%AC%D8%B1%D8%A7%DB%8C_%D8%AA%D8%B3%D8%AA_mmpi\"><\/span><strong><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0646\u062d\u0648\u0647 \u0627\u062c\u0631\u0627\u06cc \u062a\u0633\u062a mmpi<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 MMPI-2 \u0634\u0627\u0645\u0644 \u06f5\u06f6\u06f7 \u067e\u0631\u0633\u0634 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0632\u0645\u0627\u0646\u06cc \u062d\u062f\u0648\u062f \u06f6\u06f0 \u0627\u0644\u06cc \u06f9\u06f0 \u062f\u0642\u06cc\u0642\u0647 \u0627\u062d\u062a\u06cc\u0627\u062c \u062f\u0627\u0631\u062f. \u062a\u0633\u062a mmpi 2 \u0641\u0631\u0645 \u06a9\u0648\u062a\u0627\u0647 \u0634\u0627\u0645\u0644 \u06f3\u06f7\u06f0 \u0633\u0648\u0627\u0644 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0632\u0645\u0627\u0646 \u062d\u062f\u0648\u062f \u06f3\u06f5 \u0627\u0644\u06cc \u06f5\u06f0 \u062f\u0642\u06cc\u0642\u0647 \u0627\u062d\u062a\u06cc\u0627\u062c \u062f\u0627\u0631\u062f.<\/p>\r\n\r\n\r\n\r\n<p id=\"6\" style=\"text-align: justify;\">\u0627\u062c\u0631\u0627\u06cc \u0627\u06cc\u0646 \u062a\u0633\u062a\u060c \u0646\u0645\u0631\u0647 \u06af\u0630\u0627\u0631\u06cc \u0648 \u062a\u0641\u0633\u06cc\u0631 \u0622\u0646 \u0628\u0627\u06cc\u062f \u062a\u062d\u062a \u0646\u0638\u0631 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u062f. \u0627\u0632 \u0627\u06cc\u0646 \u062a\u0633\u062a \u0628\u0627\u06cc\u062f \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0633\u0627\u06cc\u0631 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u062f. \u062f\u0631 \u0648\u0627\u0642\u0639 \u0628\u0631\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0628\u0647 \u0647\u06cc\u0686 \u0648\u062c\u0647 \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u062a\u0646\u0647\u0627 \u0628\u0647 \u0646\u062a\u0627\u06cc\u062c \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0627\u06a9\u062a\u0641\u0627 \u06a9\u0631\u062f.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a mmpi \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0635\u0648\u0631\u062a \u0641\u0631\u062f\u06cc \u06cc\u0627 \u06af\u0631\u0648\u0647\u06cc \u0627\u062c\u0631\u0627 \u06a9\u0631\u062f \u0648 \u062a\u0633\u062a mmpi \u0622\u0646\u0644\u0627\u06cc\u0646 \u0646\u06cc\u0632 \u0645\u0648\u062c\u0648\u062f \u0627\u0633\u062a. \u0647\u0631 \u062f\u0648 MMPI 2 \u0648 MMPI 2 \u0641\u0631\u0645 \u06a9\u0648\u062a\u0627\u0647 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f \u06f1\u06f8 \u0633\u0627\u0644 \u0648 \u0628\u0627\u0644\u0627\u062a\u0631 \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0646\u062f. \u0627\u06cc\u0646 \u0622\u0632\u0645\u0648\u0646 \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0627 \u062f\u0633\u062a \u06cc\u0627 \u0631\u0627\u06cc\u0627\u0646\u0647 \u0646\u0645\u0631\u0647 \u062f\u0627\u062f\u060c \u0627\u0645\u0627 \u0646\u062a\u0627\u06cc\u062c \u0628\u0627\u06cc\u062f \u0647\u0645\u06cc\u0634\u0647 \u062a\u0648\u0633\u0637 \u06cc\u06a9 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u060c \u062a\u0641\u0633\u06cc\u0631 \u0634\u0648\u062f.<\/p>\r\n<div class=\"custom-box-specialist\"><div class=\"content\"><strong>\u062c\u0647\u062a \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u0634\u0627\u0648\u0631\u0647 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc\u060c \u0631\u0648\u0627\u0646\u067e\u0632\u0634\u06a9\u06cc \u0648 \u0631\u0648\u0627\u0646\u06a9\u0627\u0648\u06cc \u0628\u0627 \u0645\u062c\u0631\u0628\u200c\u062a\u0631\u06cc\u0646 \u062f\u0631\u0645\u0627\u0646\u06af\u0631\u0627\u0646 \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u06cc\u062f:<\/strong>\r\n<ul>\r\n \t<li><a href=\"https:\/\/ravandarman.com\/psychologists\/1c-tehran\" target=\"_blank\" rel=\"noopener\"><strong>\u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u062e\u0648\u0628 \u062f\u0631 \u062a\u0647\u0631\u0627\u0646<\/strong><\/a><\/li>\r\n \t<li><a href=\"https:\/\/ravandarman.com\/psychologists\/2c-shiraz\" target=\"_blank\" rel=\"noopener\"><strong>\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u0634\u06cc\u0631\u0627\u0632\u00a0<\/strong><\/a><\/li>\r\n \t<li><a href=\"https:\/\/ravandarman.com\/psychologists\/13c-tabriz\" target=\"_blank\" rel=\"noopener\"><strong>\u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u062e\u0648\u0628 \u062f\u0631 \u062a\u0628\u0631\u06cc\u0632<\/strong><\/a><\/li>\r\n<\/ul>\r\n<strong>\u0628\u0631\u0627\u06cc \u0627\u0631\u062a\u0628\u0627\u0637 \u0648 \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u0634\u0627\u0648\u0631\u0647 \u0628\u0627 <a href=\"https:\/\/ravandarman.com\/psychologists\" target=\"_blank\" rel=\"noopener\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646<\/a> \u062f\u0631 \u062a\u0645\u0627\u0645 \u0646\u0642\u0627\u0637 \u0627\u06cc\u0631\u0627\u0646 \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f.<\/strong><\/div><img decoding=\"async\" class=\"img-box-spec\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2025\/07\/svg-spec.svg\"><\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D8%A8%D8%A7%D9%84%DB%8C%D9%86%DB%8C_%D8%AA%D8%B3%D8%AA_MMPI\"><\/span><strong><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631\u0647\u0627\u06cc \u0628\u0627\u0644\u06cc\u0646\u06cc \u062a\u0633\u062a MMPI<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0645\u0642\u06cc\u0627\u0633 \u0647\u0627\u06cc \u062a\u0633\u062a MMPI \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u0628\u0641\u0647\u0645\u0646\u062f \u062f\u0631 \u062f\u0647 \u0645\u0642\u06cc\u0627\u0633 \u0645\u062e\u062a\u0644\u0641 \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u06a9\u062c\u0627 \u0647\u0633\u062a\u06cc\u062f. \u0647\u0631 \u0645\u0642\u06cc\u0627\u0633 \u0628\u0647 \u06cc\u06a9 \u0627\u0644\u06af\u0648\u06cc \u0631\u0648\u0627\u0646\u06cc \u06cc\u0627 \u0634\u0631\u0627\u06cc\u0637 \u0645\u062a\u0641\u0627\u0648\u062a \u0645\u0631\u0628\u0648\u0637 \u0645\u06cc \u0634\u0648\u062f\u060c \u0627\u0645\u0627 \u0647\u0645\u067e\u0648\u0634\u0627\u0646\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0628\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0647\u0627 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc\u060c \u0646\u0645\u0631\u0627\u062a \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0646\u0634\u0627\u0646 \u062f\u0647\u0646\u062f\u0647 \u06cc\u06a9 \u0627\u062e\u062a\u0644\u0627\u0644 \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u0628\u0627\u0634\u062f. \u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u062a\u0648\u0636\u06cc\u062d \u0645\u062e\u062a\u0635\u0631\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0622\u0646\u0686\u0647 \u06a9\u0647 \u0647\u0631 \u0645\u0642\u06cc\u0627\u0633 \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0645\u06cc \u06a9\u0646\u062f \u0622\u0648\u0631\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06f1. <a href=\"https:\/\/ravandarman.com\/blog\/health-anxiety\/\" target=\"_blank\" rel=\"noopener\">\u062e\u0648\u062f\u0628\u06cc\u0645\u0627\u0631\u0627\u0646\u06af\u0627\u0631\u06cc<\/a> \u06cc\u0627 \u0647\u06cc\u067e\u0648\u06a9\u0646\u062f\u0631\u06cc\u0627\u0632\u06cc\u0633 <strong>(Hs)<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0634\u0627\u0645\u0644 \u06f3\u06f2 \u0622\u06cc\u062a\u0645 \u0627\u0633\u062a \u0648 \u0628\u0631\u0627\u06cc \u0633\u0646\u062c\u0634 \u0627\u06cc\u0646\u06a9\u0647 \u0622\u06cc\u0627 \u0646\u06af\u0631\u0627\u0646\u06cc \u0646\u0627\u0633\u0627\u0644\u0645\u06cc \u0628\u0631\u0627\u06cc \u0633\u0644\u0627\u0645\u062a\u06cc \u062e\u0648\u062f \u062f\u0627\u0631\u06cc\u062f \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0646\u06af\u0631\u0627\u0646\u06cc\u200c\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0645\u0628\u0647\u0645 \u0647\u0633\u062a\u0646\u062f \u0648 \u0639\u0644\u06cc\u200c\u0631\u063a\u0645 \u062a\u0623\u06cc\u06cc\u062f \u0646\u0634\u062f\u0646 \u0622\u0646\u0647\u0627 \u0627\u062f\u0627\u0645\u0647 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f. \u0646\u0645\u0631\u0647 \u0628\u0627\u0644\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0646\u06af\u0631\u0627\u0646\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0633\u0644\u0627\u0645\u062a\u06cc \u0634\u0645\u0627 \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0634\u0645\u0627 \u0627\u062e\u062a\u0644\u0627\u0644 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u0645\u0634\u06a9\u0644\u0627\u062a\u06cc \u062f\u0631 \u0631\u0648\u0627\u0628\u0637 \u0634\u0645\u0627 \u0645\u06cc \u0634\u0648\u062f.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">\u0622\u06cc\u062a\u0645 \u0647\u0627\u06cc \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0628\u0647 \u0639\u0644\u0627\u0626\u0645 \u062c\u0633\u0645\u0627\u0646\u06cc \u0648 \u0628\u0647\u0632\u06cc\u0633\u062a\u06cc \u0645\u0631\u0628\u0648\u0637 \u0645\u06cc \u0634\u0648\u0646\u062f. \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0645\u062b\u0627\u0644\u060c \u0641\u0631\u062f\u06cc \u0628\u0627 \u0646\u0645\u0631\u0647 \u0645\u0642\u06cc\u0627\u0633 \u06f1 \u0628\u0627\u0644\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u0633\u062a\u0639\u062f \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0639\u0644\u0627\u0626\u0645 \u062c\u0633\u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u062f\u0644\u06cc\u0644 \u0632\u0645\u06cc\u0646\u0647\u200c\u0627\u06cc \u0646\u062f\u0627\u0631\u0646\u062f\u060c \u0628\u0647 \u062e\u0635\u0648\u0635 \u062f\u0631 \u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u0627\u0633\u062a\u0631\u0633 \u0628\u0627\u0644\u0627.<\/span><\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06f2. <a href=\"https:\/\/ravandarman.com\/blog\/%d8%a7%d9%81%d8%b3%d8%b1%d8%af%da%af%db%8c\/\" target=\"_blank\" rel=\"noopener\">\u0627\u0641\u0633\u0631\u062f\u06af\u06cc<\/a> <strong>(D)<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0628\u0631\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0627\u0641\u0633\u0631\u062f\u06af\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0628\u0648\u062f \u06a9\u0647 \u0628\u0627 \u0631\u0648\u062d\u06cc\u0647 \u0636\u0639\u06cc\u0641\u060c \u0639\u062f\u0645 \u0627\u0645\u06cc\u062f \u0628\u0647 \u0622\u06cc\u0646\u062f\u0647 \u0648 \u0646\u0627\u0631\u0636\u0627\u06cc\u062a\u06cc \u0639\u0645\u0648\u0645\u06cc \u0627\u0632 \u0648\u0636\u0639\u06cc\u062a \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0645\u0634\u062e\u0635 \u0645\u06cc \u0634\u0648\u062f. \u0646\u0645\u0631\u0627\u062a \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0646\u0634\u0627\u0646 \u062f\u0647\u0646\u062f\u0647 \u0627\u0641\u0633\u0631\u062f\u06af\u06cc \u0628\u0627\u0634\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0646\u0645\u0631\u0627\u062a \u0645\u062a\u0648\u0633\u0637 \u062a\u0645\u0627\u06cc\u0644 \u0628\u0647 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0646 \u0646\u0627\u0631\u0636\u0627\u06cc\u062a\u06cc \u06a9\u0644\u06cc \u0627\u0632 \u0632\u0646\u062f\u06af\u06cc \u062f\u0627\u0631\u062f.<br \/>\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u06a9\u0647 \u062f\u0627\u0631\u0627\u06cc \u06f5\u06f7 \u06af\u0648\u06cc\u0647 \u0627\u0633\u062a \u0645\u06cc\u0632\u0627\u0646 \u0631\u0636\u0627\u06cc\u062a \u0627\u0632 \u0632\u0646\u062f\u06af\u06cc \u0634\u0645\u0627 \u0631\u0627 \u0645\u06cc \u0633\u0646\u062c\u062f. \u0641\u0631\u062f\u06cc \u0628\u0627 \u0646\u0645\u0631\u0647 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627 \u062f\u0631 \u0645\u0642\u06cc\u0627\u0633 \u06f2 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u0627\u0641\u0633\u0631\u062f\u06af\u06cc \u0628\u0627\u0644\u06cc\u0646\u06cc \u06cc\u0627 \u0627\u0641\u06a9\u0627\u0631 \u062e\u0648\u062f\u06a9\u0634\u06cc \u0645\u06a9\u0631\u0631 \u0633\u0631 \u0648 \u06a9\u0627\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u06cc\u06a9 \u0627\u0645\u062a\u06cc\u0627\u0632 \u06a9\u0645\u06cc \u0628\u0627\u0644\u0627\u062a\u0631 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0646\u0634\u0627\u0646\u0647 \u0627\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0634\u0645\u0627 \u0627\u0632 \u0634\u0631\u0627\u06cc\u0637 \u062e\u0648\u062f \u06a9\u0646\u0627\u0631\u0647 \u06af\u06cc\u0631\u06cc \u06a9\u0631\u062f\u0647 \u0627\u06cc\u062f \u06cc\u0627 \u0646\u0627\u0631\u0627\u0636\u06cc \u0647\u0633\u062a\u06cc\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06f3. \u0647\u06cc\u0633\u062a\u0631\u06cc <strong>(Hy)<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u06f6\u06f0 \u0645\u0627\u062f\u0647 \u0627\u06cc \u067e\u0627\u0633\u062e \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u0627\u0633\u062a\u0631\u0633\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u0639\u0644\u0627\u0626\u0645 \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u0648 \u0648\u0627\u06a9\u0646\u0634 \u0639\u0627\u0637\u0641\u06cc \u0628\u0647 \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0628\u0648\u062f\u0646\u060c \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0645\u06cc \u06a9\u0646\u062f. \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u0645\u0628\u062a\u0644\u0627 \u0628\u0647 \u062f\u0631\u062f \u0645\u0632\u0645\u0646 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0633\u0647 \u0645\u0642\u06cc\u0627\u0633 \u0627\u0648\u0644 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0646\u06af\u0631\u0627\u0646\u06cc\u200c\u0647\u0627\u06cc \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0644\u0627\u0645\u062a\u06cc\u060c \u0627\u0645\u062a\u06cc\u0627\u0632 \u0628\u06cc\u0634\u062a\u0631\u06cc \u06a9\u0633\u0628 \u06a9\u0646\u0646\u062f.<\/span><\/p>\r\n<p style=\"text-align: justify;\">\u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u062a\u062d\u0635\u06cc\u0644\u0627\u062a \u062e\u0648\u0628\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u0627\u0632 \u0637\u0628\u0642\u0647 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0627\u0644\u0627\u06cc\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0647\u0633\u062a\u0646\u062f\u060c \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0627\u0645\u062a\u06cc\u0627\u0632 \u0628\u06cc\u0634\u062a\u0631\u06cc \u06a9\u0633\u0628 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0632\u0646\u0627\u0646 \u0646\u06cc\u0632 \u062a\u0645\u0627\u06cc\u0644 \u062f\u0627\u0631\u0646\u062f \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0646\u0645\u0631\u0627\u062a \u0628\u0627\u0644\u0627\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0645\u0631\u062f\u0627\u0646 \u06a9\u0633\u0628 \u06a9\u0646\u0646\u062f. \u0645\u0642\u06cc\u0627\u0633 \u0647\u06cc\u0633\u062a\u0631\u06cc \u067e\u0646\u062c \u062c\u0646\u0628\u0647 \u0627\u0632 \u06cc\u06a9 \u0641\u0631\u062f \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u0645\u06cc \u06a9\u0646\u062f: \u0633\u0644\u0627\u0645\u062a \u062c\u0633\u0645\u0627\u0646\u06cc \u0636\u0639\u06cc\u0641\u060c \u062e\u062c\u0627\u0644\u062a\u06cc \u0628\u0648\u062f\u0646\u060c \u0628\u062f\u0628\u06cc\u0646\u06cc\u060c \u0633\u0631\u062f\u0631\u062f\u060c \u0631\u0648\u0627\u0646 \u0631\u0646\u062c\u0648\u0631\u06cc. \u0646\u0645\u0631\u0647 \u0628\u0627\u0644\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0627\u0646\u0648\u0627\u0639 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u0645\u0627\u0646\u0646\u062f \u0627\u0636\u0637\u0631\u0627\u0628\u060c \u067e\u0627\u0631\u0627\u0646\u0648\u06cc\u0627 \u06cc\u0627 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u062a\u062c\u0632\u06cc\u0647 \u0627\u06cc \u0627\u0634\u0627\u0631\u0647 \u06a9\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06f4. \u0627\u0646\u062d\u0631\u0627\u0641 \u0631\u0648\u0627\u0646\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc <strong>(Pd)<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0628\u0631\u0627\u06cc \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0646 \u0627\u06cc\u0646 \u0628\u0648\u062f \u06a9\u0647 \u0622\u06cc\u0627 \u0634\u0645\u0627 \u06cc\u06a9 \u0622\u0633\u06cc\u0628 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u062e\u062a\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc \u06a9\u0646\u06cc\u062f \u06cc\u0627 \u062e\u06cc\u0631. \u06f5\u06f0 \u0645\u0648\u0631\u062f \u0622\u0646\u060c \u0631\u0641\u062a\u0627\u0631\u0647\u0627 \u0648 \u0646\u06af\u0631\u0634\u200c\u0647\u0627\u06cc \u0636\u062f\u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0631\u0627 \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u062a\u0628\u0639\u06cc\u062a \u06cc\u0627 \u0645\u0642\u0627\u0648\u0645\u062a \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0642\u062f\u0631\u062a\u060c \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06af\u0631 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0627\u0645\u062a\u06cc\u0627\u0632 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627\u06cc\u06cc \u06a9\u0633\u0628 \u06a9\u0646\u06cc\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644 \u0634\u062e\u0635\u06cc\u062a \u0631\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u06cc\u062f.\u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0627\u0645\u062a\u06cc\u0627\u0632 \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u0646\u062f \u0628\u06cc\u0634\u062a\u0631 \u0633\u0631\u06a9\u0634 \u0647\u0633\u062a\u0646\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u06a9\u0645 \u0627\u0645\u062a\u06cc\u0627\u0632 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0642\u062a\u062f\u0627\u0631 \u0631\u0627 \u0645\u06cc \u067e\u0630\u06cc\u0631\u0646\u062f.<\/span><\/p>\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u062d\u0633\u0627\u0633 \u0628\u06cc\u06af\u0627\u0646\u06af\u06cc \u0627\u0632 \u062e\u0648\u062f \u0648 \u062c\u0627\u0645\u0639\u0647 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u06a9\u0633\u0627\u0644\u062a \u0631\u0627 \u0645\u06cc \u0633\u0646\u062c\u062f. \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u06a9\u0647 \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0628\u0631\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0627\u0641\u0631\u0627\u062f \u0631\u0648\u0627\u0646 \u067e\u0631\u06cc\u0634 \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u060c \u0627\u0646\u062d\u0631\u0627\u0641 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u0639\u062f\u0645 \u067e\u0630\u06cc\u0631\u0634 \u0627\u0642\u062a\u062f\u0627\u0631 \u0648 \u0628\u06cc \u0627\u062e\u0644\u0627\u0642\u06cc (\u0628\u06cc \u062a\u0648\u062c\u0647\u06cc \u0628\u0647 \u0627\u062e\u0644\u0627\u0642) \u0631\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u0645\u06cc \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0645\u0639\u06cc\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u0646\u0627\u0641\u0631\u0645\u0627\u0646\u06cc \u0648 \u0631\u0641\u062a\u0627\u0631 \u0636\u062f \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06f5. \u0645\u0631\u062f\u0627\u0646\u06af\u06cc\/\u0632\u0646\u0627\u0646\u06af\u06cc <strong>(Mf)<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0647\u062f\u0641 \u0627\u0635\u0644\u06cc \u0627\u06cc\u0646 \u0628\u062e\u0634 \u0622\u0632\u0645\u0648\u0646 \u06f5\u06f6 \u0633\u0648\u0627\u0644\u06cc \u0627\u0633\u062a\u062e\u0631\u0627\u062c \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062f\u0631 \u0645\u0648\u0631\u062f \u062a\u0645\u0627\u06cc\u0644\u0627\u062a \u062c\u0646\u0633\u06cc \u0627\u0641\u0631\u0627\u062f \u0628\u0648\u062f. \u0627\u06cc\u0646 \u0627\u0632 \u0632\u0645\u0627\u0646\u06cc \u0646\u0627\u0634\u06cc \u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0628\u0631\u062e\u06cc \u0627\u0632 \u0645\u062a\u062e\u0635\u0635\u0627\u0646 \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646\u060c \u062c\u0630\u0627\u0628\u06cc\u062a \u0647\u0645\u062c\u0646\u0633 \u06af\u0631\u0627 \u0631\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0627\u062e\u062a\u0644\u0627\u0644 \u0648 \u0627\u06cc\u0646 \u0631\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u062a\u0633\u062a \u0647\u0645\u062c\u0646\u0633\u06af\u0631\u0627\u06cc\u06cc \u062f\u0631 \u0646\u0638\u0631 \u0645\u06cc \u06af\u0631\u0641\u062a\u0646\u062f. \u0627\u0645\u0631\u0648\u0632\u0647\u060c \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0628\u0631\u0627\u06cc \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0645\u06cc\u0632\u0627\u0646 \u0633\u0627\u0632\u06af\u0627\u0631\u06cc \u0634\u0645\u0627 \u0628\u0627 \u0647\u0646\u062c\u0627\u0631\u0647\u0627\u06cc \u062c\u0646\u0633\u06cc\u062a\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f. <\/span>\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0641\u0631\u062f \u0686\u0642\u062f\u0631 \u0627\u0632 \u0627\u0631\u0632\u0634\u200c\u0647\u0627 \u0648 \u0646\u0642\u0634\u200c\u0647\u0627\u06cc \u06a9\u0644\u06cc\u0634\u0647\u200c\u0627\u06cc \u0645\u0631\u062f\u0627\u0646\u0647 \u0648 \u0632\u0646\u0627\u0646\u0647 \u062a\u0628\u0639\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\r\n<p><img decoding=\"async\" class=\"aligncenter wp-image-16217 size-full\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-mmpi-\u0686\u06cc\u0633\u062a.jpg\" alt=\"\u062a\u0633\u062a mmpi \u0686\u06cc\u0633\u062a\" width=\"1001\" height=\"645\" srcset=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-mmpi-\u0686\u06cc\u0633\u062a.jpg 1001w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-mmpi-\u0686\u06cc\u0633\u062a-300x193.jpg 300w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-mmpi-\u0686\u06cc\u0633\u062a-768x495.jpg 768w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-mmpi-\u0686\u06cc\u0633\u062a-585x377.jpg 585w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06f6. <a href=\"https:\/\/ravandarman.com\/blog\/what-is-paranoia\/\" target=\"_blank\" rel=\"noopener\">\u067e\u0627\u0631\u0627\u0646\u0648\u06cc\u0627<\/a> (<\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0628\u062f\u06af\u0645\u0627\u0646\u06cc)<strong> (Pa)<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u06a9\u0647 \u062f\u0627\u0631\u0627\u06cc \u06f4\u06f0 \u0633\u0648\u0627\u0644 \u0627\u0633\u062a\u060c \u0639\u0644\u0627\u0626\u0645 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u0631\u0648\u0627\u0646 \u067e\u0631\u06cc\u0634\u06cc \u0631\u0627 \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0645\u06cc \u06a9\u0646\u062f\u060c \u0628\u0647 \u0648\u06cc\u0698\u0647: \u0633\u0648\u0621 \u0638\u0646 \u0634\u062f\u06cc\u062f \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0641\u0631\u0627\u062f \u062f\u06cc\u06af\u0631\u060c \u062a\u0641\u06a9\u0631 \u062e\u0648\u062f \u0628\u0632\u0631\u06af \u0628\u06cc\u0646\u06cc\u060c \u062a\u0641\u06a9\u0631 \u0633\u0641\u062a \u0648 \u0633\u062e\u062a \u0648 \u0633\u06cc\u0627\u0647 \u0648 \u0633\u0641\u06cc\u062f\u060c \u0627\u062d\u0633\u0627\u0633 \u0622\u0632\u0627\u0631 \u0648 \u0627\u0630\u06cc\u062a \u0627\u0632 \u0637\u0631\u0641 \u062c\u0627\u0645\u0639\u0647\u060c \u0646\u0645\u0631\u0627\u062a \u0628\u0627\u0644\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0646\u0634\u0627\u0646 \u062f\u0647\u062f \u06a9\u0647 \u0634\u0645\u0627 \u0628\u0627 \u06cc\u06a9 \u0627\u062e\u062a\u0644\u0627\u0644 \u0631\u0648\u0627\u0646 \u067e\u0631\u06cc\u0634\u06cc \u06cc\u0627 \u06cc\u06a9 \u0627\u062e\u062a\u0644\u0627\u0644 \u0634\u062e\u0635\u06cc\u062a \u067e\u0627\u0631\u0627\u0646\u0648\u0626\u06cc\u062f \u0631\u0648\u0628\u0631\u0648 \u0647\u0633\u062a\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0634\u0627\u0645\u0644 \u0645\u0648\u0627\u0631\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u0646\u0639\u06a9\u0633 \u06a9\u0646\u0646\u062f\u0647 \u0647\u0630\u06cc\u0627\u0646 \u0628\u0627\u0634\u062f. <\/span>\u0646\u0645\u0631\u0647 \u0628\u0627\u0644\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u0646\u0634\u0627\u0646 \u0645\u06cc \u062f\u0647\u062f \u06a9\u0647 \u0641\u0631\u062f \u0627\u062d\u062a\u0645\u0627\u0644\u0627\u064b \u0628\u0647 \u06cc\u06a9 \u0627\u062e\u062a\u0644\u0627\u0644 \u0633\u0627\u06cc\u06a9\u0648\u0632 \u06cc\u0627 <strong><a href=\"https:\/\/ravandarman.com\/blog\/paranoid-personality-disorder\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0627\u062e\u062a\u0644\u0627\u0644 \u0634\u062e\u0635\u06cc\u062a \u0628\u062f\u06af\u0645\u0627\u0646 (\u067e\u0627\u0631\u0627\u0646\u0648\u0626\u06cc\u062f)<\/a><\/strong> \u0645\u0628\u062a\u0644\u0627 \u0627\u0633\u062a.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06f7. \u0636\u0639\u0641 \u0631\u0648\u0627\u0646\u06cc<strong> (Pt)<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0641\u0631\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u0645\u0642\u0627\u0648\u0645\u062a \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0627\u0641\u06a9\u0627\u0631 \u06cc\u0627 \u0631\u0641\u062a\u0627\u0631\u0647\u0627\u06cc \u062e\u0627\u0635 \u0645\u06cc \u0633\u0646\u062c\u062f. \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u06f4\u06f8 \u0622\u06cc\u062a\u0645\u06cc \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u0645\u06cc \u06a9\u0646\u062f: \u0627\u0636\u0637\u0631\u0627\u0628\u060c \u0627\u0641\u0633\u0631\u062f\u06af\u06cc\u060c \u0631\u0641\u062a\u0627\u0631\u0647\u0627\u06cc \u0627\u062c\u0628\u0627\u0631\u06cc\u060c \u0639\u0644\u0627\u0626\u0645<a href=\"https:\/\/ravandarman.com\/blog\/obsessive-compulsive-disorder\/\" target=\"_blank\" rel=\"noopener\"> \u0627\u062e\u062a\u0644\u0627\u0644 \u0648\u0633\u0648\u0627\u0633 \u0641\u06a9\u0631\u06cc \u0627\u062c\u0628\u0627\u0631\u06cc (OCD)<\/a> \u0627\u0635\u0637\u0644\u0627\u062d \u00ab\u0636\u0639\u0641 \u0631\u0648\u0627\u0646\u06cc\u00bb \u062f\u06cc\u06af\u0631 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u062a\u0634\u062e\u06cc\u0635 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u06cc \u0634\u0648\u062f. \u0627\u0645\u0627 \u0645\u062a\u062e\u0635\u0635\u0627\u0646 \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u0647\u0646\u0648\u0632 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0631\u0627\u0647\u06cc \u0628\u0631\u0627\u06cc \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0627\u062c\u0628\u0627\u0631\u0647\u0627\u06cc \u0646\u0627\u0633\u0627\u0644\u0645 \u0648 \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u0645\u062e\u0631\u0628 \u0646\u0627\u0634\u06cc \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06f8. \u0627\u0633\u06a9\u06cc\u0632\u0648\u0641\u0631\u0646\u06cc <strong>(Sc)<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u06f7\u06f8 \u0645\u0627\u062f\u0647 \u0627\u06cc \u0628\u0631\u0627\u06cc \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0646 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0622\u06cc\u0627 \u0634\u0645\u0627 \u0628\u0647 \u06cc\u06a9 \u0627\u062e\u062a\u0644\u0627\u0644 \u0627\u0633\u06a9\u06cc\u0632\u0648\u0641\u0631\u0646\u06cc \u0645\u0628\u062a\u0644\u0627 \u0647\u0633\u062a\u06cc\u062f \u06cc\u0627 \u0627\u062d\u062a\u0645\u0627\u0644 \u062f\u0627\u0631\u062f \u0628\u0647 \u0622\u0646 \u0645\u0628\u062a\u0644\u0627 \u0634\u0648\u06cc\u062f.\u0628\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u062a\u0648\u062c\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0622\u06cc\u0627 \u062a\u0648\u0647\u0645\u060c \u0647\u0630\u06cc\u0627\u0646\u060c \u06cc\u0627 \u062d\u0645\u0644\u0627\u062a \u062a\u0641\u06a9\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0622\u0634\u0641\u062a\u0647 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u062a\u0639\u06cc\u06cc\u0646 \u0645\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u062a\u0627 \u0686\u0647 \u062d\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u062d\u0633\u0627\u0633 \u0628\u06cc\u06af\u0627\u0646\u06af\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0628\u0642\u06cc\u0647 \u0627\u0641\u0631\u0627\u062f \u062c\u0627\u0645\u0639\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/span><\/p>\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0645\u0646\u0639\u06a9\u0633 \u06a9\u0646\u0646\u062f\u0647 \u0637\u06cc\u0641 \u06af\u0633\u062a\u0631\u062f\u0647 \u0627\u06cc \u0627\u0632 \u0632\u0645\u06cc\u0646\u0647 \u0647\u0627 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0641\u0631\u0622\u06cc\u0646\u062f\u0647\u0627\u06cc \u0641\u06a9\u0631\u06cc \u0639\u062c\u06cc\u0628 \u0648 \u063a\u0631\u06cc\u0628 \u0648 \u0627\u062f\u0631\u0627\u06a9\u0627\u062a \u0639\u062c\u06cc\u0628 \u0648 \u063a\u0631\u06cc\u0628\u060c \u0628\u06cc\u06af\u0627\u0646\u06af\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u0631\u0648\u0627\u0628\u0637 \u062e\u0627\u0646\u0648\u0627\u062f\u06af\u06cc \u0636\u0639\u06cc\u0641\u060c \u0645\u0634\u06a9\u0644\u0627\u062a \u062f\u0631 \u062a\u0645\u0631\u06a9\u0632 \u0648 \u06a9\u0646\u062a\u0631\u0644 \u062a\u06a9\u0627\u0646\u0647\u060c \u0641\u0642\u062f\u0627\u0646 \u0639\u0644\u0627\u06cc\u0642 \u0639\u0645\u06cc\u0642\u060c \u067e\u0631\u0633\u0634 \u0647\u0627\u06cc \u0646\u06af\u0631\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647 \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u0631\u0632\u0634 \u0648 \u0647\u0648\u06cc\u062a \u0634\u062e\u0635\u06cc\u060c \u0648 \u0645\u0634\u06a9\u0644\u0627\u062a \u062c\u0646\u0633\u06cc \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0633\u0648\u0621\u0645\u0635\u0631\u0641 \u0628\u0627\u0644\u0642\u0648\u0647 \u0645\u0648\u0627\u062f\u060c \u0628\u06cc\u06af\u0627\u0646\u06af\u06cc \u0639\u0627\u0637\u0641\u06cc \u06cc\u0627 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u063a\u06cc\u0631\u0639\u0627\u062f\u06cc\u200c\u0647\u0627 \u0648 \u0639\u0644\u0627\u0642\u0647 \u0645\u062d\u062f\u0648\u062f \u0628\u0647 \u0627\u0641\u0631\u0627\u062f \u062f\u06cc\u06af\u0631 \u0631\u0627 \u0646\u0634\u0627\u0646 \u062f\u0647\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06f9. \u0647\u06cc\u067e\u0648\u0645\u0627\u0646\u06cc\u0627 <strong>(Ma)<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0647\u062f\u0641 \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u06f4\u06f6 \u0645\u0627\u062f\u0647 \u0627\u06cc \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0639\u0644\u0627\u0626\u0645 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u0647\u06cc\u067e\u0648\u0645\u0627\u0646\u06cc\u0627 \u0627\u0633\u062a\u060c \u0627\u0632 \u062c\u0645\u0644\u0647: \u0627\u0646\u0631\u0698\u06cc \u0628\u06cc \u062c\u0647\u062a \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f\u060c \u06af\u0641\u062a\u0627\u0631 \u0633\u0631\u06cc\u0639\u060c \u067e\u0631\u0634 \u0627\u0641\u06a9\u0627\u0631\u060c \u062a\u0648\u0647\u0645\u0627\u062a\u060c \u062a\u06a9\u0627\u0646\u0634\u06af\u0631\u06cc\u060c \u0647\u0630\u06cc\u0627\u0646 \u0647\u0627\u06cc \u062e\u0648\u062f \u0628\u0632\u0631\u06af \u0628\u06cc\u0646\u06cc. \u0627<\/span><span style=\"font-weight: 400;\">\u06af\u0631 \u0646\u0645\u0631\u0647 \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u06cc\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0639\u0644\u0627\u0626\u0645 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u0627\u062e\u062a\u0644\u0627\u0644 \u062f\u0648\u0642\u0637\u0628\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. \u0627\u06af\u0631 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u0641\u0631\u062f\u06cc \u0646\u0645\u0631\u0647 \u0628\u0627\u0644\u0627\u06cc\u06cc \u06a9\u0633\u0628 \u06a9\u0646\u062f \u0627\u062d\u062a\u0645\u0627\u0644 \u0648\u062c\u0648\u062f \u0639\u0644\u0627\u0626\u0645 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 <strong><a href=\"https:\/\/ravandarman.com\/blog\/bipolar-disorder\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0627\u062e\u062a\u0644\u0627\u0644 \u062f\u0648\u0642\u0637\u0628\u06cc <\/a><\/strong>\u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f.<\/span><\/p>\r\n<p><img decoding=\"async\" class=\"aligncenter wp-image-16218 size-full\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-\u0645\u06cc\u0646\u0647-\u0633\u0648\u062a\u0627-\u06cc\u0627-\u062a\u0633\u062a-mmoi.jpg\" alt=\"\u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi\" width=\"1001\" height=\"645\" srcset=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-\u0645\u06cc\u0646\u0647-\u0633\u0648\u062a\u0627-\u06cc\u0627-\u062a\u0633\u062a-mmoi.jpg 1001w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-\u0645\u06cc\u0646\u0647-\u0633\u0648\u062a\u0627-\u06cc\u0627-\u062a\u0633\u062a-mmoi-300x193.jpg 300w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-\u0645\u06cc\u0646\u0647-\u0633\u0648\u062a\u0627-\u06cc\u0627-\u062a\u0633\u062a-mmoi-768x495.jpg 768w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/\u062a\u0633\u062a-\u0645\u06cc\u0646\u0647-\u0633\u0648\u062a\u0627-\u06cc\u0627-\u062a\u0633\u062a-mmoi-585x377.jpg 585w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/p>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u06f1\u06f0. \u062f\u0631\u0648\u0646\u06af\u0631\u0627\u06cc\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc <strong>(Si)<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u062f\u06cc\u0631\u062a\u0631 \u0627\u0632 \u06f9 \u0645\u0642\u06cc\u0627\u0633 \u062f\u06cc\u06af\u0631 \u0627\u06cc\u062c\u0627\u062f \u0634\u062f. \u0627\u06cc\u0646 \u0628\u0631\u0627\u06cc \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u06a9\u0645\u0631\u0648\u06cc\u06cc \u0648 \u062a\u0645\u0627\u06cc\u0644 \u0641\u0631\u062f \u0628\u0647 \u06a9\u0646\u0627\u0631\u0647 \u06af\u06cc\u0631\u06cc \u0627\u0632 \u062a\u0645\u0627\u0633 \u0647\u0627 \u0648 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0641\u0632\u0648\u062f\u0647\u200c\u0647\u0627\u06cc \u0628\u0639\u062f\u06cc \u0628\u0647 MMPI\u060c \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u06f6\u06f9 \u0645\u0648\u0631\u062f\u06cc \u0628\u0631\u0648\u0646\u200c\u06af\u0631\u0627\u06cc\u06cc \u06cc\u0627 \u062f\u0631\u0648\u0646\u200c\u06af\u0631\u0627\u06cc\u06cc \u0631\u0627 \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0645\u06cc\u0632\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0634\u0645\u0627 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06cc\u0627 \u06a9\u0646\u0627\u0631\u0647 \u06af\u06cc\u0631\u06cc \u0627\u0632 \u062a\u0639\u0627\u0645\u0644\u0627\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0647\u0633\u062a\u06cc\u062f. \u0627\u06cc\u0646 \u0645\u0642\u06cc\u0627\u0633 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0631\u0627 \u062f\u0631 \u0646\u0638\u0631 \u0645\u06cc \u06af\u06cc\u0631\u062f: \u0631\u0642\u0627\u0628\u062a \u067e\u0630\u06cc\u0631\u06cc\u060c \u0627\u0646\u0637\u0628\u0627\u0642\u060c \u062a\u0631\u0633\u0648 \u0628\u0648\u062f\u0646\u060c \u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0645\u0627\u062f \u0628\u0648\u062f\u0646.<\/span><\/p>\r\n<blockquote>\r\n<p style=\"text-align: justify;\"><a style=\"text-align: right;\" href=\"https:\/\/ravandarman.com\/blog\/best-personality-test\/\" target=\"_blank\" rel=\"noopener\"><strong>\u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0634\u0646\u0627\u0633\u06cc\u061b \u06a9\u062f\u0627\u0645 \u062a\u0633\u062a \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u061f<\/strong><\/a><\/p>\r\n<\/blockquote>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D8%B1%D9%88%D8%A7%DB%8C%DB%8C_%D8%AF%D8%B1_%D8%AA%D8%B3%D8%AA_mmpi_%D8%A2%D9%86%D9%84%D8%A7%DB%8C%D9%86\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\"><strong>\u0645\u0639\u06cc\u0627\u0631\u0647\u0627\u06cc \u0631\u0648\u0627\u06cc\u06cc \u062f\u0631 \u062a\u0633\u062a mmpi \u0622\u0646\u0644\u0627\u06cc\u0646<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0645\u0639\u06cc\u0627\u0631\u0647\u0627\u06cc \u0631\u0648\u0627\u06cc\u06cc \u0628\u0647 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u062a\u0627 \u0628\u0641\u0647\u0645\u0646\u062f \u067e\u0627\u0633\u062e\u200c\u0647\u0627\u06cc \u0641\u0631\u062f \u062a\u0627 \u0686\u0647 \u062d\u062f \u0648\u0627\u0642\u0639\u06cc \u0647\u0633\u062a\u0646\u062f. \u062f\u0631 \u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u0646\u062a\u0627\u06cc\u062c \u062a\u0633\u062a \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0632\u0646\u062f\u06af\u06cc \u0641\u0631\u062f \u0631\u0627 \u062a\u062d\u062a \u062a\u0627\u062b\u06cc\u0631 \u0642\u0631\u0627\u0631 \u062f\u0647\u062f (\u0645\u062b\u0644\u0627\u064b \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u06cc\u0627 \u062d\u0636\u0627\u0646\u062a \u0641\u0631\u0632\u0646\u062f) \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0641\u0631\u062f \u0635\u062f\u0627\u0642\u062a \u06a9\u0645\u062a\u0631\u06cc \u062f\u0631 \u067e\u0627\u0633\u062e \u062f\u0627\u062f\u0646 \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u0628\u0647 \u062e\u0631\u062c \u062f\u0647\u062f. \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0645\u0639\u06cc\u0627\u0631\u0647\u0627\u06cc \u0631\u0648\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0647 \u0622\u0634\u06a9\u0627\u0631 \u0633\u0627\u062e\u062a\u0646 \u067e\u0627\u0633\u062e\u200c\u0647\u0627\u06cc \u0628\u0627 \u062f\u0642\u062a \u067e\u0627\u06cc\u06cc\u0646 \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u0647\u200c\u0627\u0646\u062f.<\/p>\r\n<p style=\"text-align: justify;\">\u0645\u0642\u06cc\u0627\u0633\u200c\u0647\u0627\u06cc \u0627\u0639\u062a\u0628\u0627\u0631 \u06cc\u0627 \u0631\u0648\u0627\u06cc\u06cc \u062f\u0631 \u0628\u06cc\u0646 \u0646\u0633\u062e\u0647\u200c\u0647\u0627\u06cc MMPI \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a\u060c \u0627\u0645\u0627 MMPI-2 \u0634\u0627\u0645\u0644 \u0633\u0647 \u0646\u0648\u0639 \u06a9\u0644\u06cc \u0645\u0642\u06cc\u0627\u0633 \u0627\u0639\u062a\u0628\u0627\u0631 \u0627\u0633\u062a:<\/p>\r\n<ul style=\"text-align: justify;\">\r\n<li>\u0628\u062f\u0648\u0646 \u067e\u0627\u0633\u062e \u06cc\u0627 \u067e\u0627\u0633\u062e\u200c\u062f\u0647\u06cc \u0646\u0627\u0633\u0627\u0632\u06af\u0627\u0631 (CNS\u060c VRIN\u060c TRIN)<\/li>\r\n<li>\u06af\u0632\u0627\u0631\u0634 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f\u060c \u06cc\u0627 \u0627\u063a\u0631\u0627\u0642 \u0622\u0645\u06cc\u0632 \u0639\u0644\u0627\u0626\u0645 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u062e\u062a\u06cc\u060c \u06a9\u0647 \u0639\u0645\u0648\u0645\u0627\u064b \u0628\u062f \u062c\u0644\u0648\u0647 \u062f\u0627\u062f\u0646 \u0646\u0627\u0645\u06cc\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f (F\u060c Fb\u060c Fp\u060c FBS)<\/li>\r\n<li>\u06a9\u0645 \u06af\u0632\u0627\u0631\u0634 \u06a9\u0631\u062f\u0646\u060c \u06cc\u0627 \u06a9\u0627\u0647\u0634 \u0639\u0644\u0627\u0626\u0645 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u062e\u062a\u06cc\u060c \u06a9\u0647 \u0639\u0645\u0648\u0645\u0627\u064b \u062e\u0648\u0628 \u062c\u0644\u0648\u0647 \u062f\u0627\u062f\u0646 \u0646\u0627\u0645\u06cc\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f (L\u060c K\u060c S)<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"mntl-sc-block_1-0-97\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D8%AA%D8%B8%D8%A7%D9%87%D8%B1_%D8%A8%D9%87_%D8%AE%D9%88%D8%A8%DB%8C_%DB%8C%D8%A7_%D8%AF%D8%B1%D9%88%D8%BA_L\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631 \u062a\u0638\u0627\u0647\u0631 \u0628\u0647 \u062e\u0648\u0628\u06cc \u06cc\u0627 \u062f\u0631\u0648\u063a\u00a0 (L)<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u06a9\u0647 \u0628\u0647 \u0645\u0639\u06cc\u0627\u0631 \u062f\u0631\u0648\u063a \u0647\u0645 \u0634\u0647\u0631\u062a \u062f\u0627\u0631\u062f \u0628\u0631\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u062a\u0644\u0627\u0634 \u0641\u0631\u062f \u062f\u0631 \u062e\u0648\u0628 \u062c\u0644\u0648\u0647 \u062f\u0627\u062f\u0646 \u062e\u0648\u062f \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u0646\u0645\u0631\u0647 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0628\u0647 \u062f\u0633\u062a \u0645\u06cc\u200c\u0622\u0648\u0631\u0646\u062f \u0639\u0645\u062f\u0627\u064b \u062a\u0644\u0627\u0634 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u062a\u0627 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0628\u0647\u062a\u0631\u06cc\u0646 \u062d\u0627\u0644\u062a \u0645\u0645\u06a9\u0646 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647 \u0648 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0646\u0627\u062e\u0648\u0634\u0627\u06cc\u0646\u062f \u0648 \u06a9\u0627\u0633\u062a\u06cc\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u067e\u0646\u0647\u0627\u0646 \u06a9\u0646\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"mntl-sc-block_1-0-103\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D8%AA%D8%B8%D8%A7%D9%87%D8%B1_%D8%A8%D9%87_%D8%A8%D8%AF%DB%8C_F\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631 \u062a\u0638\u0627\u0647\u0631 \u0628\u0647 \u0628\u062f\u06cc (F)<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u0646\u0645\u0631\u0647 \u0628\u0627\u0644\u0627\u06cc\u06cc \u06a9\u0633\u0628 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u062a\u0644\u0627\u0634 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u062e\u0648\u062f \u0631\u0627 \u0628\u062f\u062a\u0631 \u0627\u0632 \u0686\u06cc\u0632\u06cc \u06a9\u0647 \u0647\u0633\u062a\u0646\u062f \u0646\u0634\u0627\u0646 \u062f\u0647\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0631\u0648\u0627\u0646\u06cc \u0634\u062f\u06cc\u062f \u0628\u0648\u062f\u0646 \u0628\u0627\u0634\u062f \u06cc\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u0641\u0631\u062f \u0628\u0647 \u0637\u0648\u0631 \u062a\u0635\u0627\u062f\u0641\u06cc \u0648 \u0628\u062f\u0648\u0646 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u067e\u0627\u0633\u062e \u062f\u0627\u062f\u0647 \u0628\u0627\u0634\u062f. \u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u0633\u0648\u0627\u0644\u0627\u062a \u0631\u0627 \u0628\u0647 \u06af\u0648\u0646\u0647 \u0627\u06cc \u0637\u0631\u0627\u062d\u06cc \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062a\u0646\u0627\u0642\u0636 \u0645\u06cc\u0627\u0646 \u067e\u0627\u0633\u062e\u200c\u0647\u0627\u06cc \u0641\u0631\u062f \u0631\u0627 \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u062a\u0633\u062a \u0622\u0634\u06a9\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"mntl-sc-block_1-0-109\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D8%AD%D8%A7%D9%84%D8%AA_%D8%AA%D8%AF%D8%A7%D9%81%D8%B9%DB%8C_K\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631 \u062d\u0627\u0644\u062a \u062a\u062f\u0627\u0641\u0639\u06cc (K)<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u06a9\u0647 \u0645\u0639\u06cc\u0627\u0631 \u062a\u062f\u0627\u0641\u0639\u06cc \u0647\u0645 \u0646\u0627\u0645 \u062f\u0627\u0631\u062f \u06cc\u06a9 \u0627\u0628\u0632\u0627\u0631 \u0645\u0648\u062b\u0631\u062a\u0631 \u0628\u0631\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0641\u0631\u062f \u062f\u0631 \u062a\u0644\u0627\u0634 \u0628\u0631\u0627\u06cc \u0628\u0647\u062a\u0631 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0646 \u062e\u0648\u062f \u0627\u0633\u062a. \u0627\u0641\u0631\u0627\u062f \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062a\u0631\u0633 \u0627\u0632 \u0642\u0636\u0627\u0648\u062a \u06cc\u0627 \u0627\u0646\u06a9\u0627\u0631 \u0645\u0634\u06a9\u0644\u0627\u062a\u060c \u062a\u0644\u0627\u0634 \u06a9\u0646\u0646\u062f \u062e\u0648\u062f \u0631\u0627 \u0628\u0647\u062a\u0631 \u0627\u0632 \u0686\u06cc\u0632\u06cc \u06a9\u0647 \u0647\u0633\u062a\u0646\u062f \u0646\u0634\u0627\u0646 \u062f\u0647\u0646\u062f. \u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u062a\u0633\u062a mmpi \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06a9\u0645\u062a\u0631 \u06af\u0632\u0627\u0631\u0634 \u062f\u0647\u0646\u062f \u0632\u06cc\u0631\u0627 \u0646\u06af\u0631\u0627\u0646 \u0642\u0636\u0627\u0648\u062a \u0634\u062f\u0646 \u0647\u0633\u062a\u0646\u062f \u06cc\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u0634\u06a9\u0644\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u062d\u062f\u0627\u0642\u0644 \u0628\u0631\u0633\u0627\u0646\u0646\u062f \u06cc\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u0635\u0644\u0627\u064b \u0645\u0634\u06a9\u0644\u06cc \u0631\u0627 \u0627\u0646\u06a9\u0627\u0631 \u06a9\u0646\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"mntl-sc-block_1-0-115\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D8%A8%DB%8C_%D9%BE%D8%A7%D8%B3%D8%AE%DB%8C_%D8%9F\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631 \u0628\u06cc \u067e\u0627\u0633\u062e\u06cc (\u061f)<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u062a\u0639\u062f\u0627\u062f \u0622\u06cc\u062a\u0645\u200c\u0647\u0627\u06cc \u0628\u062f\u0648\u0646 \u067e\u0627\u0633\u062e \u0631\u0627 \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0637\u0628\u0642 \u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u062a\u0639\u062f\u0627\u062f \u062d\u062f\u0627\u0642\u0644 \u06f3\u06f0 \u0633\u0648\u0627\u0644 \u0628\u062f\u0648\u0646 \u067e\u0627\u0633\u062e \u0628\u0627\u0639\u062b \u0639\u062f\u0645 \u0627\u0639\u062a\u0628\u0627\u0631 \u062a\u0633\u062a \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"mntl-sc-block_1-0-119\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D9%86%D8%A7%D9%87%D9%85%D8%B3%D8%A7%D9%86%DB%8C_%D9%BE%D8%A7%D8%B3%D8%AE_%D8%AF%D8%B1%D8%B3%D8%AA_TRIN\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631 \u0646\u0627\u0647\u0645\u0633\u0627\u0646\u06cc \u067e\u0627\u0633\u062e \u062f\u0631\u0633\u062a (TRIN)<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u0628\u0631\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u06cc\u06a9 \u0627\u0644\u06af\u0648\u06cc \u062b\u0627\u0628\u062a \u062f\u0631 \u067e\u0627\u0633\u062e \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u062f\u0631 \u067e\u06cc\u0634 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f. \u0645\u062b\u0644\u0627\u064b \u0628\u0647 \u062f\u0647 \u0633\u0648\u0627\u0644 \u067e\u0627\u0633\u062e \u00ab\u0635\u062d\u06cc\u062d\u00bb \u0648 \u0628\u0647 \u062f\u0647 \u0633\u0648\u0627\u0644 \u0628\u0639\u062f\u06cc \u067e\u0627\u0633\u062e \u00ab\u063a\u0644\u0637\u00bb \u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u067e\u0627\u0633\u062e \u062b\u0627\u0628\u062a \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u062e\u0627\u0637\u0631 \u0646\u0627\u062a\u0648\u0627\u0646\u06cc \u062f\u0631 \u062e\u0648\u0627\u0646\u062f\u0646 \u06cc\u0627 \u062a\u0641\u0633\u06cc\u0631 \u0633\u0648\u0627\u0644\u0627\u062a \u062a\u0633\u062a \u06cc\u0627 \u0645\u0642\u0627\u0648\u0645\u062a \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0627\u0646\u062c\u0627\u0645 \u062a\u0633\u062a \u0628\u0627\u0634\u062f. \u0627\u06cc\u0646 \u0628\u062e\u0634 \u0634\u0627\u0645\u0644 \u06f2\u06f0 \u0633\u0648\u0627\u0644 \u062f\u0648 \u0628\u0647 \u062f\u0648 \u0627\u0633\u062a \u06a9\u0647 \u0645\u062a\u0636\u0627\u062f \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0647\u0633\u062a\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"mntl-sc-block_1-0-125\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D9%86%D8%A7%D9%87%D9%85%D8%B3%D8%A7%D9%86%DB%8C_%D9%BE%D8%A7%D8%B3%D8%AE_%D9%85%D8%AA%D8%BA%DB%8C%D8%B1_VRIN\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631 \u0646\u0627\u0647\u0645\u0633\u0627\u0646\u06cc \u067e\u0627\u0633\u062e \u0645\u062a\u063a\u06cc\u0631 (VRIN)<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u0631\u0648\u0634 \u062f\u06cc\u06af\u0631\u06cc \u0628\u0631\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u067e\u0627\u0633\u062e\u200c\u0647\u0627\u06cc \u062a\u0635\u0627\u062f\u0641\u06cc \u0648 \u0646\u0627\u0647\u0645\u06af\u0648\u0646 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0639\u0645\u062f\u06cc \u06cc\u0627 \u062f\u0631 \u0627\u062b\u0631 \u0639\u062f\u0645 \u062f\u0631\u06a9 \u062f\u0631\u0633\u062a \u0633\u0648\u0627\u0644\u0627\u062a \u062a\u0633\u062a mmpi \u06cc\u0627 \u0639\u062f\u0645 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062f\u0631 \u062e\u0648\u0627\u0646\u062f\u0646 \u0622\u0646\u200c\u0647\u0627 \u0627\u062a\u0641\u0627\u0642 \u0628\u06cc\u0641\u062a\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"mntl-sc-block_1-0-129\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D9%86%D8%A7%D8%A8%D8%B3%D8%A7%D9%85%D8%AF%DB%8C_%D8%A7%D9%86%D8%AA%D9%87%D8%A7%DB%8C_%D8%A2%D8%B2%D9%85%D9%88%D9%86_Fb\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631 \u00a0\u0646\u0627\u0628\u0633\u0627\u0645\u062f\u06cc \u0627\u0646\u062a\u0647\u0627\u06cc \u0622\u0632\u0645\u0648\u0646 (Fb)<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u0628\u0631\u0627\u06cc \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0646 \u062a\u063a\u06cc\u06cc\u0631 \u0646\u062d\u0648\u0647 \u067e\u0627\u0633\u062e\u06af\u0648\u06cc\u06cc \u0641\u0631\u062f \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u062f\u0631 \u062f\u0648 \u0646\u06cc\u0645\u0647 \u0627\u0632 \u0633\u0648\u0627\u0644\u0627\u062a \u0627\u0633\u062a. \u0646\u0645\u0631\u0647 \u0628\u0627\u0644\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u06af\u0627\u0647\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0622\u0632\u0645\u0648\u062f\u0646\u06cc \u0628\u0647 \u062a\u062f\u0631\u06cc\u062c \u0646\u0633\u0628\u062a \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u0628\u06cc \u062a\u0648\u062c\u0647 \u0634\u062f\u0647 \u0648 \u0634\u0631\u0648\u0639 \u0628\u0647 \u067e\u0627\u0633\u062e \u062a\u0635\u0627\u062f\u0641\u06cc \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062f\u0644\u06cc\u0644 \u067e\u0627\u0633\u062e\u200c\u062f\u0647\u06cc \u062b\u0627\u0628\u062a\u060c \u062e\u0633\u062a\u06af\u06cc \u06cc\u0627 \u062a\u062d\u062a \u0627\u0633\u062a\u0631\u0633 \u0634\u062f\u06cc\u062f \u0628\u0648\u062f\u0646 \u0627\u062a\u0641\u0627\u0642 \u0628\u06cc\u0641\u062a\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"mntl-sc-block_1-0-135\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D9%86%D8%A7%D8%A8%D8%B3%D8%A7%D9%85%D8%AF%DB%8C_%D8%A2%D8%B3%DB%8C%D8%A8_%D8%B4%D9%86%D8%A7%D8%B3%DB%8C_%D8%B1%D9%88%D8%A7%D9%86%DB%8C_Fp\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631 \u00a0\u0646\u0627\u0628\u0633\u0627\u0645\u062f\u06cc \u0622\u0633\u06cc\u0628 \u0634\u0646\u0627\u0633\u06cc \u0631\u0648\u0627\u0646\u06cc (Fp)<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0627\u0641\u0631\u0627\u062f\u06cc \u0631\u0627 \u06a9\u0647 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u06cc\u0627 \u067e\u0627\u0633\u062e\u06af\u0648\u06cc\u06cc \u062a\u0635\u0627\u062f\u0641\u06cc \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u062f\u062a\u0631 \u0627\u0632 \u0622\u0646\u0686\u0647 \u0647\u0633\u062a\u0646\u062f \u0646\u0645\u0627\u06cc\u0634 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0634\u0648\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"mntl-sc-block_1-0-139\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_FBS_%D8%AF%D8%B1_%D8%AA%D8%B3%D8%AA_mmpi\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631 FBS \u062f\u0631 \u062a\u0633\u062a mmpi<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0627\u062f\u0639\u0627 \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f \u06cc\u06a9 \u0622\u0633\u06cc\u0628 \u0634\u062e\u0635\u06cc \u06cc\u0627 \u0646\u0627\u062a\u0648\u0627\u0646\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0627\u0639\u062a\u0628\u0627\u0631 \u0641\u0631\u062f \u0622\u0632\u0645\u0648\u062f\u0646\u06cc \u062f\u0631 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0633\u0646\u062c\u06cc\u062f\u0647 \u0634\u0648\u062f.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%DB%8C%D8%A7%D8%B1_%D8%AE%D9%88%D8%AF%D8%AA%D9%88%D8%B5%DB%8C%D9%81%DB%8C_%D8%B9%D8%A7%D9%84%DB%8C_S\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0639\u06cc\u0627\u0631 \u00a0\u062e\u0648\u062f\u062a\u0648\u0635\u06cc\u0641\u06cc \u0639\u0627\u0644\u06cc (<\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">S)<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0639\u06cc\u0627\u0631 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f9\u06f9\u06f5 \u0627\u06cc\u062c\u0627\u062f \u0634\u062f \u062a\u0627 \u0627\u0641\u0631\u0627\u062f\u06cc \u0631\u0627 \u06a9\u0647 \u062e\u0648\u062f \u0631\u0627 \u0628\u062f\u062a\u0631 \u0627\u0632 \u0622\u0646\u0686\u0647 \u0647\u0633\u062a\u0646\u062f \u0646\u0634\u0627\u0646 \u0645\u06cc \u062f\u0647\u0646\u062f \u0628\u0647\u062a\u0631 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0634\u0648\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u062f\u0627\u0631\u0627\u06cc \u0645\u0642\u06cc\u0627\u0633\u200c\u0647\u0627\u06cc \u0641\u0631\u0639\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u0639\u062a\u0642\u0627\u062f \u0622\u0632\u0645\u0648\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc\u060c \u0622\u0631\u0627\u0645\u0634\u060c \u0631\u0636\u0627\u06cc\u062a \u0627\u0632 \u0632\u0646\u062f\u06af\u06cc\u060c \u0635\u0628\u0631\/\u0627\u0646\u06a9\u0627\u0631\u060c \u062a\u062d\u0631\u06cc\u06a9\u200c\u067e\u0630\u06cc\u0631\u06cc \u0648 \u0627\u0646\u06a9\u0627\u0631 \u0639\u06cc\u0648\u0628 \u0627\u062e\u0644\u0627\u0642\u06cc \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\r\n<blockquote>\r\n<p style=\"text-align: center;\"><a href=\"https:\/\/ravandarman.com\/blog\/millon-test\/\" target=\"_blank\" rel=\"noopener\"><strong>\u062a\u0633\u062a \u0645\u06cc\u0644\u0648\u0646 \u0686\u06cc\u0633\u062a\u061f (MCMI)<\/strong><\/a><\/p>\r\n<\/blockquote>\r\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B3%D8%AA_MMPI_%DA%86%D9%82%D8%AF%D8%B1_%D8%AF%D9%82%DB%8C%D9%82_%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span><span style=\"color: #008000;\" data-darkreader-inline-color=\"\"><strong>\u062a\u0633\u062a MMPI \u0686\u0642\u062f\u0631 \u062f\u0642\u06cc\u0642 \u0627\u0633\u062a\u061f<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n<p style=\"text-align: justify;\">\u062a\u0633\u062a MMPI \u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0645\u0627\u062f \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a\u0647 \u0645\u06cc \u0634\u0648\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c \u0627\u06cc\u0646 \u062a\u0646\u0647\u0627 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0634\u0631\u0627\u06cc\u0637 \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u0627\u0633\u062a. \u0627\u06af\u0631\u0686\u0647 MMPI \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0641\u06cc\u062f\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc \u062f\u0647\u062f\u060c \u0627\u0645\u0627 \u06cc\u06a9 \u0645\u062a\u062e\u0635\u0635 \u0646\u0628\u0627\u06cc\u062f \u0628\u0631\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u06a9\u0627\u0645\u0644 \u062a\u0646\u0647\u0627 \u0628\u0647 \u06cc\u06a9 \u0627\u0628\u0632\u0627\u0631 \u062a\u06a9\u06cc\u0647 \u06a9\u0646\u062f. \u062a\u0634\u062e\u06cc\u0635 \u0628\u0627\u06cc\u062f \u0628\u0627 \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a\u0646 \u062a\u0639\u062f\u0627\u062f\u06cc \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0645\u0627\u0646\u0646\u062f \u0645\u0635\u0627\u062d\u0628\u0647\u060c \u0633\u0627\u0628\u0642\u0647 \u0633\u0644\u0627\u0645\u062a \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u062f.<\/p>\r\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%88%D8%A7%D8%B1%D8%AF%DB%8C_%DA%A9%D9%87_%D8%A8%D8%A7%DB%8C%D8%AF_%D9%87%D9%86%DA%AF%D8%A7%D9%85_%D8%A7%D9%86%D8%AC%D8%A7%D9%85_%D8%AA%D8%B3%D8%AA_%D8%B4%D8%AE%D8%B5%DB%8C%D8%AA_mmpi_%D8%AF%D8%B1_%D9%86%D8%B8%D8%B1_%D8%A8%DA%AF%DB%8C%D8%B1%DB%8C%D8%AF\"><\/span><strong><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0647\u0646\u06af\u0627\u0645 \u0627\u0646\u062c\u0627\u0645 \u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a mmpi \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n<p style=\"text-align: justify;\">\u0627\u06af\u0631 \u062f\u0631 \u062d\u0627\u0644 \u0634\u0631\u06a9\u062a \u062f\u0631 \u062a\u0633\u062a mmpi \u0647\u0633\u062a\u06cc\u062f\u060c \u0646\u06a9\u0627\u062a \u0645\u0641\u06cc\u062f\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0628\u0647 \u062e\u0627\u0637\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0628\u0647 \u0634\u0631\u062d \u0632\u06cc\u0631 \u0627\u0633\u062a:<\/p>\r\n<ul style=\"text-align: justify;\">\r\n<li><strong>\u0627\u06cc\u0646 \u06cc\u06a9 \u0622\u0632\u0645\u0648\u0646 \u0642\u0628\u0648\u0644\u06cc \u06cc\u0627 \u0645\u0631\u062f\u0648\u062f\u06cc \u0646\u06cc\u0633\u062a:<\/strong> \u0647\u06cc\u0686 \u0631\u0627\u0647\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0633\u062a \u06cc\u0627 \u063a\u0644\u0637 \u0634\u062f\u0646 \u0633\u0624\u0627\u0644\u0627\u062a \u0622\u0632\u0645\u0648\u0646 \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f. \u0622\u0632\u0645\u0648\u0646 \u0627\u0628\u0632\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0634\u062e\u0635\u06cc\u062a \u0648 \u0627\u062e\u062a\u0644\u0627\u0644 \u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u06cc \u0627\u0633\u062a.<\/li>\r\n<li><strong>\u0634\u0645\u0627 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0622\u0632\u0645\u0648\u0646 \u062a\u0645\u0631\u06cc\u0646 \u0646\u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f:<\/strong> \u0627\u0632 \u0622\u0646\u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0647\u06cc\u0686 \u067e\u0627\u0633\u062e \u062f\u0631\u0633\u062a \u06cc\u0627 \u063a\u0644\u0637\u06cc \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f\u060c \u0633\u0639\u06cc \u06a9\u0646\u06cc\u062f \u0627\u0633\u062a\u0631\u0633 \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. \u0646\u06cc\u0627\u0632 \u0646\u06cc\u0633\u062a \u0628\u0631\u0627\u06cc MMPI \u0645\u0627\u0646\u0646\u062f \u06cc\u06a9 \u0622\u0632\u0645\u0648\u0646 \u0645\u062f\u0631\u0633\u0647 \u062a\u0645\u0631\u06cc\u0646 \u0646\u0645\u06cc \u06a9\u0646\u06cc\u062f.<\/li>\r\n<li><strong>\u0635\u0627\u062f\u0642 \u0628\u0627\u0634\u06cc\u062f:<\/strong> \u0633\u0639\u06cc \u0646\u06a9\u0646\u06cc\u062f \u067e\u0627\u0633\u062e \u0647\u0627\u06cc \u0622\u0632\u0645\u0648\u0646 \u062e\u0648\u062f \u0631\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0647\u06cc\u062f. \u0635\u062f\u0627\u0642\u062a \u0628\u0647 \u0645\u0639\u062a\u0628\u0631\u062a\u0631 \u0634\u062f\u0646 \u0622\u0632\u0645\u0648\u0646 \u06a9\u0645\u06a9 \u0645\u06cc \u06a9\u0646\u062f.<\/li>\r\n<\/ul>\r\n<h2><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B3%D8%AA_mmpi_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AA%D8%B1%D9%86%D8%B3_%D9%87%D8%A7\"><\/span><strong><span style=\"color: #008000;\" data-darkreader-inline-color=\"\">\u062a\u0633\u062a mmpi \u0628\u0631\u0627\u06cc \u062a\u0631\u0646\u0633 \u0647\u0627<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n<p>\u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u0648\u0627\u0642\u0639\u06cc\u062a \u06a9\u0647 \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0645\u0628\u062a\u0644\u0627 \u0628\u0647 \u0627\u062e\u062a\u0644\u0627\u0644 \u0645\u0644\u0627\u0644 \u062c\u0646\u0633\u06cc\u062a\u06cc \u0645\u0639\u0645\u0648\u0644\u0627 \u062d\u062f\u0627\u0642\u0644 \u0622\u0633\u06cc\u0628 \u0634\u0646\u0627\u0633\u06cc \u0631\u0648\u0627\u0646\u06cc \u0631\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc \u062f\u0647\u0646\u062f\u060c \u062f\u0631 \u06cc\u06a9 <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5052958\/\" target=\"_blank\" rel=\"noopener\">\u062a\u062d\u0642\u06cc\u0642<\/a> \u0647\u06cc\u0686 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u0627\u0632 \u0646\u0645\u0631\u0627\u062a \u062f\u0631 \u0647\u06cc\u0686 \u06cc\u06a9 \u0627\u0632 \u0645\u0642\u06cc\u0627\u0633 \u0647\u0627 \u0645\u0634\u0627\u0647\u062f\u0647 \u0646\u0634\u062f. \u0647\u06cc\u0686 \u062a\u0641\u0627\u0648\u062a\u06cc \u0628\u06cc\u0646 \u062c\u0646\u0633\u06cc\u062a \u0645\u0634\u0627\u0647\u062f\u0647 \u0646\u0634\u062f \u06a9\u0647 \u0646\u0634\u0627\u0646 \u0645\u06cc \u062f\u0647\u062f \u062c\u0646\u0633\u06cc\u062a \u0627\u062d\u062a\u0645\u0627\u0644\u0627\u064b \u0639\u0627\u0645\u0644 \u062a\u0639\u06cc\u06cc\u0646 \u06a9\u0646\u0646\u062f\u0647 \u0622\u0633\u06cc\u0628 \u0634\u0646\u0627\u0633\u06cc \u0631\u0648\u0627\u0646\u06cc \u062f\u0631 \u062a\u0631\u0646\u0633 \u0647\u0627 \u0646\u06cc\u0633\u062a.<\/p>\r\n\r\n\r\n\r\n\r\n","protected":false},"excerpt":{"rendered":"<p>\u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627\u060c \u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0686\u0646\u062f\u0648\u062c\u0647\u06cc \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u06cc\u062c\u200c\u062a\u0631\u06cc\u0646 \u062a\u0633\u062a \u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0627\u0633\u062a. \u062a\u0633\u062a mmpi \u062a\u0648\u0633\u0637 \u062f\u0648 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u0648 \u0639\u0635\u0628 \u0634\u0646\u0627\u0633 \u0639\u0636\u0648 \u0647\u06cc\u0627\u062a \u0639\u0644\u0645\u06cc \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062a\u0633\u062a \u062f\u0631 \u0627\u0635\u0644 \u0628\u0631\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0647 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u062f\u0631 \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u0647 \u0628\u0648\u062f. [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":7398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[561,4],"tags":[553,567,109,728,724,726,727,133],"paper-cat":[],"class_list":["post-7388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-561","category-psychology","tag-553","tag-567","tag-109","tag-728","tag-724","tag-726","tag-727","tag-133"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.1 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646 - \u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646<\/title>\n<meta name=\"description\" content=\"\u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi \u06cc\u06a9\u06cc \u0627\u0632 \u062a\u0633\u062a\u200c\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0631\u0627\u06cc\u062c \u0627\u0633\u062a. \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u0627\u0632 \u0622\u0632\u0645\u0648\u0646 \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u062f\u0631 \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646\" \/>\n<meta property=\"og:description\" content=\"\u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi \u06cc\u06a9\u06cc \u0627\u0632 \u062a\u0633\u062a\u200c\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0631\u0627\u06cc\u062c \u0627\u0633\u062a. \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u0627\u0632 \u0622\u0632\u0645\u0648\u0646 \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u062f\u0631 \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ravandarman.com\/blog\/mmpi-test\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pezeshkekhoob\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-29T14:32:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T10:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/MMPI-Test.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1001\" \/>\n\t<meta property=\"og:image:height\" content=\"645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0645\u0647\u0646\u0627\u0632 \u062c\u0644\u062f\u06cc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pezeshkekhoob\" \/>\n<meta name=\"twitter:site\" content=\"@pezeshkekhoob\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0645\u0647\u0646\u0627\u0632 \u062c\u0644\u062f\u06cc\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/\"},\"author\":{\"name\":\"\u0645\u0647\u0646\u0627\u0632 \u062c\u0644\u062f\u06cc\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/2df0e580db176cf664bf6e8e6d852c5c\"},\"headline\":\"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646\",\"datePublished\":\"2020-12-29T14:32:10+00:00\",\"dateModified\":\"2025-07-22T10:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/\"},\"wordCount\":96,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/MMPI-Test.jpg\",\"keywords\":[\"\u0627\u062e\u062a\u0644\u0627\u0644 \u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u062e\u062a\u06cc\",\"\u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u062e\u062a\u06cc\",\"\u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc\",\"\u062a\u0633\u062a \u0627\u0632\u062f\u0648\u0627\u062c\",\"\u062a\u0633\u062a \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc\",\"\u062a\u0633\u062a \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0627\u0632\u062f\u0648\u0627\u062c\",\"\u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0634\u0646\u0627\u0633\u06cc\",\"\u0634\u062e\u0635\u06cc\u062a\u200c\u0634\u0646\u0627\u0633\u06cc\"],\"articleSection\":[\"\u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc\",\"\u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/\",\"url\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/\",\"name\":\"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646 - \u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646\",\"isPartOf\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/MMPI-Test.jpg\",\"datePublished\":\"2020-12-29T14:32:10+00:00\",\"dateModified\":\"2025-07-22T10:34:00+00:00\",\"description\":\"\u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi \u06cc\u06a9\u06cc \u0627\u0632 \u062a\u0633\u062a\u200c\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0631\u0627\u06cc\u062c \u0627\u0633\u062a. \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u0627\u0632 \u0622\u0632\u0645\u0648\u0646 \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u062f\u0631 \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.\",\"breadcrumb\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ravandarman.com\/blog\/mmpi-test\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#primaryimage\",\"url\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/MMPI-Test.jpg\",\"contentUrl\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/MMPI-Test.jpg\",\"width\":1001,\"height\":645,\"caption\":\"\u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ravandarman.com\/blog\/mmpi-test\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0635\u0641\u062d\u0647 \u0627\u0635\u0644\u06cc\",\"item\":\"https:\/\/ravandarman.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#website\",\"url\":\"https:\/\/ravandarman.com\/blog\/\",\"name\":\"\u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646\",\"description\":\"| \u0645\u0637\u0627\u0644\u0628\u06cc \u0645\u0641\u06cc\u062f \u0628\u0631\u0627\u06cc \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u0634\u0645\u0627\",\"publisher\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ravandarman.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#organization\",\"name\":\"Pezeshkekhoob\",\"url\":\"https:\/\/ravandarman.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2025\/04\/logoo.png\",\"contentUrl\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2025\/04\/logoo.png\",\"width\":197,\"height\":70,\"caption\":\"Pezeshkekhoob\"},\"image\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pezeshkekhoob\",\"https:\/\/x.com\/pezeshkekhoob\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/2df0e580db176cf664bf6e8e6d852c5c\",\"name\":\"\u0645\u0647\u0646\u0627\u0632 \u062c\u0644\u062f\u06cc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/df61c66476e6ccb9bcd27b9fa2c3c9a130dff0fe713a9ed7ef824c7928c0c26e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/df61c66476e6ccb9bcd27b9fa2c3c9a130dff0fe713a9ed7ef824c7928c0c26e?s=96&d=mm&r=g\",\"caption\":\"\u0645\u0647\u0646\u0627\u0632 \u062c\u0644\u062f\u06cc\"},\"url\":\"https:\/\/ravandarman.com\/blog\/author\/mahnaz\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646 - \u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646","description":"\u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi \u06cc\u06a9\u06cc \u0627\u0632 \u062a\u0633\u062a\u200c\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0631\u0627\u06cc\u062c \u0627\u0633\u062a. \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u0627\u0632 \u0622\u0632\u0645\u0648\u0646 \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u062f\u0631 \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ravandarman.com\/blog\/mmpi-test\/","og_locale":"fa_IR","og_type":"article","og_title":"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646","og_description":"\u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi \u06cc\u06a9\u06cc \u0627\u0632 \u062a\u0633\u062a\u200c\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0631\u0627\u06cc\u062c \u0627\u0633\u062a. \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u0627\u0632 \u0622\u0632\u0645\u0648\u0646 \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u062f\u0631 \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.","og_url":"https:\/\/ravandarman.com\/blog\/mmpi-test\/","og_site_name":"\u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646","article_publisher":"https:\/\/www.facebook.com\/pezeshkekhoob","article_published_time":"2020-12-29T14:32:10+00:00","article_modified_time":"2025-07-22T10:34:00+00:00","og_image":[{"width":1001,"height":645,"url":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/MMPI-Test.jpg","type":"image\/jpeg"}],"author":"\u0645\u0647\u0646\u0627\u0632 \u062c\u0644\u062f\u06cc","twitter_card":"summary_large_image","twitter_creator":"@pezeshkekhoob","twitter_site":"@pezeshkekhoob","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"\u0645\u0647\u0646\u0627\u0632 \u062c\u0644\u062f\u06cc","\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646":"20 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ravandarman.com\/blog\/mmpi-test\/#article","isPartOf":{"@id":"https:\/\/ravandarman.com\/blog\/mmpi-test\/"},"author":{"name":"\u0645\u0647\u0646\u0627\u0632 \u062c\u0644\u062f\u06cc","@id":"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/2df0e580db176cf664bf6e8e6d852c5c"},"headline":"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646","datePublished":"2020-12-29T14:32:10+00:00","dateModified":"2025-07-22T10:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/ravandarman.com\/blog\/mmpi-test\/"},"wordCount":96,"commentCount":3,"publisher":{"@id":"https:\/\/ravandarman.com\/blog\/#organization"},"image":{"@id":"https:\/\/ravandarman.com\/blog\/mmpi-test\/#primaryimage"},"thumbnailUrl":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/MMPI-Test.jpg","keywords":["\u0627\u062e\u062a\u0644\u0627\u0644 \u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u062e\u062a\u06cc","\u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u062e\u062a\u06cc","\u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc","\u062a\u0633\u062a \u0627\u0632\u062f\u0648\u0627\u062c","\u062a\u0633\u062a \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc","\u062a\u0633\u062a \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0627\u0632\u062f\u0648\u0627\u062c","\u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0634\u0646\u0627\u0633\u06cc","\u0634\u062e\u0635\u06cc\u062a\u200c\u0634\u0646\u0627\u0633\u06cc"],"articleSection":["\u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc","\u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ravandarman.com\/blog\/mmpi-test\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ravandarman.com\/blog\/mmpi-test\/","url":"https:\/\/ravandarman.com\/blog\/mmpi-test\/","name":"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646 - \u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646","isPartOf":{"@id":"https:\/\/ravandarman.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ravandarman.com\/blog\/mmpi-test\/#primaryimage"},"image":{"@id":"https:\/\/ravandarman.com\/blog\/mmpi-test\/#primaryimage"},"thumbnailUrl":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/MMPI-Test.jpg","datePublished":"2020-12-29T14:32:10+00:00","dateModified":"2025-07-22T10:34:00+00:00","description":"\u062a\u0633\u062a \u0634\u062e\u0635\u06cc\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u06cc\u0627 \u062a\u0633\u062a mmpi \u06cc\u06a9\u06cc \u0627\u0632 \u062a\u0633\u062a\u200c\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc \u0631\u0627\u06cc\u062c \u0627\u0633\u062a. \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646 \u0627\u0632 \u0622\u0632\u0645\u0648\u0646 \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u062f\u0631 \u062a\u0634\u062e\u06cc\u0635 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.","breadcrumb":{"@id":"https:\/\/ravandarman.com\/blog\/mmpi-test\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ravandarman.com\/blog\/mmpi-test\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/ravandarman.com\/blog\/mmpi-test\/#primaryimage","url":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/MMPI-Test.jpg","contentUrl":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2020\/12\/MMPI-Test.jpg","width":1001,"height":645,"caption":"\u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627"},{"@type":"BreadcrumbList","@id":"https:\/\/ravandarman.com\/blog\/mmpi-test\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0635\u0641\u062d\u0647 \u0627\u0635\u0644\u06cc","item":"https:\/\/ravandarman.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u062a\u0633\u062a mmpi \u06cc\u0627 \u062a\u0633\u062a \u0645\u06cc\u0646\u0647 \u0633\u0648\u062a\u0627 \u0686\u06cc\u0633\u062a\u061f \u062a\u0633\u062a MMPI \u0622\u0646\u0644\u0627\u06cc\u0646"}]},{"@type":"WebSite","@id":"https:\/\/ravandarman.com\/blog\/#website","url":"https:\/\/ravandarman.com\/blog\/","name":"\u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646","description":"| \u0645\u0637\u0627\u0644\u0628\u06cc \u0645\u0641\u06cc\u062f \u0628\u0631\u0627\u06cc \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u0634\u0645\u0627","publisher":{"@id":"https:\/\/ravandarman.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ravandarman.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/ravandarman.com\/blog\/#organization","name":"Pezeshkekhoob","url":"https:\/\/ravandarman.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/ravandarman.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2025\/04\/logoo.png","contentUrl":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2025\/04\/logoo.png","width":197,"height":70,"caption":"Pezeshkekhoob"},"image":{"@id":"https:\/\/ravandarman.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pezeshkekhoob","https:\/\/x.com\/pezeshkekhoob"]},{"@type":"Person","@id":"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/2df0e580db176cf664bf6e8e6d852c5c","name":"\u0645\u0647\u0646\u0627\u0632 \u062c\u0644\u062f\u06cc","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/df61c66476e6ccb9bcd27b9fa2c3c9a130dff0fe713a9ed7ef824c7928c0c26e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df61c66476e6ccb9bcd27b9fa2c3c9a130dff0fe713a9ed7ef824c7928c0c26e?s=96&d=mm&r=g","caption":"\u0645\u0647\u0646\u0627\u0632 \u062c\u0644\u062f\u06cc"},"url":"https:\/\/ravandarman.com\/blog\/author\/mahnaz\/"}]}},"_links":{"self":[{"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/posts\/7388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/comments?post=7388"}],"version-history":[{"count":0,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/posts\/7388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/media\/7398"}],"wp:attachment":[{"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/media?parent=7388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/categories?post=7388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/tags?post=7388"},{"taxonomy":"paper-cat","embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/paper-cat?post=7388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}