{"id":20139,"date":"2024-02-09T20:07:27","date_gmt":"2024-02-09T16:37:27","guid":{"rendered":"https:\/\/pezeshkekhoob.com\/blog\/?p=20139"},"modified":"2025-12-07T15:13:16","modified_gmt":"2025-12-07T11:43:16","slug":"vulnerability-schema","status":"publish","type":"post","link":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/","title":{"rendered":"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc"},"content":{"rendered":"<blockquote><p><span style=\"font-weight: 400;\">\u0627\u062d\u0633\u0627\u0633 \u0646\u06af\u0631\u0627\u0646\u06cc \u0627\u0632 \u0648\u0642\u0648\u0639 \u06cc\u06a9 \u0627\u062a\u0641\u0627\u0642 \u0628\u062f \u0648 \u0627\u0633\u062a\u0631\u0633 \u0646\u0627\u0634\u06cc \u0627\u0632 \u0622\u0646\u060c \u062f\u0631 \u0628\u0639\u0636\u06cc \u0645\u0648\u0627\u0642\u0639 \u0637\u0628\u06cc\u0639\u06cc \u0648 \u0644\u0627\u0632\u0645 \u0627\u0633\u062a. \u0627\u0641\u0631\u0627\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0637\u0648\u0644 \u0632\u0646\u062f\u06af\u06cc \u062f\u0631\u0628\u0627\u0631\u0647 \u0633\u0644\u0627\u0645\u062a\u06cc\u060c \u0631\u0641\u0627\u0647 \u0648 \u0634\u0631\u0627\u06cc\u0637 \u062e\u0648\u062f\u060c \u0627\u062d\u0633\u0627\u0633 \u0646\u06af\u0631\u0627\u0646\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0648 \u062e\u0637\u0631\u0646\u0627\u06a9\u060c \u062f\u0633\u062a \u0628\u0647 \u0627\u0642\u062f\u0627\u0645\u0627\u062a\u06cc \u0628\u0632\u0646\u0646\u062f. \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u062a\u0642\u0631\u06cc\u0628\u0627 \u062f\u0631 \u0647\u0645\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0648 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc\u060c \u0627\u062d\u0633\u0627\u0633 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0635\u062f\u0645\u0647 \u062f\u06cc\u062f\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u062f\u0631\u06af\u06cc\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0634\u062f\u0647 \u0627\u0646\u062f. \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u0627\u0641\u0631\u0627\u062f \u0627\u062d\u0633\u0627\u0633 \u0627\u0636\u0637\u0631\u0627\u0628 \u0648 \u0646\u06af\u0631\u0627\u0646\u06cc \u0634\u062f\u06cc\u062f\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc\u060c \u0636\u0631\u0631 \u0645\u0627\u0644\u06cc \u0648 \u0631\u0648\u0627\u0628\u0637 \u0639\u0627\u0637\u0641\u06cc \u0648 \u0645\u06cc\u0627\u0646 \u0641\u0631\u062f\u06cc \u062e\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0628\u0631\u0627\u06cc \u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc\u060c \u0639\u0644\u0644\u060c \u0627\u0646\u0648\u0627\u0639 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0622\u0646 \u0645\u0637\u0644\u0628 \u062d\u0627\u0636\u0631 \u0631\u0627 \u0645\u0637\u0627\u0644\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_80 ez-toc-wrap-right counter-hierarchy ez-toc-counter-rtl ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0642\u0627\u0644\u0647<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%AC%D8%AF%D9%88%D9%84_%D8%AE%D9%84%D8%A7%D8%B5%D9%87_%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u062c\u062f\u0648\u0644 \u062e\u0644\u0627\u0635\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D9%86%D8%B4%D8%A7%D9%86%D9%87_%D9%87%D8%A7%DB%8C_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8%E2%80%8C%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B9%D9%84%D8%AA_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D8%A8%D9%87_%D8%B6%D8%B1%D8%B1_%D9%88_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C\" >\u0639\u0644\u062a \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D9%88_%D9%88%D8%A7%D9%84%D8%AF%DB%8C%D9%86_%D8%AA%D9%86%D8%A8%DB%8C%D9%87_%DA%AF%D8%B1\" >\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0648\u0627\u0644\u062f\u06cc\u0646 \u062a\u0646\u0628\u06cc\u0647 \u06af\u0631<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D9%88%D8%A7%D9%84%D8%AF%DB%8C%D9%86_%D9%85%D8%AD%D8%A7%D9%81%D8%B8%D9%87_%DA%A9%D8%A7%D8%B1_%D9%88_%D8%AA%D9%84%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u0648\u0627\u0644\u062f\u06cc\u0646 \u0645\u062d\u0627\u0641\u0638\u0647 \u06a9\u0627\u0631 \u0648 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D9%88%D8%A7%D9%84%D8%AF%DB%8C%D9%86_%D9%85%D8%AD%D8%AF%D9%88%D8%AF_%DA%A9%D9%86%D9%86%D8%AF%D9%87_%D9%88_%D8%AA%D9%84%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u0648\u0627\u0644\u062f\u06cc\u0646 \u0645\u062d\u062f\u0648\u062f \u06a9\u0646\u0646\u062f\u0647 \u0648 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B1%D9%81%D8%AA%D8%A7%D8%B1_%D9%87%D8%A7%DB%8C_%D8%A7%D8%BA%D8%B1%D8%A7%D9%82_%D8%A2%D9%85%DB%8C%D8%B2_%D9%88%D8%A7%D9%84%D8%AF%DB%8C%D9%86\" >\u0631\u0641\u062a\u0627\u0631 \u0647\u0627\u06cc \u0627\u063a\u0631\u0627\u0642 \u0622\u0645\u06cc\u0632 \u0648\u0627\u0644\u062f\u06cc\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D9%88%D9%82%D9%88%D8%B9_%D8%B1%D9%88%DB%8C%D8%AF%D8%A7%D8%AF_%D9%87%D8%A7%DB%8C_%D9%85%D8%AE%D8%A7%D8%B7%D8%B1%D9%87_%D8%A2%D9%85%DB%8C%D8%B2_%D9%88_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u0648\u0642\u0648\u0639 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u0645\u062e\u0627\u0637\u0631\u0647 \u0622\u0645\u06cc\u0632 \u0648 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D9%81%D8%B9%D8%A7%D9%84%DB%8C%D8%AA_%D8%A8%DB%8C%D8%B4_%D8%A7%D8%B2_%D8%AD%D8%AF_%D8%A2%D9%85%DB%8C%DA%AF%D8%AF%D8%A7%D9%84_%D9%88_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u0641\u0639\u0627\u0644\u06cc\u062a \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0622\u0645\u06cc\u06af\u062f\u0627\u0644 \u0648 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D8%AF%D8%B1_%DA%A9%D9%88%D8%AF%DA%A9%D8%A7%D9%86\" >\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u062f\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%A7%D8%AE%D8%AA%D9%84%D8%A7%D9%84%D8%A7%D8%AA_%D8%B1%D9%88%D8%A7%D9%86%DB%8C_%D9%87%D9%85%D8%B1%D8%A7%D9%87_%D8%A8%D8%A7_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8%E2%80%8C%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0647\u0645\u0631\u0627\u0647 \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u0627\u0646\u0648\u0627\u0639 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D9%86%D8%B3%D8%A8%D8%AA_%D8%A8%D9%87_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C\" >\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D9%88%D9%82%D9%88%D8%B9_%D8%AE%D8%B7%D8%B1\" >\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648\u0642\u0648\u0639 \u062e\u0637\u0631<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D8%A8%D9%87_%D8%B6%D8%B1%D8%B1_%D9%88_%D9%85%D8%A7%D9%84%DB%8C\" >\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0645\u0627\u0644\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%AF%D8%B3%D8%AA_%D8%AF%D8%A7%D8%AF%D9%86_%DA%A9%D9%86%D8%AA%D8%B1%D9%84\" >\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u06a9\u0646\u062a\u0631\u0644<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D9%88_%D8%B1%D9%88%D8%A7%D8%A8%D8%B7_%D8%B9%D8%A7%D8%B7%D9%81%DB%8C\" >\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0631\u0648\u0627\u0628\u0637 \u0639\u0627\u0637\u0641\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AA%D9%84%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u062f\u0631\u0645\u0627\u0646 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%AF%D8%B1%D9%85%D8%A7%D9%86%DB%8C\" >\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B4%D9%86%D8%A7%D8%AE%D8%AA%DB%8C_%D8%B1%D9%81%D8%AA%D8%A7%D8%B1%DB%8C\" >\u062f\u0631\u0645\u0627\u0646 \u0634\u0646\u0627\u062e\u062a\u06cc \u0631\u0641\u062a\u0627\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%DA%A9%D9%86%D8%A7%D8%B1_%D8%A2%D9%85%D8%AF%D9%86_%D8%A8%D8%A7_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8%E2%80%8C%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u06a9\u0646\u0627\u0631 \u0622\u0645\u062f\u0646 \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B3%D8%A8%DA%A9_%D9%87%D8%A7%DB%8C_%D9%85%D9%82%D8%A7%D8%A8%D9%84%D9%87_%D8%A8%D8%A7_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u0633\u0628\u06a9 \u0647\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%B9%D9%88%D8%A7%D8%B1%D8%B6_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\" >\u0639\u0648\u0627\u0631\u0636 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#%D8%A2%D9%86%DA%86%D9%87_%D8%A7%D8%B2_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D8%A2%D9%85%D9%88%D8%AE%D8%AA%DB%8C%D9%85\" >\u0622\u0646\u0686\u0647 \u0627\u0632 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0622\u0645\u0648\u062e\u062a\u06cc\u0645<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AC%D8%AF%D9%88%D9%84_%D8%AE%D9%84%D8%A7%D8%B5%D9%87_%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u062c\u062f\u0648\u0644 \u062e\u0644\u0627\u0635\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-weight: 400;\">\u0648\u06cc\u0698\u06af\u06cc \u0627\u0641\u0631\u0627\u062f \u062f\u0627\u0631\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0646\u06af\u0631\u0627\u0646\u06cc \u062f\u0627\u0626\u0645\u06cc\u060c \u0633\u0646\u0627\u0631\u06cc\u0648\u0633\u0627\u0632\u06cc \u0645\u0646\u0641\u06cc\u060c \u0627\u062d\u0633\u0627\u0633 \u0628\u06cc\u200c\u0627\u0639\u062a\u0645\u0627\u062f\u06cc\u060c \u062a\u0631\u0633 \u0627\u0632 \u06a9\u0646\u062a\u0631\u0644 \u0646\u062f\u0627\u0634\u062a\u0646\u060c \u0627\u0633\u062a\u0631\u0633 \u0632\u06cc\u0627\u062f\u060c \u062a\u0645\u0631\u06a9\u0632 \u0628\u0631 \u0628\u062f\u062a\u0631\u06cc\u0646 \u0627\u062a\u0641\u0627\u0642\u200c\u0647\u0627<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">\u0639\u0644\u0644 \u0634\u06a9\u0644 \u06af\u06cc\u0631\u06cc \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0648\u0627\u0644\u062f\u06cc\u0646 \u062a\u0646\u0628\u06cc\u0647\u200c\u06af\u0631\u060c \u0645\u062d\u062f\u0648\u062f\u06a9\u0646\u0646\u062f\u0647 \u06cc\u0627 \u0628\u06cc\u0634\u200c\u0645\u062d\u0627\u0641\u0638\u061b \u0631\u0648\u06cc\u062f\u0627\u062f\u0647\u0627\u06cc \u062a\u0631\u0648\u0645\u0627\u062a\u06cc\u06a9 \u06a9\u0648\u062f\u06a9\u06cc\u061b \u062a\u062c\u0631\u0628\u0647 \u062e\u0637\u0631\u061b \u0628\u0632\u0631\u06af\u200c\u0646\u0645\u0627\u06cc\u06cc \u062a\u0631\u0633 \u062a\u0648\u0633\u0637 \u0648\u0627\u0644\u062f\u06cc\u0646\u061b \u0641\u0639\u0627\u0644\u06cc\u062a \u0628\u06cc\u0634\u200c\u0627\u0632\u062d\u062f \u0622\u0645\u06cc\u06af\u062f\u0627\u0644<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">\u067e\u06cc\u0627\u0645\u062f\u0647\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u06a9\u0627\u0647\u0634 \u06a9\u06cc\u0641\u06cc\u062a \u0632\u0646\u062f\u06af\u06cc\u060c \u0627\u062c\u062a\u0646\u0627\u0628 \u0627\u0632 \u062a\u0641\u0631\u06cc\u062d\u060c \u0631\u0648\u0627\u0628\u0637 \u0622\u0633\u06cc\u0628\u200c\u062f\u06cc\u062f\u0647\u060c \u0645\u0631\u0627\u062c\u0639\u0647\u200c\u0647\u0627\u06cc \u0645\u06a9\u0631\u0631 \u067e\u0632\u0634\u06a9\u06cc\u060c \u0641\u0627\u062c\u0639\u0647\u200c\u0633\u0627\u0632\u06cc\u060c \u0627\u0646\u0632\u0648\u0627\u060c \u0627\u0633\u062a\u0631\u0633 \u0628\u0627\u0644\u0627<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">\u0631\u0627\u0647 \u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u00a0<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u0645\u062f\u06cc\u0631\u06cc\u062a \u0627\u0641\u06a9\u0627\u0631\u060c \u0630\u0647\u0646\u200c\u0622\u06af\u0627\u0647\u06cc\u060c \u0622\u0631\u0627\u0645\u200c\u0633\u0627\u0632\u06cc\u060c \u0686\u0627\u0644\u0634 \u0628\u0627\u0648\u0631\u0647\u0627\u06cc \u063a\u06cc\u0631\u0645\u0646\u0637\u0642\u06cc\u060c \u062a\u0648\u062c\u0647 \u0628\u0647 \u0634\u0648\u0627\u0647\u062f \u0645\u062e\u0627\u0644\u0641\u060c \u0645\u0631\u0627\u062c\u0639\u0647 \u0628\u0647 \u062f\u0631\u0645\u0627\u0646\u06af\u0631<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/blockquote>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-20143 size-full\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062f\u0631\u0645\u0627\u0646-\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc.jpg\" alt=\"\u062f\u0631\u0645\u0627\u0646 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc\" width=\"1001\" height=\"645\" srcset=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062f\u0631\u0645\u0627\u0646-\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc.jpg 1001w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062f\u0631\u0645\u0627\u0646-\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-300x193.jpg 300w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062f\u0631\u0645\u0627\u0646-\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-768x495.jpg 768w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062f\u0631\u0645\u0627\u0646-\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-585x377.jpg 585w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/p>\n<div style=\"background-color: #caf0f8; padding: 10px; border-radius: 5px; text-align: justify;\">\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span><strong><span style=\"color: #008000;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0686\u06cc\u0633\u062a\u061f<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0639\u0628\u0627\u0631\u062a \u0627\u0633\u062a \u0627\u0632\u060c \u0628\u0627\u0648\u0631 \u0647\u0627\u06cc \u0628\u0646\u06cc\u0627\u062f\u06cc\u0646 \u0648 \u0627\u0628\u062a\u062f\u0627\u06cc\u06cc \u0634\u06a9\u0644 \u06af\u0631\u0641\u062a\u0647 \u062f\u0631 \u0630\u0647\u0646 \u0627\u0641\u0631\u0627\u062f \u06a9\u0647 \u0646\u0627\u0634\u06cc \u0627\u0632 \u0627\u0644\u06af\u0648\u06cc \u0627\u0631\u062a\u0628\u0627\u0637\u06cc \u0622\u0646 \u0647\u0627 \u0628\u0627 \u0648\u0627\u0644\u062f\u06cc\u0646 \u06cc\u0627 \u0645\u0631\u0627\u0642\u0628\u06cc\u0646 \u0648 \u062c\u0647\u0627\u0646 \u067e\u06cc\u0631\u0627\u0645\u0648\u0646 \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 \u0627\u0648\u0644\u06cc\u0647 \u06a9\u0648\u062f\u06a9\u06cc \u0627\u0633\u062a. \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0647\u0627 \u0631\u0627 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0634\u06cc\u0648\u0647 \u062c\u0647\u0627\u0646 \u0628\u06cc\u0646\u06cc \u0648 \u0646\u06af\u0627\u0647 \u0628\u0647 \u0631\u062e\u062f\u0627\u062f \u0647\u0627 \u0648 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0628\u06cc\u0631\u0648\u0646\u06cc \u062f\u0627\u0646\u0633\u062a \u06a9\u0647 \u0647\u0631 \u0641\u0631\u062f \u0628\u0647 \u0634\u06a9\u0644 \u062e\u0627\u0635 \u062e\u0648\u062f \u0628\u0627 \u0622\u0646\u0647\u0627 \u0645\u0648\u0627\u062c\u0647 \u0634\u062f\u0647 \u0648 \u0631\u0641\u062a\u0627\u0631 \u0645\u06cc \u06a9\u0646\u062f. \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0647\u0627 \u0645\u0634\u062e\u0635 \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f \u0686\u06af\u0648\u0646\u0647 \u0645\u0639\u0646\u0627 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f.<\/span><\/p>\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc (Vulnerability schema) \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u06f1\u06f8 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0646\u0627\u0633\u0627\u0632\u06af\u0627\u0631 \u0645\u0637\u0631\u062d \u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u062c\u0641\u0631\u06cc \u06cc\u0627\u0646\u06af \u0627\u0633\u062a. \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u06cc\u0627 \u062a\u0644\u0647 \u0641\u0627\u062c\u0639\u0647 \u0633\u0627\u0632\u06cc\u060c \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u0627\u0641\u0631\u0627\u062f \u062f\u0627\u0626\u0645\u0627 \u0646\u0633\u0628\u062a \u0628\u0647 \u0648\u0642\u0648\u0639 \u06cc\u06a9 \u062d\u0627\u062f\u062b\u0647 \u062e\u0637\u0631\u0646\u0627\u06a9 \u0648 \u0641\u0627\u062c\u0639\u0647 \u0622\u0645\u06cc\u0632\u060c \u0627\u062d\u0633\u0627\u0633 \u062a\u0646\u0634 \u0648 \u0627\u0636\u0637\u0631\u0627\u0628 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0627\u0641\u0631\u0627\u062f \u062f\u0627\u0631\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc \u06cc\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062a\u0631\u0633 \u0627\u0632 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u0639\u0645\u0648\u0644\u0627 \u0628\u0647 \u0628\u062f\u062a\u0631\u06cc\u0646 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u0645\u0645\u06a9\u0646 \u0641\u06a9\u0631 \u06a9\u0631\u062f\u0647 \u0648 \u0628\u062f\u062a\u0631\u06cc\u0646 \u0633\u0646\u0627\u0631\u06cc\u0648 \u0647\u0627\u06cc \u0630\u0647\u0646\u06cc \u0631\u0627 \u0645\u06cc \u0633\u0627\u0632\u0646\u062f \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0647\u06cc\u0686 \u0648\u0642\u062a \u0628\u0647 \u0648\u0627\u0642\u0639\u06cc\u062a \u0646\u067e\u06cc\u0648\u0646\u062f\u062f. \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc\u060c \u0627\u0634\u062a\u063a\u0627\u0644 \u0630\u0647\u0646\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc \u0648 \u0628\u06cc\u0645\u0627\u0631\u06af\u0648\u0646\u0647 \u0627\u06cc \u0628\u0647 \u0645\u0648\u0636\u0648\u0639\u0627\u062a\u06cc \u0645\u0627\u0646\u0646\u062f \u0633\u0644\u0627\u0645\u062a\u06cc \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc\u060c \u0636\u0631\u0631 \u0647\u0627\u06cc \u0645\u0627\u0644\u06cc\u060c \u0631\u0648\u0627\u0628\u0637 \u0639\u0627\u0637\u0641\u06cc \u0648 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u062c\u0646\u0627\u06cc\u06cc \u062f\u0627\u0631\u0646\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06cc\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u06af\u0632\u0646\u062f \u0648 \u0622\u0633\u06cc\u0628\u060c \u0641\u06a9\u0631 \u06a9\u0631\u062f\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0628\u0647 \u0648\u0642\u0648\u0639 \u0627\u062a\u0641\u0627\u0642\u06cc \u0648\u062d\u0634\u062a\u0646\u0627\u06a9 \u0648 \u0646\u0627\u062e\u0648\u0634\u0627\u06cc\u0646\u062f \u062f\u0631\u0628\u0627\u0631\u0647 \u062e\u0648\u062f \u06cc\u0627 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0627\u0633\u062a\u060c \u06a9\u0647 \u0642\u0627\u062f\u0631 \u0628\u0647 \u0627\u062c\u062a\u0646\u0627\u0628 \u06cc\u0627 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0622\u0646 \u0646\u06cc\u0633\u062a\u0646\u062f. \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u062a\u0627 \u0627\u0641\u0631\u0627\u062f \u062f\u0631\u06af\u06cc\u0631 \u0622\u0646\u060c \u0628\u0647 \u0637\u0648\u0631 \u062f\u0627\u0626\u0645\u06cc \u0646\u06af\u0631\u0627\u0646 \u0645\u062d\u0627\u0641\u0638\u062a \u0627\u0632 \u062e\u0648\u062f \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0622\u0633\u06cc\u0628 \u0647\u0627\u06cc \u0648\u0627\u0631\u062f \u0634\u062f\u0647 \u0627\u0632 \u0637\u0631\u0641 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0628\u0627\u0634\u0646\u062f \u0648 \u0646\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0631\u0648\u0632\u0645\u0631\u0647 \u062e\u0648\u062f \u0631\u0633\u06cc\u062f\u06af\u06cc \u06a9\u0631\u062f\u0647 \u0648 \u0645\u0627\u0646\u0646\u062f \u062f\u06cc\u06af\u0631\u0627\u0646 \u062a\u0641\u0631\u06cc\u062d \u06a9\u0646\u0646\u062f \u06cc\u0627 \u0628\u0647 \u0627\u0633\u062a\u0631\u0627\u062d\u062a \u0628\u067e\u0631\u062f\u0627\u0632\u0646\u062f. \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u0632 \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0627\u06cc \u0631\u0648\u0632\u0645\u0631\u0647 \u062e\u0648\u062f \u062f\u0633\u062a \u0628\u06a9\u0634\u0646\u062f\u060c \u06cc\u0627 \u0627\u0632 \u062d\u0636\u0648\u0631 \u062f\u0631 \u0645\u0648\u0642\u0639\u06cc\u062a \u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u062c\u0645\u0639 \u0647\u0627\u06cc \u062f\u0648\u0633\u062a\u0627\u0646\u0647\u060c \u0633\u062e\u0646\u0631\u0627\u0646\u06cc \u0647\u0627 \u0648 \u0645\u0633\u0627\u0641\u0631\u062a \u0627\u062c\u062a\u0646\u0627\u0628 \u06a9\u0646\u0646\u062f. \u0645\u0639\u0645\u0648\u0644\u0627 \u0627\u0641\u0631\u0627\u062f\u06cc \u062f\u0686\u0627\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0645\u06cc \u0634\u0648\u0646\u062f \u06a9\u0647 \u062f\u0648\u0631\u0627\u0646 \u06a9\u0648\u062f\u06a9\u06cc \u0645\u062e\u0627\u0637\u0631\u0647 \u0622\u0645\u06cc\u0632 \u0648 \u0633\u062e\u062a\u06cc \u0631\u0627 \u06af\u0630\u0631\u0627\u0646\u062f\u0647 \u0627\u0646\u062f \u0648 \u062f\u0631 \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u06cc \u0647\u0645\u0648\u0627\u0631\u0647 \u0627\u062d\u0633\u0627\u0633 \u062e\u0637\u0631 \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u0627\u0634\u062a.<\/span><\/p>\n<p><strong>\u0628\u0631\u0627\u06cc \u0645\u0637\u0627\u0644\u0639\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f: <a href=\"https:\/\/ravandarman.com\/blog\/young-schema-test\/\">\u0627\u0646\u0648\u0627\u0639 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0647\u0627 \u0648 \u062a\u06a9\u0646\u06cc\u06a9\u200c \u0647\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u06cc\u061b \u062a\u0633\u062a \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u06cc\u0627\u0646\u06af<\/a><\/strong><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-20146 size-full\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc.jpg\" alt=\"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc\" width=\"1001\" height=\"645\" srcset=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc.jpg 1001w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc-300x193.jpg 300w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc-768x495.jpg 768w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc-585x377.jpg 585w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/p>\n<blockquote>\n<h2><span class=\"ez-toc-section\" id=\"%D9%86%D8%B4%D8%A7%D9%86%D9%87_%D9%87%D8%A7%DB%8C_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8%E2%80%8C%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0686\u0646\u0627\u0646\u0686\u0647 \u0641\u0631\u062f \u06cc\u0627 \u0627\u0637\u0631\u0627\u0641\u06cc\u0627\u0646 \u0627\u0648 \u062f\u0627\u0631\u0627\u06cc \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0627\u0634\u0646\u062f\u060c \u0628\u0627 \u0645\u0634\u06a9\u0644\u0627\u062a \u0632\u06cc\u0627\u062f\u06cc \u062f\u0631\u06af\u06cc\u0631 \u062e\u0648\u0627\u0647\u0646\u062f \u0634\u062f. \u062a\u0634\u062e\u06cc\u0635 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0627\u0639\u062b \u062f\u0631\u06a9 \u0628\u0647\u062a\u0631 \u0622\u0646 \u0647\u0627 \u0645\u06cc \u0634\u0648\u062f. \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u0647 \u0647\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0622\u0634\u0646\u0627\u06cc\u06cc \u0648 \u0622\u06af\u0627\u0647\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0646 \u0628\u0627 \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u06cc \u0622\u0646 \u0627\u0633\u062a\u060c \u06a9\u0647 \u0639\u0628\u0627\u0631\u062a \u0627\u0633\u062a \u0627\u0632:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0646\u06af\u0631\u0627\u0646\u06cc \u062f\u0627\u0626\u0645\u06cc \u062f\u0631\u0628\u0627\u0631\u0647 \u0627\u062d\u062a\u0645\u0627\u0644 \u0627\u0634\u062a\u0628\u0627\u0647 \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062a\u0631\u0633 \u0647\u0645\u06cc\u0634\u06af\u06cc \u0627\u0632 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0646\u0627\u062e\u0648\u0634\u0627\u06cc\u0646\u062f<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u0634\u062a\u063a\u0627\u0644 \u0630\u0647\u0646\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc \u0628\u0627 \u0627\u0641\u06a9\u0627\u0631 \u201c\u0686\u0647 \u0645\u06cc\u200c\u0634\u062f \u0627\u06af\u0631\u2026\u201d<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062a\u062c\u0631\u0628\u0647 \u0634\u062f\u06cc\u062f \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u0627\u0636\u0637\u0631\u0627\u0628 \u0648 \u0627\u0633\u062a\u0631\u0633<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u0648 \u0628\u06cc \u0627\u0639\u062a\u0645\u0627\u062f\u06cc \u0628\u0647 \u062f\u0646\u06cc\u0627<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062a\u0631\u0633 \u0627\u0632 \u0648\u0642\u0648\u0639 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u063a\u06cc\u0631 \u0642\u0627\u0628\u0644 \u06a9\u0646\u062a\u0631\u0644<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u0634\u062f\u06cc\u062f \u0648 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u06a9\u0646\u062a\u0631\u0644 \u062e\u0648\u062f<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0627\u0634\u062a\u0646 \u0627\u0641\u06a9\u0627\u0631 \u0627\u0633\u062a\u0631\u0633 \u0632\u0627 \u0648 \u0646\u06af\u0631\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0646\u06af\u0631\u0627\u0646\u06cc \u0634\u062f\u06cc\u062f \u062f\u0631 \u0645\u0648\u0631\u062f \u0628\u06cc\u0645\u0627\u0631\u06cc \u0648 \u0633\u0644\u0627\u0645\u062a \u062c\u0633\u0645\u0627\u0646\u06cc<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062a\u0631\u0633 \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u0627\u0645\u0648\u0627\u0644 \u0648 \u062f\u0627\u0631\u0627\u06cc\u06cc \u0647\u0627<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u0686\u0646\u0627\u0646\u0686\u0647 \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0631\u0627 \u062f\u0631 \u062e\u0648\u062f \u0645\u0634\u0627\u0647\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0627\u06cc\u062f\u060c \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 <\/span><a href=\"https:\/\/pezeshkekhoob.com\/psychologists\/1c-tehran\"><span style=\"font-weight: 400;\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u062a\u0647\u0631\u0627\u0646<\/span><\/a><span style=\"font-weight: 400;\"> \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/span><\/p><\/blockquote>\n<blockquote>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B9%D9%84%D8%AA_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D8%A8%D9%87_%D8%B6%D8%B1%D8%B1_%D9%88_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0639\u0644\u062a \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0627\u0632 \u062f\u0644\u0627\u06cc\u0644 \u0634\u06a9\u0644 \u06af\u06cc\u0631\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc\u060c \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u0646\u0627\u0634\u06cc \u0627\u0632 \u0633\u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0648 \u0628\u062f\u0631\u0641\u062a\u0627\u0631\u06cc \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 \u06a9\u0648\u062f\u06a9\u06cc \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 \u06a9\u0648\u062f\u06a9\u06cc \u062e\u0648\u062f\u060c \u0627\u062d\u0633\u0627\u0633 \u0646\u06af\u0631\u0627\u0646\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u0628\u0647 \u062f\u0644\u0627\u06cc\u0644 \u0645\u062a\u0641\u0627\u0648\u062a \u062a\u062c\u0631\u0628\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0646\u062f\u061b \u0645\u0639\u0645\u0648\u0644\u0627 \u062f\u0631 \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u06cc \u0646\u06cc\u0632 \u062f\u0627\u0626\u0645\u0627 \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u0627\u0632 \u0648\u0642\u0648\u0639 \u06cc\u06a9 \u0627\u062a\u0641\u0627\u0642 \u0645\u062e\u0627\u0637\u0631\u0647 \u0622\u0645\u06cc\u0632 \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u0627\u0634\u062a. \u0628\u0631\u0627\u06cc \u0628\u0631\u0631\u0633\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0639\u0644\u0644 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647 \u0631\u06cc\u0634\u0647 \u0647\u0627\u06cc \u062a\u062d\u0648\u0644\u06cc \u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 \u0631\u0634\u062f \u0628\u067e\u0631\u062f\u0627\u0632\u06cc\u0645. \u0631\u06cc\u0634\u0647 \u0647\u0627\u06cc \u062a\u062d\u0648\u0644\u06cc \u0627\u06cc\u0646 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0639\u0628\u0627\u0631\u062a \u0627\u0633\u062a \u0627\u0632:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0648\u0627\u0644\u062f\u06cc\u0646 \u062a\u0646\u0628\u06cc\u0647 \u06af\u0631<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0648\u0627\u0644\u062f\u06cc\u0646 \u0645\u062d\u0627\u0641\u0638\u0647 \u06a9\u0627\u0631<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0648\u0627\u0644\u062f\u06cc\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0645\u062d\u062f\u0648\u062f \u06a9\u0646\u0646\u062f\u0647<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0631\u0641\u062a\u0627\u0631 \u0647\u0627\u06cc \u0627\u063a\u0631\u0627\u0642 \u0622\u0645\u06cc\u0632 \u0648\u0627\u0644\u062f\u06cc\u0646<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0648\u0642\u0648\u0639 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u0645\u062e\u0627\u0637\u0631\u0647 \u0622\u0645\u06cc\u0632<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0641\u0639\u0627\u0644\u06cc\u062a \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0622\u0645\u06cc\u06af\u062f\u0627\u0644<\/span><\/li>\n<\/ul>\n<p><strong>\u0645\u0642\u0627\u0644\u0647 \u0645\u0634\u0627\u0628\u0647: <a href=\"https:\/\/ravandarman.com\/blog\/dependence-incompetence-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0648\u0627\u0628\u0633\u062a\u06af\u06cc \u0686\u06cc\u0633\u062a\u061f \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u060c \u0639\u0644\u0644 \u0648 \u062f\u0631\u0645\u0627\u0646 \u062a\u0644\u0647 \u0648\u0627\u0628\u0633\u062a\u06af\u06cc<\/a><\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D9%88_%D9%88%D8%A7%D9%84%D8%AF%DB%8C%D9%86_%D8%AA%D9%86%D8%A8%DB%8C%D9%87_%DA%AF%D8%B1\"><\/span><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0648\u0627\u0644\u062f\u06cc\u0646 \u062a\u0646\u0628\u06cc\u0647 \u06af\u0631<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0648\u0627\u0644\u062f\u06cc\u0646\u06cc \u06a9\u0647 \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0634\u06a9\u0644 \u0647\u0627\u06cc \u06a9\u0644\u0627\u0645\u06cc \u0648 \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u0645\u0648\u0631\u062f \u062a\u0647\u062f\u06cc\u062f \u0648 \u062a\u0646\u0628\u06cc\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc \u062f\u0647\u0646\u062f\u060c \u0632\u0645\u06cc\u0646\u0647 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u0631 \u0628\u0648\u062f\u0646 \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633\u060c \u0627\u0636\u0637\u0631\u0627\u0628 \u0648 \u0634\u06a9\u0644 \u06af\u06cc\u0631\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06cc\u0627 \u0622\u0633\u06cc\u0628 \u0631\u0627 \u062f\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062e\u0648\u062f \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0686\u0646\u06cc\u0646 \u06a9\u0648\u062f\u06a9\u0627\u0646\u06cc \u062f\u0631 \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u06cc \u0646\u06cc\u0632\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u0632 \u0645\u0648\u0631\u062f \u062a\u0647\u062f\u06cc\u062f \u0648 \u062a\u0646\u0628\u06cc\u0647 \u0634\u062f\u0646 \u0627\u062c\u062a\u0646\u0627\u0628 \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0627\u0626\u0645\u0627 \u0646\u06af\u0631\u0627\u0646 \u0645\u0648\u0631\u062f \u0627\u0630\u06cc\u062a \u0648 \u0622\u0632\u0627\u0631 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646 \u0628\u0627\u0634\u0646\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%88%D8%A7%D9%84%D8%AF%DB%8C%D9%86_%D9%85%D8%AD%D8%A7%D9%81%D8%B8%D9%87_%DA%A9%D8%A7%D8%B1_%D9%88_%D8%AA%D9%84%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0648\u0627\u0644\u062f\u06cc\u0646 \u0645\u062d\u0627\u0641\u0638\u0647 \u06a9\u0627\u0631 \u0648 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0627\u0632 \u062f\u06cc\u06af\u0631 \u0639\u0644\u062a \u0647\u0627\u06cc \u0628\u0648\u062c\u0648\u062f \u0622\u0645\u062f\u0646 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc \u062f\u0631 \u0627\u0641\u0631\u0627\u062f\u060c \u0648\u0627\u0644\u062f\u06cc\u0646\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0628\u0627 \u0631\u0641\u062a\u0627\u0631 \u0647\u0627\u06cc \u0645\u062d\u0627\u0641\u0638\u0647 \u06a9\u0627\u0631\u0627\u0646\u0647 \u062e\u0648\u062f\u060c \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u0648 \u0646\u06af\u0631\u0627\u0646\u06cc \u0627\u0632 \u0648\u0642\u0648\u0639 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u0645\u062e\u0627\u0637\u0631\u0647 \u0622\u0645\u06cc\u0632 \u0648 \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u0646 \u0631\u0627 \u062f\u0631 \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u062e\u0648\u062f \u0646\u0647\u0627\u062f\u06cc\u0646\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0646\u062f. \u0648\u0627\u0644\u062f\u06cc\u0646 \u0628\u0627 \u0628\u0631\u0648\u0632 \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u0648 \u0627\u0636\u0637\u0631\u0627\u0628 \u062e\u0648\u062f \u0646\u0633\u0628\u062a \u0628\u0647 \u0648\u0642\u0627\u06cc\u0639\u060c \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u0646\u062f \u062a\u0627 \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u0646\u06cc\u0632 \u0628\u0627 \u0645\u0634\u0627\u0647\u062f\u0647 \u0622\u0646 \u0647\u0627 \u0627\u062d\u0633\u0627\u0633 \u0646\u06af\u0631\u0627\u0646\u06cc \u06a9\u0631\u062f\u0647 \u0648 \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637 \u062a\u0627 \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u06cc \u0622\u0646 \u0647\u0627 \u0646\u06cc\u0632 \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u0631 \u0628\u0627\u0634\u062f. \u0627\u06cc\u0646 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062f\u0627\u0626\u0645\u0627 \u062f\u0631\u06af\u06cc\u0631 \u0631\u0641\u062a\u0627\u0631 \u0647\u0627\u06cc \u0647\u0634\u062f\u0627\u0631 \u0622\u0645\u06cc\u0632 \u0648\u0627\u0644\u062f\u06cc\u0646 \u062e\u0648\u062f \u0628\u0648\u062f\u0647 \u0627\u0646\u062f.<\/span><\/p>\n<p><strong>\u062e\u0648\u0627\u0646\u062f\u0646 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0646\u062f\u0647\u06cc\u062f: <a href=\"https:\/\/ravandarman.com\/blog\/entitlement-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0633\u062a\u062d\u0642\u0627\u0642\u061b \u0639\u0644\u0627\u0626\u0645\u060c \u0639\u0644\u062a\u060c \u0627\u0646\u0648\u0627\u0639 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0628\u0632\u0631\u06af \u0645\u0646\u0634\u06cc<\/a><\/strong><\/p><\/blockquote>\n<h2><img decoding=\"async\" class=\"aligncenter wp-image-20144 size-full\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc.jpg\" alt=\"\u062a\u0644\u0647 \u06cc\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc\" width=\"1001\" height=\"645\" srcset=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc.jpg 1001w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc-300x193.jpg 300w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc-768x495.jpg 768w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc-585x377.jpg 585w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/h2>\n<blockquote>\n<h3><span class=\"ez-toc-section\" id=\"%D9%88%D8%A7%D9%84%D8%AF%DB%8C%D9%86_%D9%85%D8%AD%D8%AF%D9%88%D8%AF_%DA%A9%D9%86%D9%86%D8%AF%D9%87_%D9%88_%D8%AA%D9%84%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0648\u0627\u0644\u062f\u06cc\u0646 \u0645\u062d\u062f\u0648\u062f \u06a9\u0646\u0646\u062f\u0647 \u0648 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0648\u0627\u0644\u062f\u06cc\u0646\u06cc \u06a9\u0647 \u0628\u0627 \u0645\u062d\u062f\u0648\u062f \u06a9\u0631\u062f\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0648 \u0646\u06af\u0631\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647 \u06a9\u0648\u062f\u06a9\u060c \u0628\u0627\u0639\u062b \u0639\u062f\u0645 \u062a\u062c\u0631\u0628\u0647 \u0634\u06a9\u0633\u062a \u0648 \u0645\u0648\u0627\u062c\u0647\u0647 \u0628\u0627 \u0631\u0648\u06cc\u062f\u0627\u062f\u0647\u0627\u06cc \u0627\u0633\u062a\u0631\u0633 \u0622\u0645\u06cc\u0632 \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u062e\u0648\u062f \u0645\u06cc \u0634\u0648\u0646\u062f\u060c \u0632\u0645\u06cc\u0646\u0647 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0641\u0631\u0632\u0646\u062f\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0633\u0637\u062d\u06cc \u0627\u0632 \u0646\u06af\u0631\u0627\u0646\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u0646\u062f\u060c \u0628\u0627 \u0645\u062d\u0627\u0641\u0638\u062a \u0648 \u0627\u062c\u0631\u0627\u06cc \u0645\u062d\u062f\u0648\u062f\u06cc\u062a \u0647\u0627\u06cc \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0648\u0627\u0644\u062f\u06cc\u0646 \u062e\u0648\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062a\u0627 \u0632\u0645\u0627\u0646 \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u06cc \u062a\u062c\u0631\u0628\u0647 \u06af\u0630\u0631 \u0627\u0632 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u062e\u0637\u0631\u0646\u0627\u06a9 \u0648 \u0647\u0634\u062f\u0627\u0631 \u062f\u0647\u0646\u062f\u0647 \u0631\u0627 \u0628\u062f\u0633\u062a \u0646\u06cc\u0627\u0648\u0631\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0639\u062f \u0627\u0632 \u062f\u0648\u0631\u0627\u0646 \u06a9\u0648\u062f\u06a9\u06cc \u062f\u0627\u0626\u0645\u0627 \u0646\u06af\u0631\u0627\u0646 \u0648\u0642\u0648\u0639 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0645\u062e\u0627\u0637\u0631\u0647 \u0622\u0645\u06cc\u0632\u06cc \u0645\u0627\u0646\u0646\u062f \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u0633\u0644\u0627\u0645\u062a\u06cc\u060c \u062c\u0627\u0646 \u0648 \u0645\u0627\u0644 \u062e\u0648\u062f \u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0648\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B1%D9%81%D8%AA%D8%A7%D8%B1_%D9%87%D8%A7%DB%8C_%D8%A7%D8%BA%D8%B1%D8%A7%D9%82_%D8%A2%D9%85%DB%8C%D8%B2_%D9%88%D8%A7%D9%84%D8%AF%DB%8C%D9%86\"><\/span><span style=\"font-weight: 400;\">\u0631\u0641\u062a\u0627\u0631 \u0647\u0627\u06cc \u0627\u063a\u0631\u0627\u0642 \u0622\u0645\u06cc\u0632 \u0648\u0627\u0644\u062f\u06cc\u0646<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0648\u0627\u0644\u062f\u06cc\u0646\u06cc \u06a9\u0647 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062e\u0648\u062f \u0631\u0627 \u0646\u0647 \u062a\u0646\u0647\u0627 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc \u0646\u06a9\u0631\u062f\u0647\u060c \u0628\u0644\u06a9\u0647 \u0622\u0646 \u0647\u0627 \u0631\u0627 \u0627\u0632 \u0648\u0642\u0648\u0639 \u0627\u062a\u0641\u0627\u0642\u06cc \u0648\u062d\u0634\u062a\u0646\u0627\u06a9 \u0645\u06cc \u062a\u0631\u0633\u0627\u0646\u0646\u062f\u061b \u06a9\u0648\u062f\u06a9 \u0631\u0627 \u0622\u0645\u0627\u062f\u0647 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0641\u0627\u062c\u0639\u0647 \u0633\u0627\u0632\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0628\u0647 \u0637\u0648\u0631 \u0645\u062b\u0627\u0644 \u067e\u062f\u0631 \u0648 \u0645\u0627\u062f\u0631\u06cc \u06a9\u0647 \u0641\u0631\u0632\u0646\u062f \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u067e\u0627\u0631\u06a9 \u0628\u0631\u062f\u0647 \u0627\u0646\u062f \u0648 \u0628\u0647 \u062c\u0627\u06cc \u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc \u06a9\u0648\u062f\u06a9\u060c \u062f\u0631 \u0645\u0648\u0631\u062f \u0645\u062d\u0627\u0641\u0638\u062a \u0627\u0632 \u062e\u0648\u062f \u0647\u0646\u06af\u0627\u0645 \u0628\u0627\u0632\u06cc\u060c \u0627\u0648 \u0631\u0627 \u0627\u0632 \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u06af\u06cc \u0634\u062f\u06cc\u062f \u0648 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u062c\u062f\u06cc \u0633\u0644\u0627\u0645\u062a\u06cc\u060c \u0645\u06cc \u062a\u0631\u0633\u0627\u0646\u0646\u062f. \u0686\u0646\u06cc\u0646 \u06a9\u0648\u062f\u06a9\u06cc \u0627\u062d\u0633\u0627\u0633 \u062e\u0637\u0631 \u0634\u062f\u06cc\u062f \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0646\u06cc\u0627 \u0631\u0627 \u0645\u06a9\u0627\u0646\u06cc \u0646\u0627 \u0627\u0645\u0646 \u062f\u0631 \u0646\u0638\u0631 \u062e\u0648\u0627\u0647\u062f \u06af\u0631\u0641\u062a.<\/span><\/p>\n<p><strong>\u0645\u0637\u0644\u0628 \u062e\u0648\u0627\u0646\u062f\u0646\u06cc: <a href=\"https:\/\/ravandarman.com\/blog\/abandonment-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0631\u0647\u0627\u0634\u062f\u06af\u06cc \u0686\u06cc\u0633\u062a\u061f \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u060c \u0639\u0644\u062a \u0648 \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u062a\u0644\u0647 \u0631\u0647\u0627 \u0634\u062f\u06af\u06cc<\/a><\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%88%D9%82%D9%88%D8%B9_%D8%B1%D9%88%DB%8C%D8%AF%D8%A7%D8%AF_%D9%87%D8%A7%DB%8C_%D9%85%D8%AE%D8%A7%D8%B7%D8%B1%D9%87_%D8%A2%D9%85%DB%8C%D8%B2_%D9%88_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0648\u0642\u0648\u0639 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u0645\u062e\u0627\u0637\u0631\u0647 \u0622\u0645\u06cc\u0632 \u0648 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0637\u0648\u0644 \u0632\u0646\u062f\u06af\u06cc \u0648 \u0628\u0647 \u062e\u0635\u0648\u0635 \u062f\u0648\u0631\u0627\u0646 \u06a9\u0648\u062f\u06a9\u06cc \u062e\u0648\u062f\u060c \u0634\u0627\u0647\u062f \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0648\u062d\u0634\u062a\u0646\u0627\u06a9 \u0648 \u0627\u0633\u062a\u0631\u0633 \u0622\u0645\u06cc\u0632\u06cc \u0645\u0627\u0646\u0646\u062f \u0645\u0631\u06af \u06cc\u06a9\u06cc \u0627\u0632 \u0639\u0632\u06cc\u0632\u0627\u0646\u060c \u0645\u0627\u0646\u062f\u0646 \u0632\u06cc\u0631 \u0622\u0648\u0627\u0631 \u0632\u0644\u0632\u0644\u0647 \u0648 \u062a\u0635\u0627\u062f\u0641\u0627\u062a \u0631\u0627\u0646\u0646\u062f\u06af\u06cc \u0634\u062f\u06cc\u062f \u0628\u0648\u062f\u0647 \u0627\u0646\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0686\u0627\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06cc\u0627 \u0622\u0633\u06cc\u0628 \u0634\u0648\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc \u0627\u062c\u062a\u0646\u0627\u0628 \u0627\u0632 \u0648\u0642\u0648\u0639 \u062f\u0648\u0628\u0627\u0631\u0647 \u062d\u0648\u0627\u062f\u062b \u0648 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0646\u06af\u0631\u0627\u0646\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u0633\u0644\u0627\u0645\u062a\u06cc \u0648 \u06cc\u0627 \u0627\u0645\u0648\u0627\u0644 \u062e\u0648\u062f\u060c \u0627\u062d\u0633\u0627\u0633 \u0627\u0636\u0637\u0631\u0627\u0628 \u0634\u062f\u06cc\u062f\u06cc \u06a9\u0631\u062f\u0647 \u0648 \u0631\u0641\u062a\u0627\u0631 \u0647\u0627\u06cc \u0627\u062c\u062a\u0646\u0627\u0628\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f \u0648 \u062f\u0686\u0627\u0631 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0634\u0648\u0646\u062f.<\/span><\/p>\n<p><strong>\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0645\u0631\u062a\u0628\u0637: <a href=\"https:\/\/ravandarman.com\/blog\/isolation-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0646\u0632\u0648\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0686\u06cc\u0633\u062a\u061f \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u060c \u0639\u0644\u0644 \u0648 \u062f\u0631\u0645\u0627\u0646<\/a><\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%81%D8%B9%D8%A7%D9%84%DB%8C%D8%AA_%D8%A8%DB%8C%D8%B4_%D8%A7%D8%B2_%D8%AD%D8%AF_%D8%A2%D9%85%DB%8C%DA%AF%D8%AF%D8%A7%D9%84_%D9%88_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0641\u0639\u0627\u0644\u06cc\u062a \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0622\u0645\u06cc\u06af\u062f\u0627\u0644 \u0648 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0627\u0632 \u0639\u0644\u062a \u0647\u0627\u06cc \u0641\u06cc\u0632\u06cc\u0648\u0644\u0648\u0698\u06cc\u06a9 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc\u060c \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0622\u0645\u06cc\u06af\u062f\u0627\u0644 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0622\u0645\u06cc\u06af\u062f\u0627\u0644 \u0628\u062e\u0634\u06cc \u0627\u0632 \u0645\u063a\u0632 \u0627\u0633\u062a \u06a9\u0647 \u0645\u0633\u0626\u0648\u0644 \u067e\u0631\u062f\u0627\u0632\u0634 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u0627\u0633\u062a\u0631\u0633 \u0622\u0645\u06cc\u0632 \u0628\u0648\u062f\u0647 \u0648 \u0631\u0641\u062a\u0627\u0631 \u0627\u062c\u062a\u0646\u0627\u0628\u06cc \u06cc\u0627 \u062c\u0646\u06af \u0648 \u0641\u0631\u0627\u0631 \u0631\u0627 \u062f\u0631 \u0627\u0641\u0631\u0627\u062f \u06a9\u0646\u062a\u0631\u0644 \u0645\u06cc \u06a9\u0646\u062f. \u0622\u0645\u06cc\u06af\u062f\u0627\u0644 \u0628\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u0627\u0637\u0644\u0627\u0639\u0627\u062a\u06cc \u0645\u0628\u0646\u06cc \u0628\u0631 \u0648\u0642\u0648\u0639 \u06cc\u06a9 \u062d\u0627\u062f\u062b\u0647 \u06cc\u0627 \u0631\u0648\u06cc\u062f\u0627\u062f\u06cc \u0646\u06af\u0631\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647\u060c \u062f\u0633\u062a\u0648\u0631 \u0628\u0647 \u0641\u0631\u0627\u0631\u060c \u0627\u062c\u062a\u0646\u0627\u0628 \u0648 \u06cc\u0627 \u0631\u0648\u06cc\u0627\u0631\u0648\u06cc\u06cc \u0628\u0627 \u0634\u0631\u0627\u06cc\u0637 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0645\u06cc \u062f\u0647\u062f. \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u0632 \u062f\u0644\u0627\u06cc\u0644 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0627\u0641\u0631\u0627\u062f \u0641\u0639\u0627\u0644\u06cc\u062a \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0648 \u0627\u0641\u0631\u0627\u0637\u06cc \u0622\u0645\u06cc\u06af\u062f\u0627\u0644 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0622\u0646 \u0647\u0627 \u0631\u0627 \u062f\u0627\u0626\u0645\u0627 \u062f\u0631\u06af\u06cc\u0631 \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u0648 \u0627\u0636\u0637\u0631\u0627\u0628 \u0646\u06af\u0647 \u0645\u06cc \u062f\u0627\u0631\u062f.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D8%AF%D8%B1_%DA%A9%D9%88%D8%AF%DA%A9%D8%A7%D9%86\"><\/span><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u062f\u0631 \u06a9\u0648\u062f\u06a9\u0627\u0646<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u06a9\u0648\u062f\u06a9\u0627\u0646 \u062f\u0627\u0631\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a\u060c \u0628\u0647 \u0637\u0648\u0631 \u0627\u0641\u0631\u0627\u0637\u06cc \u0646\u06af\u0631\u0627\u0646 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0628\u062f \u0648 \u062e\u0637\u0631\u0646\u0627\u06a9 \u0647\u0633\u062a\u0646\u062f. \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u0648 \u0647\u06cc\u062c\u0627\u0646\u0627\u062a \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc\u060c \u0645\u0639\u0645\u0648\u0644\u0627 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0639\u062f\u0645 \u0627\u0628\u0631\u0627\u0632 \u0648 \u0641\u0631\u0648 \u062e\u0648\u0631\u062f\u0646 \u0627\u0636\u0637\u0631\u0627\u0628\u061b \u062a\u0634\u062f\u06cc\u062f \u0645\u06cc \u0634\u0648\u062f. \u0628\u0632\u0631\u06af\u0633\u0627\u0644\u0627\u0646 \u0646\u06cc\u0632 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u06a9\u0648\u062f\u06a9 \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u0641\u06a9\u0627\u0631 \u0648 \u0627\u062d\u0633\u0627\u0633 \u062e\u0648\u062f \u062f\u0631\u0628\u0627\u0631\u0647 \u062a\u0631\u0633 \u0627\u0632 \u062d\u0648\u0627\u062f\u062b \u0635\u062d\u0628\u062a \u0646\u06a9\u0646\u062f\u060c \u0645\u062a\u0648\u062c\u0647 \u0622\u0646 \u0646\u0634\u0648\u0646\u062f. \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0631\u0627\u06cc \u0631\u0647\u0627\u06cc\u06cc \u0627\u0632 \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u0648 \u0627\u0641\u06a9\u0627\u0631 \u0622\u0632\u0627\u0631 \u062f\u0647\u0646\u062f\u0647 \u062e\u0648\u062f \u0628\u0647 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0648\u0627\u0628\u0633\u062a\u06af\u06cc \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f\u060c \u0686\u0631\u0627 \u06a9\u0647 \u0641\u06a9\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0628\u0647 \u0627\u06cc\u0646 \u0634\u06a9\u0644 \u062f\u0631 \u0627\u0645\u0627\u0646 \u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0648\u062f. \u0631\u0648\u06cc\u0627\u0631\u0648\u06cc\u06cc \u0628\u0627 \u0627\u0641\u0631\u0627\u062f \u0632\u0648\u0631\u06af\u0648 \u0648 \u062a\u0647\u062f\u06cc\u062f \u06a9\u0646\u0646\u062f\u0647 \u062f\u0631 \u0647\u0645\u0633\u0627\u0644\u0627\u0646 \u06cc\u0627 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u060c \u062a\u0631\u0633 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0627\u062f\u0647 \u0648 \u062f\u0631 \u0635\u0648\u0631\u062a \u0639\u062f\u0645 \u062a\u0648\u062c\u0647 \u06a9\u0627\u0641\u06cc \u0628\u0647 \u06a9\u0648\u062f\u06a9 \u0628\u0627 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0622\u0646 \u0647\u0627 \u062f\u0686\u0627\u0631 \u0637\u0631\u062f \u0634\u062f\u0647 \u0648 \u0627\u062d\u0633\u0627\u0633 \u0645\u0646\u0632\u0648\u06cc \u0628\u0648\u062f\u0646 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f.<\/span><\/p>\n<p><strong>\u0628\u06cc\u0634\u062a\u0631 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f: <a href=\"https:\/\/ravandarman.com\/blog\/defectiveness-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0646\u0642\u0635 \u0648 \u0634\u0631\u0645 \u06cc\u0627 \u062a\u0644\u0647 \u0628\u06cc \u0627\u0631\u0632\u0634\u06cc \u0686\u06cc\u0633\u062a\u061f \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u060c \u0639\u0644\u0644 \u0648 \u062f\u0631\u0645\u0627\u0646<\/a><\/strong><\/p><\/blockquote>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20147 size-full\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc.jpg\" alt=\"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc\" width=\"1001\" height=\"645\" srcset=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc.jpg 1001w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-300x193.jpg 300w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-768x495.jpg 768w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-585x377.jpg 585w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/h2>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D8%AE%D8%AA%D9%84%D8%A7%D9%84%D8%A7%D8%AA_%D8%B1%D9%88%D8%A7%D9%86%DB%8C_%D9%87%D9%85%D8%B1%D8%A7%D9%87_%D8%A8%D8%A7_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8%E2%80%8C%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u0647\u0645\u0631\u0627\u0647 \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0647\u0633\u062a\u0647 \u0627\u0635\u0644\u06cc \u0648 \u06a9\u0627\u0646\u0648\u0646 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc\u060c \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633\u060c \u0646\u06af\u0631\u0627\u0646\u06cc \u0648 \u0627\u0636\u0637\u0631\u0627\u0628 \u0634\u062f\u06cc\u062f \u062f\u0631 \u0645\u0648\u0631\u062f \u0648\u0642\u0648\u0639 \u0631\u0648\u06cc\u062f\u0627\u062f\u06cc \u0642\u0631\u06cc\u0628 \u0627\u0644\u0648\u0642\u0648\u0639 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u0627\u062d\u062a\u0645\u0627\u0644 \u0645\u06cc \u062f\u0647\u0646\u062f\u060c \u0628\u0627\u0639\u062b \u0628\u0647 \u062e\u0637\u0631 \u0627\u0641\u062a\u0627\u062f\u0646 \u0633\u0644\u0627\u0645\u062a\u06cc\u060c \u0645\u0627\u0644 \u0648 \u062c\u0627\u0646 \u0622\u0646 \u0647\u0627 \u0645\u06cc \u0634\u0648\u062f. \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637 \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u062a\u0627 \u0628\u0631\u0627\u06cc \u0627\u062c\u062a\u0646\u0627\u0628 \u0627\u0632 \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u0646 \u0627\u0632 \u062d\u0636\u0648\u0631 \u062f\u0631 \u0628\u0639\u0636\u06cc \u062c\u0648\u0627\u0645\u0639\u060c \u0645\u062d\u06cc\u0637 \u0647\u0627 \u06cc\u0627 \u0627\u0646\u062c\u0627\u0645 \u0628\u0639\u0636\u06cc \u06a9\u0627\u0631 \u0647\u0627 \u0627\u062c\u062a\u0646\u0627\u0628 \u06a9\u0646\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u0632 \u062f\u0627\u0634\u062a\u0646 \u0627\u0641\u06a9\u0627\u0631 \u0622\u0632\u0627\u0631 \u062f\u0647\u0646\u062f\u0647 \u0627\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0648\u062d\u0634\u062a\u0646\u0627\u06a9 \u0627\u0628\u0631\u0627\u0632 \u0646\u06af\u0631\u0627\u0646\u06cc \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u062f\u0631 \u0628\u0639\u0636\u06cc \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc\u060c \u0645\u0634\u0627\u0647\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f. \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0631\u0648\u0627\u0646\u06cc \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0647\u0645\u0631\u0627\u0647 \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/generalized-anxiety-disorder\/\"><span style=\"font-weight: 400;\">\u0627\u062e\u062a\u0644\u0627\u0644 \u0627\u0636\u0637\u0631\u0627\u0628 \u0641\u0631\u0627\u06af\u06cc\u0631<\/span><\/a><span style=\"font-weight: 400;\"> (GAD)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/social-anxiety\/\"><span style=\"font-weight: 400;\">\u0627\u062e\u062a\u0644\u0627\u0644 \u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> (SAD)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/obsessive-compulsive-disorder\/\"><span style=\"font-weight: 400;\">\u0627\u062e\u062a\u0644\u0627\u0644 \u0648\u0633\u0648\u0627\u0633 \u0641\u06a9\u0631\u06cc \u0648 \u0639\u0645\u0644\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> (OCD)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/%D8%A7%D8%AE%D8%AA%D9%84%D8%A7%D9%84-%D9%BE%D8%A7%D9%86%DB%8C%DA%A9-%D9%88%D8%AD%D8%B4%D8%AA%D8%B2%D8%AF%DA%AF%DB%8C\/\"><span style=\"font-weight: 400;\">\u0627\u062e\u062a\u0644\u0627\u0644 \u067e\u0627\u0646\u06cc\u06a9<\/span><\/a><span style=\"font-weight: 400;\"> \u06cc\u0627 \u0648\u062d\u0634\u062a \u0632\u062f\u06af\u06cc<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/how-to-deal-with-phobia\/\"><span style=\"font-weight: 400;\">\u0627\u062e\u062a\u0644\u0627\u0644 \u0641\u0648\u0628\u06cc\u0627<\/span><\/a><span style=\"font-weight: 400;\"> \u06cc\u0627 \u0647\u0631\u0627\u0633 \u062e\u0627\u0635<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/agoraphobia\/\"><span style=\"font-weight: 400;\">\u0627\u062e\u062a\u0644\u0627\u0644 \u0622\u06af\u0648\u0631\u0627\u0641\u0648\u0628\u06cc\u0627<\/span><\/a><span style=\"font-weight: 400;\"> \u06cc\u0627 \u0628\u0627\u0632\u0627\u0631 \u0647\u0631\u0627\u0633\u06cc<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/posttraumatic-stress-disorder\/\"><span style=\"font-weight: 400;\">\u0627\u062e\u062a\u0644\u0627\u0644 \u0627\u0633\u062a\u0631\u0633 \u067e\u0633 \u0627\u0632 \u0633\u0627\u0646\u062d\u0647<\/span><\/a><span style=\"font-weight: 400;\"> (PTSD)<\/span><\/li>\n<\/ul>\n<p><strong>\u0645\u0637\u0627\u0644\u0639\u0647 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc \u0634\u0648\u062f: <a href=\"https:\/\/ravandarman.com\/blog\/emotional-deprivation-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0645\u062d\u0631\u0648\u0645\u06cc\u062a \u0647\u06cc\u062c\u0627\u0646\u06cc \u0686\u06cc\u0633\u062a\u061f \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u060c \u0639\u0644\u062a \u0648 \u062f\u0631\u0645\u0627\u0646<\/a><\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0627\u0646\u0648\u0627\u0639 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u062f\u0627\u0631\u0627\u06cc \u0627\u0646\u0648\u0627\u0639 \u0645\u062e\u062a\u0644\u0641\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u0641\u0631\u0627\u062f \u0631\u0627 \u062f\u0631\u06af\u06cc\u0631 \u06a9\u0646\u062f. \u0647\u0631\u06a9\u062f\u0627\u0645 \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0631 \u06cc\u06a9 \u0628\u062e\u0634 \u0627\u0632 \u0632\u0646\u062f\u06af\u06cc \u0641\u0631\u062f \u062a\u0645\u0631\u06a9\u0632 \u062f\u0627\u0631\u062f. \u0627\u0646\u0648\u0627\u0639 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0639\u0628\u0627\u0631\u062a \u0627\u0633\u062a \u0627\u0632:<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D9%86%D8%B3%D8%A8%D8%AA_%D8%A8%D9%87_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0628\u0639\u0636\u06cc \u0627\u0641\u0631\u0627\u062f \u062f\u0627\u0626\u0645\u0627 \u0646\u06af\u0631\u0627\u0646 \u0648\u0636\u0639\u06cc\u062a \u0633\u0644\u0627\u0645\u062a \u062c\u0633\u0645\u0627\u0646\u06cc \u0648 \u0634\u0631\u0627\u06cc\u0637 \u067e\u0632\u0634\u06a9\u06cc \u062e\u0648\u062f \u0647\u0633\u062a\u0646\u062f. \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0648 \u0633\u0644\u0627\u0645\u062a\u060c \u062a\u0631\u0633 \u0632\u06cc\u0627\u062f\u06cc \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631 \u0634\u062f\u0646 \u0648 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u0633\u0644\u0627\u0645\u062a\u06cc \u062e\u0648\u062f \u062f\u0627\u0631\u0646\u062f. \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0631\u0627\u06cc \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u06cc\u0627\u0641\u062a\u0646 \u0627\u0632 \u0648\u0636\u0639\u06cc\u062a \u0633\u0644\u0627\u0645\u062a\u06cc \u062c\u0633\u0645\u0627\u0646\u06cc \u062e\u0648\u062f \u0645\u06a9\u0631\u0631\u0627 \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0631\u062f\u0647\u060c \u06cc\u0627 \u0627\u0632 \u0627\u0646\u062c\u0627\u0645 \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u062d\u062a\u0645\u0627\u0644 \u0645\u06cc \u062f\u0647\u0646\u062f \u0633\u0644\u0627\u0645\u062a\u06cc\u0634\u0627\u0646 \u0631\u0627 \u0628\u0647 \u062e\u0637\u0631 \u0645\u06cc \u0627\u0646\u062f\u0627\u0632\u062f\u060c \u0627\u062c\u062a\u0646\u0627\u0628 \u06a9\u0646\u0646\u062f.<\/span><\/p>\n<p><strong>\u0633\u0627\u06cc\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0647\u0627: <a href=\"https:\/\/ravandarman.com\/blog\/enmeshment-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062e\u0648\u06cc\u0634\u062a\u0646 \u062a\u062d\u0648\u0644 \u0646\u06cc\u0627\u0641\u062a\u0647 \u0686\u06cc\u0633\u062a\u061f \u0639\u0644\u0627\u0626\u0645\u060c \u0639\u0644\u0644 \u0648 \u062f\u0631\u0645\u0627\u0646 \u062a\u0644\u0647 \u06af\u0631\u0641\u062a\u0627\u0631\u06cc<\/a><\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D9%88%D9%82%D9%88%D8%B9_%D8%AE%D8%B7%D8%B1\"><\/span><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648\u0642\u0648\u0639 \u062e\u0637\u0631<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0648\u0642\u0648\u0639 \u062e\u0637\u0631\u060c \u0627\u062d\u0633\u0627\u0633 \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u062f\u0646\u06cc\u0627 \u062c\u0627\u06cc \u062e\u0637\u0631\u0646\u0627\u06a9\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u06af\u0631 \u062f\u0627\u0626\u0645\u0627 \u0646\u06af\u0631\u0627\u0646 \u0648 \u0645\u0648\u0627\u0638\u0628 \u0646\u0628\u0627\u0634\u0646\u062f\u060c \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u062e\u0637\u0631\u0646\u0627\u06a9 \u0648 \u0645\u062e\u0627\u0637\u0631\u0647 \u0622\u0645\u06cc\u0632\u06cc \u0628\u0631\u0627\u06cc \u0622\u0646 \u0647\u0627 \u0631\u062e \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u062f. \u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u062f\u0627\u0626\u0645\u0627 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0628\u062f \u0641\u06a9\u0631 \u06a9\u0631\u062f\u0647 \u0648 \u0627\u062d\u0633\u0627\u0633 \u0627\u0636\u0637\u0631\u0627\u0628 \u0645\u06cc \u06a9\u0646\u0646\u062f.<\/span><\/p>\n<div class=\"custom-box-specialist\"><div class=\"content\"><strong>\u062c\u0647\u062a \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u0634\u0627\u0648\u0631\u0647 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc\u060c \u0631\u0648\u0627\u0646\u067e\u0632\u0634\u06a9\u06cc \u0648 \u0631\u0648\u0627\u0646\u06a9\u0627\u0648\u06cc \u0628\u0627 \u0645\u062c\u0631\u0628\u200c\u062a\u0631\u06cc\u0646 \u062f\u0631\u0645\u0627\u0646\u06af\u0631\u0627\u0646 \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u06cc\u062f:<\/strong>\r\n<ul>\r\n \t<li><a href=\"https:\/\/ravandarman.com\/psychologists\/1c-tehran\" target=\"_blank\" rel=\"noopener\"><strong>\u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u062e\u0648\u0628 \u062f\u0631 \u062a\u0647\u0631\u0627\u0646<\/strong><\/a><\/li>\r\n \t<li><a href=\"https:\/\/ravandarman.com\/psychologists\/2c-shiraz\" target=\"_blank\" rel=\"noopener\"><strong>\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u0634\u06cc\u0631\u0627\u0632\u00a0<\/strong><\/a><\/li>\r\n \t<li><a href=\"https:\/\/ravandarman.com\/psychologists\/13c-tabriz\" target=\"_blank\" rel=\"noopener\"><strong>\u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u062e\u0648\u0628 \u062f\u0631 \u062a\u0628\u0631\u06cc\u0632<\/strong><\/a><\/li>\r\n<\/ul>\r\n<strong>\u0628\u0631\u0627\u06cc \u0627\u0631\u062a\u0628\u0627\u0637 \u0648 \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u0634\u0627\u0648\u0631\u0647 \u0628\u0627 <a href=\"https:\/\/ravandarman.com\/psychologists\" target=\"_blank\" rel=\"noopener\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u0627\u0646<\/a> \u062f\u0631 \u062a\u0645\u0627\u0645 \u0646\u0642\u0627\u0637 \u0627\u06cc\u0631\u0627\u0646 \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f.<\/strong><\/div><img decoding=\"async\" class=\"img-box-spec\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2025\/07\/svg-spec.svg\"><\/div>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D8%A8%D9%87_%D8%B6%D8%B1%D8%B1_%D9%88_%D9%85%D8%A7%D9%84%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0645\u0627\u0644\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0627\u0632 \u0646\u0648\u0639 \u0641\u0642\u0631\u060c \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0632 \u0631\u0648\u06cc\u062f\u0627\u062f\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0631\u0627\u06cc \u0622\u0646\u0647\u0627 \u0627\u062a\u0641\u0627\u0642 \u0627\u0641\u062a\u0627\u062f\u0647 \u0648 \u0628\u0627\u0639\u062b \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u0645\u0627\u0644 \u0648 \u0627\u0645\u0648\u0627\u0644\u0634\u0627\u0646 \u0634\u0648\u062f\u061b \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u0634\u062f\u06cc\u062f\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u062d\u0627\u0644\u062a \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0631\u0627\u06cc \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u06cc\u06a9 \u0628\u0627\u0631 \u0627\u0645\u0648\u0627\u0644 \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0647 \u0648 \u06cc\u0627 \u062f\u0631 \u06af\u0630\u0634\u062a\u0647 \u0641\u0642\u0631 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0646\u062f \u0628\u06cc\u0634\u062a\u0631 \u0627\u062a\u0641\u0627\u0642 \u0628\u06cc \u0627\u0641\u062a\u062f. \u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u062d\u062a\u06cc \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u06a9\u0627\u0641\u06cc \u067e\u0648\u0644 \u062f\u0627\u0631\u0646\u062f \u0646\u06cc\u0632\u060c \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u062f\u0627\u0631\u0646\u062f.<\/span><\/p>\n<p><strong>\u0645\u0637\u0644\u0628 \u0645\u0631\u062a\u0628\u0637: <a href=\"https:\/\/ravandarman.com\/blog\/punitiveness-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062a\u0646\u0628\u06cc\u0647 \u0686\u06cc\u0633\u062a\u061f \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u060c \u0639\u0644\u0644 \u0648 \u062f\u0631\u0645\u0627\u0646 \u062a\u0644\u0647 \u062a\u0646\u0628\u06cc\u0647<\/a><\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%AF%D8%B3%D8%AA_%D8%AF%D8%A7%D8%AF%D9%86_%DA%A9%D9%86%D8%AA%D8%B1%D9%84\"><\/span><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u06a9\u0646\u062a\u0631\u0644<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u0628\u0647 \u0637\u0648\u0631 \u062f\u0627\u0626\u0645\u06cc \u0627\u062d\u0633\u0627\u0633 \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0647\u0631 \u0644\u062d\u0638\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06a9\u0646\u062a\u0631\u0644 \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0628\u062f\u0647\u0646\u062f. \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647 \u0686\u0646\u06cc\u0646 \u062d\u0627\u0644\u062a\u06cc \u0648 \u0628\u0631\u0627\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0648\u0642\u0648\u0639 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u062e\u0637\u0631\u0646\u0627\u06a9\u06cc \u06a9\u0647 \u0628\u0647 \u0630\u0647\u0646\u0634\u0627\u0646 \u0645\u06cc \u0631\u0633\u062f\u060c \u0627\u0632 \u062d\u0636\u0648\u0631 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0648\u0642\u0639\u06cc\u062a \u0647\u0627 \u0627\u062c\u062a\u0646\u0627\u0628 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u06cc\u0627 \u062a\u0644\u0647 \u0641\u0627\u062c\u0639\u0647 \u0633\u0627\u0632\u06cc\u060c \u0641\u06a9\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u06a9\u0646\u062a\u0631\u0644 \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0628\u062f\u0647\u0646\u062f\u061b \u0647\u0645\u0647 \u0686\u06cc\u0632 \u0628\u0647\u0645 \u0631\u06cc\u062e\u062a\u0647 \u0648 \u0634\u0631\u0627\u06cc\u0637\u06cc \u0648\u062d\u0634\u062a\u0646\u0627\u06a9\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u062e\u0648\u0627\u0647\u0646\u062f \u06a9\u0631\u062f.<\/span><\/p>\n<p><strong>\u0645\u0637\u0644\u0628 \u0645\u0641\u06cc\u062f: <a href=\"https:\/\/ravandarman.com\/blog\/self-sacrifice-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u06cc\u062b\u0627\u0631 \u0686\u06cc\u0633\u062a\u061f \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u06cc\u062b\u0627\u0631\u06af\u0631\u06cc \u0648 \u062f\u0631\u0645\u0627\u0646 \u0622\u0646<\/a><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20142 size-full\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc.jpg\" alt=\"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u06cc\u0627 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc\" width=\"1001\" height=\"645\" srcset=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc.jpg 1001w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-300x193.jpg 300w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-768x495.jpg 768w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-585x377.jpg 585w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D9%88_%D8%B1%D9%88%D8%A7%D8%A8%D8%B7_%D8%B9%D8%A7%D8%B7%D9%81%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0631\u0648\u0627\u0628\u0637 \u0639\u0627\u0637\u0641\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0641\u0631\u062f\u06cc \u06a9\u0647 \u062f\u0627\u0631\u0627\u06cc \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0627\u0633\u062a\u060c \u062f\u0631 \u0631\u0648\u0627\u0628\u0637 \u0639\u0627\u0637\u0641\u06cc \u062e\u0648\u062f \u0648 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0622\u0632\u0627\u0631 \u062f\u0647\u0646\u062f\u0647 \u0627\u062d\u0633\u0627\u0633 \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u0646 \u0627\u0632 \u0637\u0631\u0641 \u0645\u0642\u0627\u0628\u0644 \u06cc\u0627 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u0627\u0648 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f. \u0627\u062d\u0633\u0627\u0633 \u0627\u0632 \u0628\u06cc\u0646 \u0631\u0641\u062a\u0646 \u0639\u0634\u0642 \u0648 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0646 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0648\u060c \u0628\u0627\u0639\u062b \u0634\u06a9\u0644 \u06af\u06cc\u0631\u06cc \u0627\u062d\u0633\u0627\u0633 \u0627\u0636\u0637\u0631\u0627\u0628 \u0645\u06cc \u0634\u0648\u062f. \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc \u0628\u0631\u0627\u06cc \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u06cc\u0627\u0641\u062a\u0646 \u0627\u0632 \u0631\u0627\u0628\u0637\u0647 \u0639\u0627\u0637\u0641\u06cc \u062e\u0648\u062f\u060c \u062f\u0627\u0626\u0645\u0627 \u0627\u0632 \u0637\u0631\u0641 \u0645\u0642\u0627\u0628\u0644 \u0645\u06cc \u062e\u0648\u0627\u0647\u0646\u062f \u06a9\u0647 \u0639\u0634\u0642 \u0648 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0646 \u0631\u0627 \u0627\u0628\u0632\u0627\u0631 \u0648 \u0627\u062b\u0628\u0627\u062a \u06a9\u0646\u0646\u062f\u061b \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0628\u0627\u0639\u062b \u0628\u0647\u0645 \u0631\u06cc\u062e\u062a\u0646 \u0622\u0631\u0627\u0645\u0634 \u0631\u0648\u0627\u0646\u06cc \u062f\u06cc\u06af\u0631\u0627\u0646 \u0648 \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647 \u062f\u0648\u0631\u06cc \u0622\u0646\u0647\u0627 \u062e\u0648\u0627\u0647\u062f \u0634\u062f.<\/span><\/p>\n<p><strong>\u062c\u0647\u062a \u0645\u0637\u0627\u0644\u0639\u0647 \u0628\u06cc\u0634\u062a\u0631\u060c \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f: <a href=\"https:\/\/ravandarman.com\/blog\/subjugation-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0637\u0627\u0639\u062a \u0686\u06cc\u0633\u062a\u061f \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u060c \u0639\u0644\u0644 \u0648 \u0631\u0627\u0647 \u062f\u0631\u0645\u0627\u0646 \u062a\u0644\u0647 \u0627\u0637\u0627\u0639\u062a<\/a><\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AA%D9%84%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u062f\u0631\u0645\u0627\u0646 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647 \u062f\u0631\u0645\u0627\u0646 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc\u060c \u0645\u0631\u0627\u062c\u0639\u0647 \u0628\u0647 \u06cc\u06a9 <\/span><a href=\"https:\/\/pezeshkekhoob.com\/psychologists\"><span style=\"font-weight: 400;\">\u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633 \u062e\u0648\u0628<\/span><\/a><span style=\"font-weight: 400;\"> \u0648 \u0627\u0646\u062c\u0627\u0645 <\/span><a href=\"https:\/\/ravandarman.com\/blog\/psychotherapy\/\"><span style=\"font-weight: 400;\">\u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> \u0627\u0633\u062a. \u0627\u0632 \u0627\u0635\u0644\u06cc \u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc\u060c \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u06cc \u0648 \u062f\u0631\u0645\u0627\u0646 \u0634\u0646\u0627\u062e\u062a\u06cc \u0631\u0641\u062a\u0627\u0631\u06cc \u0627\u0633\u062a\u061b \u06a9\u0647 \u0639\u0628\u0627\u0631\u062a \u0627\u0646\u062f \u0627\u0632:<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%AF%D8%B1%D9%85%D8%A7%D9%86%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><a href=\"https:\/\/ravandarman.com\/blog\/%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87-%D8%AF%D8%B1%D9%85%D8%A7%D9%86%DB%8C-%D8%AA%D9%88%D8%B6%DB%8C%D8%AD%D8%A7%D8%AA-%D9%88-%D8%A7%D9%86%D9%88%D8%A7%D8%B9-%D8%B1%D9%88%D8%B4-%D9%87%D8%A7%DB%8C\/\"><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> (schema therapy)\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u0631\u0648\u0627\u0646\u062f\u0631\u0645\u0627\u0646\u06cc \u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0645\u0634\u06a9\u0644\u0627\u062a \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0622\u0646 \u062f\u0631\u0645\u0627\u0646 \u062e\u0648\u0627\u0647\u0646\u062f \u0634\u062f. \u0647\u062f\u0641 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc\u060c \u06a9\u0645\u06a9 \u0628\u0647 \u0627\u0641\u0631\u0627\u062f \u0627\u0633\u062a \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u0646\u062f:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0639\u0644\u062a \u062a\u0631\u0633\u06cc \u06a9\u0647 \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0631\u0648\u0632\u0645\u0631\u0647 \u062e\u0648\u062f \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0631\u0627 \u062f\u0631\u06a9 \u06a9\u0646\u0646\u062f<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0628\u062f\u0627\u0646\u0646\u062f \u06a9\u0647 \u062a\u0631\u0633 \u0648 \u0646\u06af\u0631\u0627\u0646\u06cc \u0622\u0646 \u0647\u0627 \u063a\u06cc\u0631 \u0645\u0646\u0637\u0642\u06cc \u0627\u0633\u062a<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u0641\u06a9\u0627\u0631 \u0646\u0627\u0633\u0627\u0644\u0645 \u0648 \u0628\u0627\u0648\u0631 \u0647\u0627\u06cc \u0645\u0634\u06a9\u0644 \u0622\u0641\u0631\u06cc\u0646 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0686\u0627\u0644\u0634 \u0628\u06a9\u0634\u0646\u062f<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0648\u0627\u0628\u0633\u062a\u06af\u06cc \u062e\u0648\u062f \u0628\u0647 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0647\u0646\u062f<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0628\u0627\u0648\u0631 \u0647\u0627\u06cc \u06a9\u0627\u0631\u0622\u0645\u062f \u0631\u0627 \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646 \u0627\u0641\u06a9\u0627\u0631 \u0646\u0627\u0633\u0627\u0644\u0645 \u062e\u0648\u062f \u06a9\u0646\u0646\u062f<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062a\u062c\u0631\u0628\u06cc\u0627\u062a \u0628\u062f \u0648 \u0622\u0633\u06cc\u0628 \u0632\u0627 \u06af\u0630\u0634\u062a\u0647 \u0631\u0627 \u0645\u062c\u062f\u062f\u0627 \u0648 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0633\u0627\u0644\u0645 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u0646\u062f<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0647\u06cc\u062c\u0627\u0646\u0627\u062a \u0645\u0646\u0641\u06cc \u062e\u0648\u062f \u0631\u0627 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0645\u0641\u06cc\u062f \u062a\u0631 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u0646\u062f<\/span><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B4%D9%86%D8%A7%D8%AE%D8%AA%DB%8C_%D8%B1%D9%81%D8%AA%D8%A7%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u062f\u0631\u0645\u0627\u0646 \u0634\u0646\u0627\u062e\u062a\u06cc \u0631\u0641\u062a\u0627\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f \u062f\u0627\u0631\u062f\u060c <\/span><a href=\"https:\/\/ravandarman.com\/blog\/cognitive-behavioral-therapy\/\"><span style=\"font-weight: 400;\">\u062f\u0631\u0645\u0627\u0646 \u0634\u0646\u0627\u062e\u062a\u06cc \u0631\u0641\u062a\u0627\u0631\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> (CBT)\u060c \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u062f\u0631\u0645\u0627\u0646\u06cc \u0628\u0627 \u0627\u0641\u06a9\u0627\u0631 \u0648 \u0628\u0627\u0648\u0631 \u0647\u0627\u06cc \u0646\u0627\u0633\u0627\u0644\u0645 \u0686\u0627\u0644\u0634 \u0634\u062f\u0647 \u0648 \u0633\u0639\u06cc \u0645\u06cc \u0634\u0648\u062f \u062a\u0627 \u0627\u0641\u0631\u0627\u062f \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0644\u06cc\u0644 \u0632\u06cc\u0631 \u0628\u0646\u0627\u06cc\u06cc \u0627\u0641\u06a9\u0627\u0631 \u063a\u06cc\u0631 \u0645\u0646\u0637\u0642\u06cc \u062e\u0648\u062f \u0631\u0627 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0631 \u062c\u0647\u062a \u0631\u0641\u062a\u0627\u0631 \u0647\u0627\u06cc \u0633\u0627\u0644\u0645 \u062a\u0631 \u0642\u062f\u0645 \u0628\u0631\u062f\u0627\u0631\u0646\u062f. \u0627\u0632 \u062a\u06a9\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0634\u0646\u0627\u062e\u062a\u06cc \u0631\u0641\u062a\u0627\u0631\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u062a\u06a9\u0646\u06cc\u06a9 \u062a\u0635\u0648\u06cc\u0631 \u0633\u0627\u0632\u06cc\u060c \u0686\u0627\u0644\u0634 \u0628\u0627 \u062e\u0637\u0627\u0647\u0627\u06cc \u0634\u0646\u0627\u062e\u062a\u06cc \u0648 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u0631\u0641\u062a\u0627\u0631 \u0647\u0627\u06cc \u0645\u0634\u06a9\u0644 \u0633\u0627\u0632\u060c \u0646\u0627\u0645 \u0628\u0631\u062f.<\/span><\/p>\n<p><strong>\u0628\u0631\u0627\u06cc \u0645\u0637\u0627\u0644\u0639\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f: <a href=\"https:\/\/ravandarman.com\/blog\/failure-schema\/\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0634\u06a9\u0633\u062a \u0686\u06cc\u0633\u062a\u061f \u0627\u0632 \u0646\u0634\u0627\u0646\u0647 \u0647\u0627 \u062a\u0627 \u062f\u0631\u0645\u0627\u0646 \u062a\u0644\u0647 \u0634\u06a9\u0633\u062a<\/a><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20141 size-full\" src=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u06cc\u0627-\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc.jpg\" alt=\"\u062a\u0644\u0647 \u06cc\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc\" width=\"1001\" height=\"645\" srcset=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u06cc\u0627-\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc.jpg 1001w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u06cc\u0627-\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc-300x193.jpg 300w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u06cc\u0627-\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc-768x495.jpg 768w, https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u062a\u0644\u0647-\u06cc\u0627-\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc-\u0646\u0633\u0628\u062a-\u0628\u0647-\u0636\u0631\u0631-\u06cc\u0627-\u0628\u06cc\u0645\u0627\u0631\u06cc-585x377.jpg 585w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%DA%A9%D9%86%D8%A7%D8%B1_%D8%A2%D9%85%D8%AF%D9%86_%D8%A8%D8%A7_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8%E2%80%8C%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u06a9\u0646\u0627\u0631 \u0622\u0645\u062f\u0646 \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0647 \u0631\u0641\u0639 \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633\u060c \u0646\u06af\u0631\u0627\u0646\u06cc \u0648 \u0627\u0636\u0637\u0631\u0627\u0628 \u0646\u0627\u0634\u06cc \u0627\u0632 \u0627\u0641\u06a9\u0627\u0631 \u0646\u0627\u0633\u0627\u0644\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u062e\u0637\u0631\u0646\u0627\u06a9 \u0648 \u063a\u06cc\u0631 \u0642\u0627\u0628\u0644 \u06a9\u0646\u062a\u0631\u0644 \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc\u060c \u0627\u0646\u062c\u0627\u0645 \u0631\u0627\u0647\u06a9\u0627\u0631 \u0647\u0627\u06cc \u0632\u06cc\u0631 \u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc \u0634\u0648\u062f:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0645\u062f\u06cc\u0631\u06cc\u062a \u0627\u0641\u06a9\u0627\u0631: \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u06a9\u0647 \u062f\u0642\u06cc\u0642\u0627 \u0686\u0647 \u0632\u0645\u0627\u0646\u06cc \u062f\u0631\u06af\u06cc\u0631 \u0627\u0641\u06a9\u0627\u0631 \u0622\u0632\u0627\u0631 \u062f\u0647\u0646\u062f\u0647 \u0645\u06cc \u0634\u0648\u06cc\u062f\u060c \u0622\u06af\u0627\u0647\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0647 \u0648 \u0627\u0641\u06a9\u0627\u0631 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0637\u0648\u0644 \u0631\u0648\u0632 \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/%D9%85%D8%A7%DB%8C%D9%86%D8%AF%D9%81%D9%88%D9%84%D9%86%D8%B3\/\"><span style=\"font-weight: 400;\">\u0645\u0627\u06cc\u0646\u062f \u0641\u0648\u0644\u0646\u0633<\/span><\/a><span style=\"font-weight: 400;\"> \u06cc\u0627 \u0630\u0647\u0646 \u0622\u06af\u0627\u0647\u06cc: \u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0622\u0646\u0686\u0647 \u062f\u0631 \u0644\u062d\u0638\u0647 \u062d\u0627\u0644\u060c \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc \u06a9\u0646\u06cc\u062f \u0631\u0627 \u062a\u0645\u0631\u06cc\u0646 \u06a9\u0646\u06cc\u062f\u060c \u062a\u0627 \u0646\u0633\u0628\u062a \u0628\u0647 \u0622\u0646\u0686\u0647 \u06a9\u0647 \u062f\u0631 \u062d\u0627\u0644 \u06af\u0630\u0631 \u062f\u0631 \u062c\u0633\u0645 \u0648 \u0631\u0648\u0627\u0646 \u0627\u0633\u062a\u061b \u0622\u06af\u0627\u0647 \u0634\u0648\u06cc\u062f \u0648 \u0627\u0632 \u0646\u06a9\u0627\u062a \u0645\u0646\u0641\u06cc \u062f\u0648\u0631\u06cc \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0622\u0631\u0627\u0645\u0634 \u0628\u062e\u0634\u06cc: \u0647\u0646\u06af\u0627\u0645 \u0628\u0631\u0648\u0632 \u0627\u0641\u06a9\u0627\u0631 \u0645\u0646\u0641\u06cc\u060c \u0631\u06cc\u0644\u06a9\u0633\u06cc\u0634\u0646 \u0648 \u0622\u0631\u0627\u0645 \u0633\u0627\u0632\u06cc \u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f. \u0628\u0627 \u0627\u0646\u062c\u0627\u0645 \u062a\u06a9\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u0622\u0631\u0627\u0645\u0634 \u0628\u062e\u0634\u06cc\u060c \u062a\u0648\u0627\u0646 \u0645\u0642\u0627\u0628\u0644\u0647 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0634\u0631\u0627\u06cc\u0637 \u0627\u0633\u062a\u0631\u0633 \u0622\u0645\u06cc\u0632 \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc \u0634\u0648\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0686\u0627\u0644\u0634 \u0627\u0641\u06a9\u0627\u0631 \u063a\u06cc\u0631 \u0645\u0646\u0637\u0642\u06cc: \u0645\u0646\u0637\u0642 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0628\u0627\u0648\u0631 \u0647\u0627 \u0648 \u0627\u0641\u06a9\u0627\u0631 \u0646\u0627\u0645\u0639\u0642\u0648\u0644 \u0628\u0647 \u06a9\u0627\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f \u0648 \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0627\u0647 \u0628\u0627 \u0627\u0641\u06a9\u0627\u0631 \u063a\u06cc\u0631 \u0645\u0646\u0637\u0642\u06cc \u06a9\u0647 \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0636\u0637\u0631\u0627\u0628 \u0645\u06cc \u0634\u0648\u0646\u062f\u060c \u0686\u0627\u0644\u0634 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062a\u0648\u062c\u0647 \u0628\u0647 \u0634\u0648\u0627\u0647\u062f \u0645\u062e\u0627\u0644\u0641: \u0633\u0639\u06cc \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0634\u0648\u0627\u0647\u062f\u06cc \u062e\u0644\u0627\u0641 \u0627\u0641\u06a9\u0627\u0631 \u062e\u0648\u062f \u067e\u06cc\u062f\u0627 \u06a9\u0646\u06cc\u062f\u060c \u062a\u0627 \u062f\u0631\u06af\u06cc\u0631 \u0627\u0641\u06a9\u0627\u0631 \u0646\u06af\u0631\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647 \u062f\u0631 \u0645\u0648\u0631\u062f \u063a\u06cc\u0631 \u0627\u062c\u062a\u0646\u0627\u0628 \u0628\u0648\u062f\u0646 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627 \u0646\u0634\u0648\u06cc\u062f. \u062a\u0648\u062c\u0647 \u0628\u0647 \u0634\u0648\u0627\u0647\u062f \u0645\u062e\u0627\u0644\u0641\u060c \u0627\u0633\u062a\u0631\u0633 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc \u062f\u0647\u062f.<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B3%D8%A8%DA%A9_%D9%87%D8%A7%DB%8C_%D9%85%D9%82%D8%A7%D8%A8%D9%84%D9%87_%D8%A8%D8%A7_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0633\u0628\u06a9 \u0647\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u062a\u0627 \u0627\u0641\u0631\u0627\u062f \u0646\u062a\u0648\u0627\u0646\u0646\u062f \u0632\u0646\u062f\u06af\u06cc \u0631\u0648\u0632\u0645\u0631\u0647 \u062e\u0648\u062f \u0631\u0627 \u0628\u0627 \u0627\u062d\u0633\u0627\u0633 \u0622\u0631\u0627\u0645\u0634 \u0628\u06af\u0630\u0631\u0627\u0646\u0646\u062f\u060c \u0686\u0631\u0627 \u06a9\u0647 \u062f\u0627\u0626\u0645\u0627 \u062f\u0631\u06af\u06cc\u0631 \u0627\u062d\u0633\u0627\u0633 \u062a\u0631\u0633 \u0648 \u0627\u0636\u0637\u0631\u0627\u0628 \u0647\u0633\u062a\u0646\u062f. \u0627\u0641\u0631\u0627\u062f \u0628\u0631\u0627\u06cc \u06a9\u0646\u0627\u0631 \u0622\u0645\u062f\u0646 \u0628\u0627 \u0645\u0634\u06a9\u0644 \u062e\u0648\u062f \u0645\u0639\u0645\u0648\u0644\u0627 \u0628\u0647 \u0633\u0647 \u0634\u06cc\u0648\u0647 \u0631\u0641\u062a\u0627\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0631\u0648\u0634 \u0647\u0627\u06cc \u06a9\u0646\u0627\u0631 \u0622\u0645\u062f\u0646 \u0628\u0627 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0639\u0628\u0627\u0631\u062a \u0627\u0633\u062a \u0627\u0632:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u062c\u062a\u0646\u0627\u0628<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062c\u0628\u0631\u0627\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062a\u0633\u0644\u06cc\u0645<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u0627\u062c\u062a\u0646\u0627\u0628: \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u06a9\u0627\u0647\u0634 \u0627\u0636\u0637\u0631\u0627\u0628 \u062e\u0648\u062f\u060c \u062f\u0633\u062a \u0628\u0647 \u0631\u0641\u062a\u0627\u0631 \u0647\u0627\u06cc \u0627\u062c\u062a\u0646\u0627\u0628\u06cc \u0628\u0632\u0646\u0646\u062f. \u062f\u0631 \u0686\u0646\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637\u06cc\u060c \u0627\u0632 \u062d\u0636\u0648\u0631 \u062f\u0631 \u0645\u0648\u0642\u0639\u06cc\u062a \u0647\u0627 \u06cc\u0627 \u0627\u0632 \u0631\u0648\u06cc\u0627\u0631\u0648 \u0634\u062f\u0646 \u0628\u0627 \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0627\u062d\u0633\u0627\u0633 \u0648\u0642\u0648\u0639 \u062e\u0637\u0631 \u062f\u0631 \u0622\u0646 \u0647\u0627 \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u062f\u061b \u0627\u062c\u062a\u0646\u0627\u0628 \u0648 \u062f\u0648\u0631\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u062c\u0628\u0631\u0627\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f: \u062f\u0631 \u0627\u06cc\u0646 \u062d\u0627\u0644\u062a\u060c \u0627\u0641\u0631\u0627\u062f \u0628\u0647 \u062c\u0627\u06cc \u0627\u062c\u062a\u0646\u0627\u0628 \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0648 \u0645\u0648\u0642\u0639\u06cc\u062a \u0647\u0627\u060c \u062f\u0633\u062a \u0628\u0647 \u0627\u0646\u062c\u0627\u0645 \u06a9\u0627\u0631\u0647\u0627\u06cc\u06cc \u0645\u06cc \u0632\u0646\u0646\u062f \u06a9\u0647 \u0628\u0631 \u062e\u0644\u0627\u0641 \u0627\u0641\u06a9\u0627\u0631 \u0648 \u0628\u0627\u0648\u0631 \u0647\u0627\u06cc \u0622\u0646 \u0647\u0627 \u0645\u0628\u0646\u06cc \u0628\u0631 \u0648\u0642\u0648\u0639 \u0622\u0633\u06cc\u0628 \u0627\u0633\u062a. \u0645\u0627\u0646\u0646\u062f \u0641\u0631\u062f\u06cc \u06a9\u0647 \u0628\u0627 \u0648\u062c\u0648\u062f \u062a\u0631\u0633 \u062e\u0648\u062f \u0645\u0628\u0646\u06cc \u0628\u0631 \u0648\u0642\u0648\u0639 \u0631\u062e\u062f\u0627\u062f \u0647\u0627\u06cc \u062e\u0637\u0631\u0646\u0627\u06a9\u060c \u0645\u0633\u0627\u0641\u0631\u062a \u0645\u06cc \u06a9\u0646\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u062a\u0633\u0644\u06cc\u0645: \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0627\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc\u060c \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0628\u0627\u0648\u0631 \u0646\u0627\u0633\u0627\u0644\u0645 \u062e\u0648\u062f \u0645\u0628\u0646\u06cc \u0628\u0631 \u062e\u0637\u0631\u0646\u0627\u06a9 \u0628\u0648\u062f\u0646 \u062f\u0646\u06cc\u0627 \u0648 \u0648\u0642\u0648\u0639 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u0622\u0633\u06cc\u0628 \u0632\u0627\u060c \u062a\u0633\u0644\u06cc\u0645 \u0645\u06cc \u0634\u0648\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u06cc\u0634 \u0627\u0632 \u067e\u06cc\u0634 \u0627\u062d\u0633\u0627\u0633 \u0627\u0636\u0637\u0631\u0627\u0628 \u0646\u0627\u0634\u06cc \u0627\u0632 \u0648\u0642\u0648\u0639 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0628\u062f \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u0646\u062f.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B9%D9%88%D8%A7%D8%B1%D8%B6_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C\"><\/span><span style=\"font-weight: 400;\">\u0639\u0648\u0627\u0631\u0636 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0627\u0632 \u0622\u0646 \u062c\u0627 \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u062f\u0627\u0626\u0645\u0627 \u062f\u0631\u06af\u06cc\u0631 \u0645\u0634\u06a9\u0644\u0627\u062a \u0627\u0636\u0637\u0631\u0627\u0628\u06cc \u0648 \u0627\u062d\u0633\u0627\u0633 \u0646\u06af\u0631\u0627\u0646\u06cc \u062e\u0648\u062f \u0647\u0633\u062a\u0646\u062f\u060c \u0645\u0645\u06a9\u0646 \u062f\u0686\u0627\u0631 \u0645\u0634\u06a9\u0644\u0627\u062a \u0628\u0633\u06cc\u0627\u0631\u06cc \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0634\u0648\u0646\u062f. \u0627\u0632 \u0639\u0648\u0627\u0631\u0636 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0646\u0627\u062a\u0648\u0627\u0646\u06cc \u062f\u0631 \u062a\u0641\u0631\u06cc\u062d \u0648 \u0633\u067e\u0631\u06cc \u06a9\u0631\u062f\u0646 \u0627\u0648\u0642\u0627\u062a \u0641\u0631\u0627\u063a\u062a<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0627\u0634\u062a\u0646 \u0627\u0641\u06a9\u0627\u0631 \u0634\u06a9 \u0648 \u062a\u0631\u062f\u06cc\u062f \u0646\u0633\u0628\u062a \u0628\u0647 \u0622\u06cc\u0646\u062f\u0647<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0639\u062f\u0645 \u062d\u0636\u0648\u0631 \u062f\u0631 \u0628\u0639\u0636\u06cc \u0634\u0631\u0627\u06cc\u0637 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062a\u0631\u0633 \u0627\u0632 \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u06af\u06cc<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0627\u0634\u062a\u0646 \u0645\u0634\u06a9\u0644 \u0647\u0646\u06af\u0627\u0645 \u0627\u0646\u062c\u0627\u0645 \u06a9\u0627\u0631 \u0647\u0627\u06cc \u06af\u0631\u0648\u0647\u06cc<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0645\u0634\u06a9\u0644 \u062f\u0631 \u0631\u0648\u0627\u0628\u0637 \u0632\u0646\u0627\u0634\u0648\u06cc\u06cc \u0648 \u0639\u0627\u0637\u0641\u06cc\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062a\u0631\u0633 \u0634\u062f\u06cc\u062f<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0645\u0631\u0627\u062c\u0639\u0647 \u0686\u0646\u062f\u06cc\u0646 \u0628\u0627\u0631\u0647 \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0628\u0631\u0627\u06cc \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0627\u0632 \u0633\u0644\u0627\u0645\u062a \u062e\u0648\u062f<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0641\u0627\u062c\u0639\u0647 \u0633\u0627\u0632\u06cc \u0627\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a \u06a9\u0648\u0686\u06a9 \u0648 \u0627\u06cc\u062c\u0627\u062f \u0646\u0627\u0631\u0627\u062d\u062a\u06cc \u0628\u0631\u0627\u06cc \u062f\u06cc\u06af\u0631\u0627\u0646<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0648\u0631\u06cc \u0627\u0632 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0648 \u062f\u0648\u0633\u062a\u0627\u0646 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0647\u0645\u0631\u0627\u0647 \u0646\u0628\u0648\u062f\u0646 \u0628\u0627 \u0622\u0646 \u0647\u0627 \u062f\u0631 \u0627\u06a9\u062b\u0631 \u0645\u0648\u0642\u0639\u06cc\u062a \u0647\u0627 \u0645\u0627\u0646\u0646\u062f \u0633\u0641\u0631<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0627\u0634\u062a\u0646 \u0633\u0637\u062d \u0627\u0633\u062a\u0631\u0633 \u0648 \u0627\u0636\u0637\u0631\u0627\u0628 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u062d\u0633\u0627\u0633 \u0637\u0631\u062f \u0648 \u0627\u0646\u0632\u0648\u0627<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A2%D9%86%DA%86%D9%87_%D8%A7%D8%B2_%D8%B7%D8%B1%D8%AD%D9%88%D8%A7%D8%B1%D9%87_%D8%A2%D8%B3%DB%8C%D8%A8_%D9%BE%D8%B0%DB%8C%D8%B1%DB%8C_%D8%A2%D9%85%D9%88%D8%AE%D8%AA%DB%8C%D9%85\"><\/span><span style=\"font-weight: 400;\">\u0622\u0646\u0686\u0647 \u0627\u0632 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0622\u0645\u0648\u062e\u062a\u06cc\u0645<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u062f\u0631 \u0627\u06cc\u0646 \u0648\u0628\u0644\u0627\u06af \u0627\u0632 \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646 \u0628\u0647 \u0627\u06cc\u0646 \u067e\u0631\u062f\u0627\u062e\u062a\u06cc\u0645 \u06a9\u0647 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f <\/span><span style=\"font-weight: 400;\">\u0627\u0641\u0631\u0627\u062f \u062f\u0631\u06af\u06cc\u0631 \u0627\u06cc\u0646 \u062a\u0644\u0647 \u062f\u0627\u0626\u0645\u0627 \u0646\u0633\u0628\u062a \u0628\u0647 \u0648\u0642\u0648\u0639 \u06cc\u06a9 \u062d\u0627\u062f\u062b\u0647 \u062e\u0637\u0631\u0646\u0627\u06a9 \u0648 \u0641\u0627\u062c\u0639\u0647 \u0622\u0645\u06cc\u0632\u060c \u0627\u062d\u0633\u0627\u0633 \u062a\u0646\u0634 \u0648 \u0627\u0636\u0637\u0631\u0627\u0628 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0627\u0641\u0631\u0627\u062f \u062f\u0627\u0631\u0627\u06cc \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u06cc \u06cc\u0627 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062a\u0631\u0633 \u0627\u0632 \u0636\u0631\u0631 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u0639\u0645\u0648\u0644\u0627 \u0628\u0647 \u0628\u062f\u062a\u0631\u06cc\u0646 \u0631\u0648\u06cc\u062f\u0627\u062f \u0647\u0627\u06cc \u0645\u0645\u06a9\u0646 \u0641\u06a9\u0631 \u06a9\u0631\u062f\u0647 \u0648 \u0628\u062f\u062a\u0631\u06cc\u0646 \u0633\u0646\u0627\u0631\u06cc\u0648 \u0647\u0627\u06cc \u0630\u0647\u0646\u06cc \u0631\u0627 \u0645\u06cc \u0633\u0627\u0632\u0646\u062f \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0647\u06cc\u0686 \u0648\u0642\u062a \u0628\u0647 \u0648\u0627\u0642\u0639\u06cc\u062a \u0646\u067e\u06cc\u0648\u0646\u062f\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0647 \u0627\u06cc\u0646 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f\u06cc\u0645 \u06a9\u0647 \u0639\u0644\u0644 \u0645\u0648\u062b\u0631 \u062f\u0631 \u0634\u06a9\u0644 \u06af\u0631\u0641\u062a\u0646 \u0627\u06cc\u0646 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0686\u0647 \u0647\u0633\u062a\u0646\u062f \u0627\u0632 \u062c\u0645\u0644\u0647 \u0631\u0648\u06cc\u062f\u0627\u062f\u0647\u0627\u06cc \u062a\u0631\u0648\u0645\u0627\u062a\u06cc\u06a9 \u06a9\u0648\u062f\u06a9\u06cc\u060c \u062a\u062c\u0631\u0628\u0647 \u062e\u0637\u0631 \u0648 \u0628\u0632\u0631\u06af\u200c\u0646\u0645\u0627\u06cc\u06cc \u062a\u0631\u0633 \u062a\u0648\u0633\u0637 \u0648\u0627\u0644\u062f\u06cc\u0646. \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0646\u06cc\u0632 \u0628\u0647 \u0628\u0631\u062e\u06cc \u067e\u06cc\u0627\u0645\u062f\u0647\u0627\u06cc \u0627\u06cc\u0646 \u062a\u0644\u0647 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0622\u0646 \u0628\u0648\u06cc\u0698\u0647 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062a\u0631\u0627\u067e\u06cc\u0633\u062a \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0633\u06cc\u0631 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f\u06cc\u0645.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0633\u0627\u06cc\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0647\u0627<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/unrelenting-standards-schema\/\"><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0645\u0639\u06cc\u0627\u0631\u0647\u0627\u06cc \u0633\u062e\u062a\u06af\u06cc\u0631\u0627\u0646\u0647 \u0686\u06cc\u0633\u062a\u061f \u0627\u0632 \u0646\u0634\u0627\u0646\u0647 \u0647\u0627 \u062a\u0627 \u062f\u0631\u0645\u0627\u0646<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/mistrust-schema\/\"><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0628\u06cc \u0627\u0639\u062a\u0645\u0627\u062f\u06cc \u0686\u06cc\u0633\u062a\u061f \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u060c \u0639\u0644\u062a \u0648 \u062f\u0631\u0645\u0627\u0646<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/insufficient-self-control-schema\/\"><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062e\u0648\u06cc\u0634\u062a\u0646 \u062f\u0627\u0631\u06cc \u0646\u0627\u06a9\u0627\u0641\u06cc \u0686\u06cc\u0633\u062a\u061f \u0646\u0634\u0627\u0646\u0647 \u0647\u0627\u060c\u0639\u0644\u062a \u0648 \u062f\u0631\u0645\u0627\u0646<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/approval-seeking-schema\/\"><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u062a\u0627\u06cc\u06cc\u062f \u0637\u0644\u0628\u06cc \u06cc\u0627 \u067e\u0630\u06cc\u0631\u0634 \u062c\u0648\u06cc\u06cc \u0686\u06cc\u0633\u062a\u061f \u0627\u0632 \u0646\u0634\u0627\u0646\u0647 \u0647\u0627 \u062a\u0627 \u062f\u0631\u0645\u0627\u0646<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/ravandarman.com\/blog\/negativity-pessimism-schema\/\"><span style=\"font-weight: 400;\">\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0645\u0646\u0641\u06cc \u06af\u0631\u0627\u06cc\u06cc \u0648 \u0628\u062f\u0628\u06cc\u0646\u06cc \u0686\u06cc\u0633\u062a\u061f \u0639\u0644\u0627\u0626\u0645\u060c \u0639\u0644\u0644\u060c \u067e\u06cc\u0627\u0645\u062f\u0647\u0627 \u0648 \u062f\u0631\u0645\u0627\u0646<\/span><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u062d\u0633\u0627\u0633 \u0646\u06af\u0631\u0627\u0646\u06cc \u0627\u0632 \u0648\u0642\u0648\u0639 \u06cc\u06a9 \u0627\u062a\u0641\u0627\u0642 \u0628\u062f \u0648 \u0627\u0633\u062a\u0631\u0633 \u0646\u0627\u0634\u06cc \u0627\u0632 \u0622\u0646\u060c \u062f\u0631 \u0628\u0639\u0636\u06cc \u0645\u0648\u0627\u0642\u0639 \u0637\u0628\u06cc\u0639\u06cc \u0648 \u0644\u0627\u0632\u0645 \u0627\u0633\u062a. \u0627\u0641\u0631\u0627\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0637\u0648\u0644 \u0632\u0646\u062f\u06af\u06cc \u062f\u0631\u0628\u0627\u0631\u0647 \u0633\u0644\u0627\u0645\u062a\u06cc\u060c \u0631\u0641\u0627\u0647 \u0648 \u0634\u0631\u0627\u06cc\u0637 \u062e\u0648\u062f\u060c \u0627\u062d\u0633\u0627\u0633 \u0646\u06af\u0631\u0627\u0646\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0627\u062a\u0641\u0627\u0642\u0627\u062a \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0648 \u062e\u0637\u0631\u0646\u0627\u06a9\u060c \u062f\u0633\u062a \u0628\u0647 \u0627\u0642\u062f\u0627\u0645\u0627\u062a\u06cc \u0628\u0632\u0646\u0646\u062f. \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u062a\u0642\u0631\u06cc\u0628\u0627 [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":20151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[758,128,730],"paper-cat":[],"class_list":["post-20139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-psychology","tag-758","tag-128","tag-730"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.1 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc - \u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646<\/title>\n<meta name=\"description\" content=\"\u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u062a\u0642\u0631\u0628\u06cc\u0627 \u062f\u0631 \u0647\u0645\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0648 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc\u060c \u0627\u062d\u0633\u0627\u0633 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0635\u062f\u0645\u0647 \u062f\u06cc\u062f\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u062f\u0631\u06af\u06cc\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0634\u062f\u0647 \u0627\u0646\u062f.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc\" \/>\n<meta property=\"og:description\" content=\"\u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u062a\u0642\u0631\u0628\u06cc\u0627 \u062f\u0631 \u0647\u0645\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0648 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc\u060c \u0627\u062d\u0633\u0627\u0633 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0635\u062f\u0645\u0647 \u062f\u06cc\u062f\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u062f\u0631\u06af\u06cc\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0634\u062f\u0647 \u0627\u0646\u062f.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pezeshkekhoob\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-09T16:37:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-07T11:43:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1001\" \/>\n\t<meta property=\"og:image:height\" content=\"645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u062a\u06cc\u0645 \u0645\u062d\u062a\u0648\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pezeshkekhoob\" \/>\n<meta name=\"twitter:site\" content=\"@pezeshkekhoob\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u062a\u06cc\u0645 \u0645\u062d\u062a\u0648\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/\"},\"author\":{\"name\":\"\u062a\u06cc\u0645 \u0645\u062d\u062a\u0648\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/6becaf60321027bf633ccc2a7612b0f0\"},\"headline\":\"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc\",\"datePublished\":\"2024-02-09T16:37:27+00:00\",\"dateModified\":\"2025-12-07T11:43:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/\"},\"wordCount\":12,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc2.jpg\",\"keywords\":[\"\u062f\u0631\u0645\u0627\u0646 \u0631\u0641\u062a\u0627\u0631\u06cc \u0634\u0646\u0627\u062e\u062a\u06cc\",\"\u0637\u0631\u062d\u0648\u0627\u0631\u0647\u200c\u062f\u0631\u0645\u0627\u0646\u06cc\",\"\u0637\u0631\u062d\u0648\u0627\u0631\u0647\u200c\u0647\u0627\"],\"articleSection\":[\"\u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/\",\"url\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/\",\"name\":\"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc - \u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646\",\"isPartOf\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc2.jpg\",\"datePublished\":\"2024-02-09T16:37:27+00:00\",\"dateModified\":\"2025-12-07T11:43:16+00:00\",\"description\":\"\u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u062a\u0642\u0631\u0628\u06cc\u0627 \u062f\u0631 \u0647\u0645\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0648 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc\u060c \u0627\u062d\u0633\u0627\u0633 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0635\u062f\u0645\u0647 \u062f\u06cc\u062f\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u062f\u0631\u06af\u06cc\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0634\u062f\u0647 \u0627\u0646\u062f.\",\"breadcrumb\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#primaryimage\",\"url\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc2.jpg\",\"contentUrl\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc2.jpg\",\"width\":1001,\"height\":645,\"caption\":\"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0635\u0641\u062d\u0647 \u0627\u0635\u0644\u06cc\",\"item\":\"https:\/\/ravandarman.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#website\",\"url\":\"https:\/\/ravandarman.com\/blog\/\",\"name\":\"\u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646\",\"description\":\"| \u0645\u0637\u0627\u0644\u0628\u06cc \u0645\u0641\u06cc\u062f \u0628\u0631\u0627\u06cc \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u0634\u0645\u0627\",\"publisher\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ravandarman.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#organization\",\"name\":\"Pezeshkekhoob\",\"url\":\"https:\/\/ravandarman.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2025\/04\/logoo.png\",\"contentUrl\":\"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2025\/04\/logoo.png\",\"width\":197,\"height\":70,\"caption\":\"Pezeshkekhoob\"},\"image\":{\"@id\":\"https:\/\/ravandarman.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pezeshkekhoob\",\"https:\/\/x.com\/pezeshkekhoob\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/6becaf60321027bf633ccc2a7612b0f0\",\"name\":\"\u062a\u06cc\u0645 \u0645\u062d\u062a\u0648\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f98703e4f7570a32d0769f6a229d28103ec6dc497fc34d8aa8bf04b0bbc91288?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f98703e4f7570a32d0769f6a229d28103ec6dc497fc34d8aa8bf04b0bbc91288?s=96&d=mm&r=g\",\"caption\":\"\u062a\u06cc\u0645 \u0645\u062d\u062a\u0648\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646\"},\"url\":\"https:\/\/ravandarman.com\/blog\/author\/content\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc - \u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646","description":"\u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u062a\u0642\u0631\u0628\u06cc\u0627 \u062f\u0631 \u0647\u0645\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0648 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc\u060c \u0627\u062d\u0633\u0627\u0633 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0635\u062f\u0645\u0647 \u062f\u06cc\u062f\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u062f\u0631\u06af\u06cc\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0634\u062f\u0647 \u0627\u0646\u062f.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc","og_description":"\u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u062a\u0642\u0631\u0628\u06cc\u0627 \u062f\u0631 \u0647\u0645\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0648 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc\u060c \u0627\u062d\u0633\u0627\u0633 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0635\u062f\u0645\u0647 \u062f\u06cc\u062f\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u062f\u0631\u06af\u06cc\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0634\u062f\u0647 \u0627\u0646\u062f.","og_url":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/","og_site_name":"\u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646","article_publisher":"https:\/\/www.facebook.com\/pezeshkekhoob","article_published_time":"2024-02-09T16:37:27+00:00","article_modified_time":"2025-12-07T11:43:16+00:00","og_image":[{"width":1001,"height":645,"url":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc2.jpg","type":"image\/jpeg"}],"author":"\u062a\u06cc\u0645 \u0645\u062d\u062a\u0648\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646","twitter_card":"summary_large_image","twitter_creator":"@pezeshkekhoob","twitter_site":"@pezeshkekhoob","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"\u062a\u06cc\u0645 \u0645\u062d\u062a\u0648\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646","\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646":"13 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#article","isPartOf":{"@id":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/"},"author":{"name":"\u062a\u06cc\u0645 \u0645\u062d\u062a\u0648\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646","@id":"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/6becaf60321027bf633ccc2a7612b0f0"},"headline":"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc","datePublished":"2024-02-09T16:37:27+00:00","dateModified":"2025-12-07T11:43:16+00:00","mainEntityOfPage":{"@id":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/"},"wordCount":12,"commentCount":6,"publisher":{"@id":"https:\/\/ravandarman.com\/blog\/#organization"},"image":{"@id":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#primaryimage"},"thumbnailUrl":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc2.jpg","keywords":["\u062f\u0631\u0645\u0627\u0646 \u0631\u0641\u062a\u0627\u0631\u06cc \u0634\u0646\u0627\u062e\u062a\u06cc","\u0637\u0631\u062d\u0648\u0627\u0631\u0647\u200c\u062f\u0631\u0645\u0627\u0646\u06cc","\u0637\u0631\u062d\u0648\u0627\u0631\u0647\u200c\u0647\u0627"],"articleSection":["\u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u06cc"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/","url":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/","name":"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc - \u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646","isPartOf":{"@id":"https:\/\/ravandarman.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#primaryimage"},"image":{"@id":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#primaryimage"},"thumbnailUrl":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc2.jpg","datePublished":"2024-02-09T16:37:27+00:00","dateModified":"2025-12-07T11:43:16+00:00","description":"\u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u062a\u0642\u0631\u0628\u06cc\u0627 \u062f\u0631 \u0647\u0645\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0648 \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc\u060c \u0627\u062d\u0633\u0627\u0633 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0648 \u0635\u062f\u0645\u0647 \u062f\u06cc\u062f\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u062f\u0631\u06af\u06cc\u0631 \u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0634\u062f\u0647 \u0627\u0646\u062f.","breadcrumb":{"@id":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ravandarman.com\/blog\/vulnerability-schema\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#primaryimage","url":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc2.jpg","contentUrl":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2024\/02\/\u0637\u0631\u062d\u0648\u0627\u0631\u0647-\u0622\u0633\u06cc\u0628-\u067e\u0630\u06cc\u0631\u06cc2.jpg","width":1001,"height":645,"caption":"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc"},{"@type":"BreadcrumbList","@id":"https:\/\/ravandarman.com\/blog\/vulnerability-schema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0635\u0641\u062d\u0647 \u0627\u0635\u0644\u06cc","item":"https:\/\/ravandarman.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u0637\u0631\u062d\u0648\u0627\u0631\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u062a\u0644\u0647 \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0636\u0631\u0631 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc"}]},{"@type":"WebSite","@id":"https:\/\/ravandarman.com\/blog\/#website","url":"https:\/\/ravandarman.com\/blog\/","name":"\u0631\u0648\u0627\u0646\u200c\u062f\u0631\u0645\u0627\u0646","description":"| \u0645\u0637\u0627\u0644\u0628\u06cc \u0645\u0641\u06cc\u062f \u0628\u0631\u0627\u06cc \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0627\u0646 \u0634\u0645\u0627","publisher":{"@id":"https:\/\/ravandarman.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ravandarman.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/ravandarman.com\/blog\/#organization","name":"Pezeshkekhoob","url":"https:\/\/ravandarman.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/ravandarman.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2025\/04\/logoo.png","contentUrl":"https:\/\/ravandarman.com\/blog\/wp-content\/uploads\/2025\/04\/logoo.png","width":197,"height":70,"caption":"Pezeshkekhoob"},"image":{"@id":"https:\/\/ravandarman.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pezeshkekhoob","https:\/\/x.com\/pezeshkekhoob"]},{"@type":"Person","@id":"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/6becaf60321027bf633ccc2a7612b0f0","name":"\u062a\u06cc\u0645 \u0645\u062d\u062a\u0648\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/ravandarman.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f98703e4f7570a32d0769f6a229d28103ec6dc497fc34d8aa8bf04b0bbc91288?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f98703e4f7570a32d0769f6a229d28103ec6dc497fc34d8aa8bf04b0bbc91288?s=96&d=mm&r=g","caption":"\u062a\u06cc\u0645 \u0645\u062d\u062a\u0648\u0627\u06cc \u0631\u0648\u0627\u0646 \u062f\u0631\u0645\u0627\u0646"},"url":"https:\/\/ravandarman.com\/blog\/author\/content\/"}]}},"_links":{"self":[{"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/posts\/20139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/comments?post=20139"}],"version-history":[{"count":1,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/posts\/20139\/revisions"}],"predecessor-version":[{"id":29228,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/posts\/20139\/revisions\/29228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/media\/20151"}],"wp:attachment":[{"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/media?parent=20139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/categories?post=20139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/tags?post=20139"},{"taxonomy":"paper-cat","embeddable":true,"href":"https:\/\/ravandarman.com\/blog\/wp-json\/wp\/v2\/paper-cat?post=20139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}